{"id":28143,"date":"2024-01-23T08:46:04","date_gmt":"2024-01-23T07:46:04","guid":{"rendered":"https:\/\/kymos.com\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/"},"modified":"2024-01-23T08:46:04","modified_gmt":"2024-01-23T07:46:04","slug":"profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici","status":"publish","type":"post","link":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/","title":{"rendered":"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute nei prodotti farmaceutici"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">La caratterizzazione delle impurezze sconosciute presenti nelle sostanze e nei prodotti farmaceutici \u00e8 una parte fondamentale del processo di approvazione normativa. Secondo le linee guida ICH, se la stima indica un contenuto di impurezze superiore allo 0,1%, \u00e8 necessario identificarlo e caratterizzarlo, garantendo la conformit\u00e0 a tutti i requisiti normativi. Questo processo \u00e8 noto anche come <strong>profilazione delle impurezze<\/strong> .  <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Il presente articolo si concentra su questo processo, fornendo maggiori dettagli sulle impurit\u00e0 e descrivendo dettagliatamente quali tecniche e attrezzature vengono impiegate da Kymos Group per gestirle.<\/span><\/p>\n<h2><strong>Comprensione delle impurit\u00e0 e della loro classificazione<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Secondo la definizione dell&#8217;OMS, un&#8217;impurezza \u00e8 &#8220;qualsiasi componente presente nel principio attivo o nel prodotto farmaceutico che non sia il prodotto desiderato, una sostanza correlata al prodotto o un eccipiente, inclusi i componenti tampone. Pu\u00f2 essere correlata al processo o al prodotto&#8221;.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">L&#8217;origine di queste impurit\u00e0 pu\u00f2 quindi essere attribuita a diverse fasi del processo di sintesi del principio attivo. Possono essere presenti sulle materie prime, prodotte durante il processo di fabbricazione, create durante il processo di degradazione durante lo stoccaggio e la spedizione, o persino presenti nei solventi utilizzati durante la fabbricazione. <\/span><\/p>\n<h2><span style=\"font-size: 18pt;\">Classificazione delle impurit\u00e0 nelle sostanze farmacologiche<\/span><\/h2>\n<p><span style=\"font-size: 14pt;\">Combinando la fonte, la composizione e la sicurezza biologica, l&#8217;ICH ha elaborato una classificazione importante per le impurit\u00e0 nelle sostanze farmaceutiche:<\/span><\/p>\n<ul>\n<li>\n<h3><span style=\"font-size: 14pt;\"><strong>Impurit\u00e0 organiche:<\/strong><\/span><\/h3>\n<p><span style=\"font-size: 14pt;\">Si trovano durante il processo di produzione o si formano durante lo stoccaggio. Possono essere identificati o non identificati. Includono materie prime, sottoprodotti, intermedi, prodotti di degradazione, reagenti, leganti e catalizzatori.  <\/span><\/li>\n<li>\n<h3><span style=\"font-size: 14pt;\"><strong>Impurit\u00e0 inorganiche:  <\/strong><\/span><\/h3>\n<p><span style=\"font-size: 14pt;\">Risultano dal processo di fabbricazione e sono normalmente noti e identificati. Tra questi rientrano reagenti, leganti, catalizzatori, <a href=\"https:\/\/kymos.com\/it\/servizi\/analisi-cmc-e-controllo-qualita\/elementari-nitrosammine-e-altre-impurita\/impurita-elementari\/\" data-wpel-link=\"internal\">metalli pesanti o altri metalli residui<\/a> , sali inorganici e altri materiali come coadiuvanti di filtrazione o carbone attivo. <\/span><\/li>\n<li>\n<h3><span style=\"font-size: 14pt;\"><strong>Solventi residui:  <\/strong><\/span><\/h3>\n<p><span style=\"font-size: 14pt;\">Derivati dal processo di fabbricazione e classificati in base al potenziale rischio per la salute umana o animale. Scopri di pi\u00f9 su <a href=\"https:\/\/kymos.com\/it\/news\/vich-gl18-r2-modifiche-nei-solventi-residui-per-prodotti-veterinari\/\" data-wpel-link=\"internal\">VICH GL18 (R2) e sui solventi residui.<\/a> <\/span><\/li>\n<\/ul>\n<h2><strong>Linee guida sul controllo delle impurit\u00e0 e sulla loro caratterizzazione<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Come accennato in precedenza, le linee guida ICH richiedono che qualsiasi impurezza sconosciuta presente nel nuovo principio attivo in concentrazioni superiori allo 0,1% debba essere caratterizzata. Se superano questa soglia, devono essere identificate e specificate singolarmente nelle specifiche.   <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Al contrario, se un&#8217;impurit\u00e0 scende al di sotto di questo limite, l&#8217;identificazione \u00e8 generalmente superflua, tranne nei casi in cui si prevede che il potenziale danno sia insolitamente elevato.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Vale la pena notare che le linee guida ICH richiedono che i prodotti di degradazione rilevati negli studi di stabilit\u00e0 del farmaco debbano essere identificati anche se presentano un livello superiore alle soglie di identificazione. Questi limiti sono riportati nell&#8217;ICH <a href=\"https:\/\/www.ema.europa.eu\/en\/ich-q3a-r2-impurities-new-drug-substances-scientific-guideline\" data-wpel-link=\"external\">Q3A (R2).<\/a> <\/span><\/p>\n<h2><strong>Tecniche utilizzate per la profilazione delle impurit\u00e0<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Per identificare impurit\u00e0 e prodotti di degradazione, si possono impiegare diversi metodi. L&#8217;approccio convenzionale prevede la verifica dei tempi di ritenzione di analiti sconosciuti rispetto ai loro standard utilizzando un metodo sviluppato, in genere tramite spiking.   <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Quando un picco supera la soglia di identificazione, viene marcato per l&#8217;identificazione e la delucidazione strutturale. Presso Kymos Group, questo processo viene comunemente eseguito utilizzando <strong>UPLC o HPLC.<\/strong> <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Sebbene questo sia il metodo convenzionale da molti anni, noi utilizziamo prevalentemente <strong>tecniche con trattino perch\u00e9 sono pi\u00f9 rapide e facili da usare quando \u00e8 necessario caratterizzare pi\u00f9 impurit\u00e0 in un singolo campione.<\/strong> <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Sono preferiti anche perch\u00e9 <strong>evitiamo potenziali problemi quando si formano impurit\u00e0 instabili<\/strong> o se c&#8217;\u00e8 la possibilit\u00e0 di una reazione secondaria durante la lavorazione.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Per queste ragioni specifiche, abbiamo deciso di utilizzare <strong>la LC-MS<\/strong> , in quanto ha il potenziale di fornire informazioni strutturali quasi chiare sull&#8217;analita sconosciuto, e in particolare lo spettrometro di massa Orbitrap.  <\/span><\/p>\n<h2><strong>Capacit\u00e0 e nuove strutture del Gruppo Kymos<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">In risposta alla crescita sostenuta delle nostre attivit\u00e0 nel corso del 2023, e in particolare per soddisfare le esigenze dei nostri clienti in materia di analisi e test delle impurit\u00e0, abbiamo recentemente ampliato il nostro sito in Italia con strutture completamente nuove.  <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Questo nuovo edificio ha una superficie tre volte superiore a quella dello stabilimento precedente e comprende tre nuovi laboratori progettati secondo l&#8217; <a href=\"https:\/\/kymos.com\/it\/news\/u-shape-e-lean-lab-migliorare-la-produttivita-in-laboratorio\/\" data-wpel-link=\"internal\">approccio &#8220;lean lab&#8221;.<\/a><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Questo investimento strategico non solo comporter\u00e0 un aumento sostanziale della nostra capacit\u00e0 di analisi delle impurit\u00e0, ma amplier\u00e0 anche la nostra gamma di servizi nella ricerca, nello sviluppo e nel controllo qualit\u00e0 dei prodotti biofarmaceutici.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>I nuovi laboratori hanno gi\u00e0 ricevuto l&#8217;approvazione dell&#8217;AIFA<\/strong> (Agenzia Italiana del Farmaco) in seguito a un&#8217;accurata verifica fisica delle strutture e siamo pronti a fornire assistenza per qualsiasi progetto che si presenti.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Se hai bisogno di assistenza con la caratterizzazione delle impurit\u00e0 o con uno qualsiasi dei tuoi studi CMC o bioanalitici, <strong><a href=\"https:\/\/kymos.com\/it\/contatto\/\" data-wpel-link=\"internal\">contattaci<\/a><\/strong> o inviaci un&#8217;e-mail a commercial@kymos.com<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La caratterizzazione delle impurezze sconosciute presenti nelle sostanze e nei  [&#8230;]<\/p>\n","protected":false},"author":7,"featured_media":28145,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[264],"tags":[67],"class_list":["post-28143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cmc","tag-carles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute<\/title>\n<meta name=\"description\" content=\"Scopri di pi\u00f9 sulla caratterizzazione delle impurit\u00e0 nei prodotti farmaceutici e sulle tecniche utilizzate per gestirle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute\" \/>\n<meta property=\"og:description\" content=\"Scopri di pi\u00f9 sulla caratterizzazione delle impurit\u00e0 nei prodotti farmaceutici e sulle tecniche utilizzate per gestirle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/\" \/>\n<meta property=\"og:site_name\" content=\"Kymos\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T07:46:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kymos.com\/wp-content\/uploads\/2024\/01\/2024-01-23-Impurity-Profiling-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carles Celma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:site\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carles Celma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/\"},\"author\":{\"name\":\"Carles Celma\",\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/#\\\/schema\\\/person\\\/3d86e112b87df4b5c1304ce33368ef23\"},\"headline\":\"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute nei prodotti farmaceutici\",\"datePublished\":\"2024-01-23T07:46:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/\"},\"wordCount\":777,\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2024-01-23-Impurity-Profiling-2.jpg\",\"keywords\":[\"carles\"],\"articleSection\":[\"CMC\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/\",\"url\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/\",\"name\":\"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2024-01-23-Impurity-Profiling-2.jpg\",\"datePublished\":\"2024-01-23T07:46:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/#\\\/schema\\\/person\\\/3d86e112b87df4b5c1304ce33368ef23\"},\"description\":\"Scopri di pi\u00f9 sulla caratterizzazione delle impurit\u00e0 nei prodotti farmaceutici e sulle tecniche utilizzate per gestirle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2024-01-23-Impurity-Profiling-2.jpg\",\"contentUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2024-01-23-Impurity-Profiling-2.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Front page of the article on impurity profiling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kymos.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute nei prodotti farmaceutici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/kymos.com\\\/it\\\/\",\"name\":\"Kymos Group\",\"description\":\"Kymos Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kymos.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kymos.com\\\/it\\\/#\\\/schema\\\/person\\\/3d86e112b87df4b5c1304ce33368ef23\",\"name\":\"Carles Celma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g\",\"caption\":\"Carles Celma\"},\"url\":\"https:\\\/\\\/kymos.com\\\/it\\\/news\\\/author\\\/dr-carles-celma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute","description":"Scopri di pi\u00f9 sulla caratterizzazione delle impurit\u00e0 nei prodotti farmaceutici e sulle tecniche utilizzate per gestirle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/","og_locale":"it_IT","og_type":"article","og_title":"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute","og_description":"Scopri di pi\u00f9 sulla caratterizzazione delle impurit\u00e0 nei prodotti farmaceutici e sulle tecniche utilizzate per gestirle.","og_url":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/","og_site_name":"Kymos","article_published_time":"2024-01-23T07:46:04+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/kymos.com\/wp-content\/uploads\/2024\/01\/2024-01-23-Impurity-Profiling-2.jpg","type":"image\/jpeg"}],"author":"Carles Celma","twitter_card":"summary_large_image","twitter_creator":"@KymosGroup","twitter_site":"@KymosGroup","twitter_misc":{"Scritto da":"Carles Celma","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/#article","isPartOf":{"@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/"},"author":{"name":"Carles Celma","@id":"https:\/\/kymos.com\/it\/#\/schema\/person\/3d86e112b87df4b5c1304ce33368ef23"},"headline":"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute nei prodotti farmaceutici","datePublished":"2024-01-23T07:46:04+00:00","mainEntityOfPage":{"@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/"},"wordCount":777,"image":{"@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2024\/01\/2024-01-23-Impurity-Profiling-2.jpg","keywords":["carles"],"articleSection":["CMC"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/","url":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/","name":"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute","isPartOf":{"@id":"https:\/\/kymos.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/#primaryimage"},"image":{"@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2024\/01\/2024-01-23-Impurity-Profiling-2.jpg","datePublished":"2024-01-23T07:46:04+00:00","author":{"@id":"https:\/\/kymos.com\/it\/#\/schema\/person\/3d86e112b87df4b5c1304ce33368ef23"},"description":"Scopri di pi\u00f9 sulla caratterizzazione delle impurit\u00e0 nei prodotti farmaceutici e sulle tecniche utilizzate per gestirle.","breadcrumb":{"@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/#primaryimage","url":"https:\/\/kymos.com\/wp-content\/uploads\/2024\/01\/2024-01-23-Impurity-Profiling-2.jpg","contentUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2024\/01\/2024-01-23-Impurity-Profiling-2.jpg","width":1920,"height":1080,"caption":"Front page of the article on impurity profiling"},{"@type":"BreadcrumbList","@id":"https:\/\/kymos.com\/it\/news\/profilazione-delle-impurita-caratterizzazione-delle-impurita-sconosciute-nei-prodotti-farmaceutici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kymos.com\/it\/"},{"@type":"ListItem","position":2,"name":"Profilazione delle impurit\u00e0: caratterizzazione delle impurit\u00e0 sconosciute nei prodotti farmaceutici"}]},{"@type":"WebSite","@id":"https:\/\/kymos.com\/it\/#website","url":"https:\/\/kymos.com\/it\/","name":"Kymos Group","description":"Kymos Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kymos.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/kymos.com\/it\/#\/schema\/person\/3d86e112b87df4b5c1304ce33368ef23","name":"Carles Celma","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g","caption":"Carles Celma"},"url":"https:\/\/kymos.com\/it\/news\/author\/dr-carles-celma\/"}]}},"_links":{"self":[{"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/posts\/28143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/comments?post=28143"}],"version-history":[{"count":0,"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/posts\/28143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/media\/28145"}],"wp:attachment":[{"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/media?parent=28143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/categories?post=28143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kymos.com\/it\/wp-json\/wp\/v2\/tags?post=28143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}