{"id":27330,"date":"2020-05-18T10:57:45","date_gmt":"2020-05-18T08:57:45","guid":{"rendered":"https:\/\/kymos.com\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/"},"modified":"2020-05-18T10:57:45","modified_gmt":"2020-05-18T08:57:45","slug":"immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie","status":"publish","type":"post","link":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/","title":{"rendered":"Immunologie : Travailler ensemble pour se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie"},"content":{"rendered":"<h3><span style=\"font-size: 14pt;\">Aujourd&rsquo;hui plus que jamais, l&rsquo;immunologie est un sujet d&rsquo;actualit\u00e9 face aux nombreux d\u00e9fis pos\u00e9s par la pand\u00e9mie de COVID-19. Le monde attend avec impatience de nouveaux traitements et vaccins pour combattre cette maladie, dans l&rsquo;espoir de retrouver une vie plus normale.   <\/span><\/h3>\n<div class=\"blog-content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><span style=\"font-size: 14pt;\">Le Dr Carles Morte, expert en immunologie chez KYMOS, nous livre sa vision de l&rsquo;avenir des nouvelles th\u00e9rapies g\u00e9niques et cellulaires prometteuses, ainsi que des anticorps monoclonaux d\u00e9velopp\u00e9s contre les virus et autres maladies. Nous l&rsquo;interrogeons sur l&rsquo;\u00e9valuation technique n\u00e9cessaire, la cible th\u00e9rapeutique se tournant d\u00e9sormais vers le syst\u00e8me immunitaire, d&rsquo;une complexit\u00e9 toujours plus grande. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u00ab&nbsp;Dans les ann\u00e9es \u00e0 venir, nous assisterons au d\u00e9veloppement de nouvelles th\u00e9rapies biologiques, o\u00f9 l\u2019immunog\u00e9nicit\u00e9 jouera un r\u00f4le majeur. Notre \u00e9quipe poss\u00e8de l\u2019expertise et la vaste exp\u00e9rience n\u00e9cessaires pour relever ces nouveaux d\u00e9fis.&nbsp;\u00bb<\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>D\u00e9fis actuels li\u00e9s au suivi et \u00e0 l&rsquo;analyse des nouveaux produits pharmaceutiques biologiques et des th\u00e9rapies g\u00e9niques et cellulaires<\/strong><\/span><br \/>\n<span style=\"font-size: 14pt;\">Le syst\u00e8me immunitaire est un \u00e9l\u00e9ment extr\u00eamement complexe et essentiel de notre d\u00e9fense contre les maladies. De ce fait, le d\u00e9veloppement de nouvelles th\u00e9rapies g\u00e9niques et cellulaires soul\u00e8ve plusieurs difficult\u00e9s. <\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Travailler avec des syst\u00e8mes cellulaires ou des r\u00e9ponses in vivo<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">D\u00e9s\u00e9quilibre du syst\u00e8me immunitaire d\u00fb \u00e0 de multiples d\u00e9clencheurs (provenant du m\u00e9dicament lui-m\u00eame et du vecteur)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">immunog\u00e9nicit\u00e9 pr\u00e9existante sp\u00e9cifique au patient<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">R\u00e9ponses cellulaires (\u00e0 m\u00e9diation par les lymphocytes T) et r\u00e9ponses inn\u00e9es<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\">Carles dirige une \u00e9quipe poss\u00e9dant une vaste exp\u00e9rience en immunologie acquise dans le milieu universitaire, l&rsquo;industrie pharmaceutique et les CRO. Cette expertise leur conf\u00e8re un savoir-faire unique pour mener \u00e0 bien les projets techniques les plus complexes gr\u00e2ce \u00e0 un \u00e9ventail de techniques analytiques telles que l&rsquo;ELISA, l&rsquo;\u00e9lectrochimiluminescence, la cytom\u00e9trie en flux, l&rsquo;ELISPOT ou les tests cellulaires. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Qu&rsquo;est-ce qui diff\u00e9rencie Carles et son \u00e9quipe des autres CRO ?<\/strong><\/span><br \/>\n<span style=\"font-size: 14pt;\">L&rsquo;\u00e9quipe d&rsquo;experts du Dr Morte poss\u00e8de une vaste exp\u00e9rience dans la mesure de la pr\u00e9sence d&rsquo;anticorps et la neutralisation d&rsquo;anticorps contre divers m\u00e9dicaments, allant des petits peptides aux grandes prot\u00e9ines, comme les toxines et les hormones.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">L&rsquo;\u00e9quipe travaille g\u00e9n\u00e9ralement sur des projets internationaux exigeant une expertise pointue, comme les essais de puissance de m\u00e9dicaments biologiques r\u00e9alis\u00e9s pour de nombreux clients en Chine et en Cor\u00e9e du Sud. Le d\u00e9partement travaille \u00e9galement sur des syst\u00e8mes cellulaires afin de d\u00e9terminer l&rsquo;effet neutralisant des anticorps, ce qui n\u00e9cessite l&rsquo;utilisation de plateformes analytiques plus complexes. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u00ab KYMOS propose une analyse compl\u00e8te des m\u00e9dicaments biologiques, centralis\u00e9e dans notre laboratoire principal&nbsp;: de la caract\u00e9risation physico-chimique \u00e0 la mise sur le march\u00e9 des lots. Notre flexibilit\u00e9 et notre compr\u00e9hension des besoins de nos clients sont essentielles pour r\u00e9pondre \u00e0 leurs attentes, voire les d\u00e9passer. \u00bb  <\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Comment peut-on s&rsquo;attendre \u00e0 ce que le march\u00e9 mondial des produits biologiques \u00e9volue \u00e0 l&rsquo;avenir&nbsp;?<\/strong><\/span><br \/>\n<span style=\"font-size: 14pt;\">Suite \u00e0 la pand\u00e9mie de COVID-19, la population est plus inform\u00e9e que jamais sur le fonctionnement du syst\u00e8me immunitaire et sa protection contre les virus et autres maladies. On peut s&rsquo;attendre \u00e0 voir appara\u00eetre davantage de m\u00e9dicaments ciblant le syst\u00e8me immunitaire, tels que des anticorps monoclonaux neutralisant les cytokines pour bloquer les effets viraux, de nouveaux vaccins ainsi que d&rsquo;autres alternatives biosimilaires. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Les syst\u00e8mes de diagnostic qui mesurent l&rsquo;immunog\u00e9nicit\u00e9 et les r\u00e9actions \u00e0 m\u00e9diation immunitaire sont essentiels et n\u00e9cessitent un d\u00e9veloppement, des tests et une validation que seuls des laboratoires hautement sp\u00e9cialis\u00e9s, dot\u00e9s d&rsquo;un haut niveau d&rsquo;expertise et d&rsquo;exp\u00e9rience, comme KYMOS, peuvent assurer.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u00ab Ce n\u2019est pas la derni\u00e8re nouvelle maladie infectieuse \u00e0 laquelle nous aurons \u00e0 faire face, mais ensemble, nous pouvons \u0153uvrer pour nous pr\u00e9parer efficacement \u00e0 la prochaine. \u00bb<\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">KYMOS est un laboratoire europ\u00e9en sous contrat, certifi\u00e9 BPL\/BPF et conforme aux BPC, inspect\u00e9 par l&rsquo;EMA et la FDA, sp\u00e9cialis\u00e9 dans la bioanalyse des macromol\u00e9cules. Vous trouverez ici plus d&rsquo;informations sur les services de KYMOS <a href=\"https:\/\/kymos.com\/fr\/services\/services-precliniques-et-cliniques\/bioanalyse-et-immunogenicite-des-produits-biologiques-et-biosimilaires\/\" data-wpel-link=\"internal\">en mati\u00e8re de bioanalyse, d&rsquo;immunog\u00e9nicit\u00e9 des produits biologiques et biosimilaires<\/a> et <a href=\"https:\/\/kymos.com\/fr\/services\/analyse-cmc-et-controle-qualite\/essais-cellulaires-et-de-puissance\/\" data-wpel-link=\"internal\">de th\u00e9rapie cellulaire<\/a> , ou vous pouvez nous contacter \u00e0 l&rsquo; <a href=\"mailto:info@kymos.com\" data-wpel-link=\"internal\">adresse commerciale@kymos.com<\/a> <a href=\"mailto:info@kymos.com?subject=Nouveaux%20instruments%20chez%20Kymos\" data-wpel-link=\"internal\">.<\/a> <\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui plus que jamais, l&rsquo;immunologie est un sujet d&rsquo;actualit\u00e9 face  [&#8230;]<\/p>\n","protected":false},"author":6,"featured_media":27332,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[],"class_list":["post-27330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioanalyse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Immunologie : Se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie | Groupe Kymos<\/title>\n<meta name=\"description\" content=\"Restez inform\u00e9(e) des derni\u00e8res recherches et avanc\u00e9es en immunologie. D\u00e9couvrez comment le groupe Kymos peut vous apporter son expertise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immunologie : Se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie | Groupe Kymos\" \/>\n<meta property=\"og:description\" content=\"Restez inform\u00e9(e) des derni\u00e8res recherches et avanc\u00e9es en immunologie. D\u00e9couvrez comment le groupe Kymos peut vous apporter son expertise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/\" \/>\n<meta property=\"og:site_name\" content=\"Kymos\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T08:57:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Joan Puig de Dou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:site\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joan Puig de Dou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/\"},\"author\":{\"name\":\"Joan Puig de Dou\",\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/#\\\/schema\\\/person\\\/264c93ce9dcf43caa9d634aeafab965c\"},\"headline\":\"Immunologie : Travailler ensemble pour se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie\",\"datePublished\":\"2020-05-18T08:57:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/\"},\"wordCount\":762,\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Carles-Morte_Immunology_Short-e1658232189298.png\",\"articleSection\":[\"Bioanalyse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/\",\"url\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/\",\"name\":\"Immunologie : Se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie | Groupe Kymos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Carles-Morte_Immunology_Short-e1658232189298.png\",\"datePublished\":\"2020-05-18T08:57:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/#\\\/schema\\\/person\\\/264c93ce9dcf43caa9d634aeafab965c\"},\"description\":\"Restez inform\u00e9(e) des derni\u00e8res recherches et avanc\u00e9es en immunologie. D\u00e9couvrez comment le groupe Kymos peut vous apporter son expertise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Carles-Morte_Immunology_Short-e1658232189298.png\",\"contentUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Carles-Morte_Immunology_Short-e1658232189298.png\",\"width\":800,\"height\":444,\"caption\":\"immunology carles morte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kymos.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immunologie : Travailler ensemble pour se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/kymos.com\\\/fr\\\/\",\"name\":\"Kymos Group\",\"description\":\"Kymos Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kymos.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kymos.com\\\/fr\\\/#\\\/schema\\\/person\\\/264c93ce9dcf43caa9d634aeafab965c\",\"name\":\"Joan Puig de Dou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g\",\"caption\":\"Joan Puig de Dou\"},\"description\":\"Active in the pharmaceutical marketing for over 30 years President of CataloniaBIO&amp;HealthTech CEO and Qualified Person at Kymos Leader of Kymos team, guaranteeing a trustable, ethical and scientific correct editorial publications. Experience Joan Puig de Dou started his career at Laboratorios Menarini first as scientist later as Qualified Person and finally as Operations General Manager. 2010 he entered Kymos where he became CEO in 2015. 2022 Joan Puig de Dou was elected as president of CataloniaBio&amp;HealthTech to represent the Catalonian biotech industry nationally and internationally. Expertise Joan Puig de Dou has extensive experience in writing scientific content adopting a didactic approach that fits any reader\u2019s level of expertise. He publishes regularely on Kymos\u2019 webpage, social media and in the specialized press. Education He graduated from Universitat de Barcelona as Pharmacist and from IESE Business School\u2019s Programa Diecci\u00f3n General (PDG) Want to know him better? Read his interview in PharmaBoardrooom in January 2019 and more about his presidency of CataloniaBio at Parc Sc\u00edentific de Barcelona.\",\"url\":\"https:\\\/\\\/kymos.com\\\/fr\\\/news\\\/author\\\/joan-puig-de-dou\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immunologie : Se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie | Groupe Kymos","description":"Restez inform\u00e9(e) des derni\u00e8res recherches et avanc\u00e9es en immunologie. D\u00e9couvrez comment le groupe Kymos peut vous apporter son expertise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/","og_locale":"fr_FR","og_type":"article","og_title":"Immunologie : Se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie | Groupe Kymos","og_description":"Restez inform\u00e9(e) des derni\u00e8res recherches et avanc\u00e9es en immunologie. D\u00e9couvrez comment le groupe Kymos peut vous apporter son expertise.","og_url":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/","og_site_name":"Kymos","article_published_time":"2020-05-18T08:57:45+00:00","og_image":[{"width":800,"height":444,"url":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","type":"image\/png"}],"author":"Joan Puig de Dou","twitter_card":"summary_large_image","twitter_creator":"@KymosGroup","twitter_site":"@KymosGroup","twitter_misc":{"\u00c9crit par":"Joan Puig de Dou","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/#article","isPartOf":{"@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/"},"author":{"name":"Joan Puig de Dou","@id":"https:\/\/kymos.com\/fr\/#\/schema\/person\/264c93ce9dcf43caa9d634aeafab965c"},"headline":"Immunologie : Travailler ensemble pour se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie","datePublished":"2020-05-18T08:57:45+00:00","mainEntityOfPage":{"@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/"},"wordCount":762,"image":{"@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","articleSection":["Bioanalyse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/","url":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/","name":"Immunologie : Se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie | Groupe Kymos","isPartOf":{"@id":"https:\/\/kymos.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/#primaryimage"},"image":{"@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","datePublished":"2020-05-18T08:57:45+00:00","author":{"@id":"https:\/\/kymos.com\/fr\/#\/schema\/person\/264c93ce9dcf43caa9d634aeafab965c"},"description":"Restez inform\u00e9(e) des derni\u00e8res recherches et avanc\u00e9es en immunologie. D\u00e9couvrez comment le groupe Kymos peut vous apporter son expertise.","breadcrumb":{"@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/#primaryimage","url":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","contentUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","width":800,"height":444,"caption":"immunology carles morte"},{"@type":"BreadcrumbList","@id":"https:\/\/kymos.com\/fr\/news\/immunologie-travailler-ensemble-pour-se-preparer-a-la-prochaine-pandemie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kymos.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Immunologie : Travailler ensemble pour se pr\u00e9parer \u00e0 la prochaine pand\u00e9mie"}]},{"@type":"WebSite","@id":"https:\/\/kymos.com\/fr\/#website","url":"https:\/\/kymos.com\/fr\/","name":"Kymos Group","description":"Kymos Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kymos.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/kymos.com\/fr\/#\/schema\/person\/264c93ce9dcf43caa9d634aeafab965c","name":"Joan Puig de Dou","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g","caption":"Joan Puig de Dou"},"description":"Active in the pharmaceutical marketing for over 30 years President of CataloniaBIO&amp;HealthTech CEO and Qualified Person at Kymos Leader of Kymos team, guaranteeing a trustable, ethical and scientific correct editorial publications. Experience Joan Puig de Dou started his career at Laboratorios Menarini first as scientist later as Qualified Person and finally as Operations General Manager. 2010 he entered Kymos where he became CEO in 2015. 2022 Joan Puig de Dou was elected as president of CataloniaBio&amp;HealthTech to represent the Catalonian biotech industry nationally and internationally. Expertise Joan Puig de Dou has extensive experience in writing scientific content adopting a didactic approach that fits any reader\u2019s level of expertise. He publishes regularely on Kymos\u2019 webpage, social media and in the specialized press. Education He graduated from Universitat de Barcelona as Pharmacist and from IESE Business School\u2019s Programa Diecci\u00f3n General (PDG) Want to know him better? Read his interview in PharmaBoardrooom in January 2019 and more about his presidency of CataloniaBio at Parc Sc\u00edentific de Barcelona.","url":"https:\/\/kymos.com\/fr\/news\/author\/joan-puig-de-dou\/"}]}},"_links":{"self":[{"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/posts\/27330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/comments?post=27330"}],"version-history":[{"count":0,"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/posts\/27330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/media\/27332"}],"wp:attachment":[{"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/media?parent=27330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/categories?post=27330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kymos.com\/fr\/wp-json\/wp\/v2\/tags?post=27330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}