{"id":47625,"date":"2026-07-24T08:49:02","date_gmt":"2026-07-24T06:49:02","guid":{"rendered":"https:\/\/kymos.com\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/"},"modified":"2026-07-24T08:53:55","modified_gmt":"2026-07-24T06:53:55","slug":"bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms","status":"publish","type":"post","link":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/","title":{"rendered":"Bioan\u00e1lisis de \u00c1cidos Nucleicos: Ampliando las capacidades anal\u00edticas con LC-MS\/MS"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1170px + 20px );margin-left: calc(-20px \/ 2 );margin-right: calc(-20px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:10px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:10px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:10px;--awb-spacing-left-medium:10px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:10px;--awb-spacing-left-small:10px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><span style=\"background-color: rgba(0, 0, 0, 0); font-size: 14pt;\">Los productos terap\u00e9uticos basados en \u00e1cidos nucleicos han surgido como una de las clases de medicamentos innovadores de m\u00e1s r\u00e1pido crecimiento, ofreciendo nuevas oportunidades de tratamiento para enfermedades que tradicionalmente han sido dif\u00edciles de abordar utilizando mol\u00e9culas peque\u00f1as o productos biol\u00f3gicos convencionales. Los oligonucle\u00f3tidos antisentido (ASO), los ARN de interferencia peque\u00f1os (siRNA), los apt\u00e1meros, los productos terap\u00e9uticos de ARN mensajero (ARNm) y otras modalidades basadas en \u00e1cidos nucleicos est\u00e1n progresando r\u00e1pidamente a trav\u00e9s del desarrollo de f\u00e1rmacos, impulsando la necesidad de m\u00e9todos bioanal\u00edticos robustos capaces de caracterizar con precisi\u00f3n estas mol\u00e9culas complejas (1,2). <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En comparaci\u00f3n con las mol\u00e9culas peque\u00f1as tradicionales, los oligonucle\u00f3tidos terap\u00e9uticos presentan desaf\u00edos anal\u00edticos \u00fanicos. Su tama\u00f1o molecular relativamente grande, alta polaridad y susceptibilidad a la degradaci\u00f3n mediada por nucleasas complican la extracci\u00f3n y cuantificaci\u00f3n de matrices biol\u00f3gicas. Adem\u00e1s, a menudo generan metabolitos truncados que pueden diferir del compuesto original en un solo nucle\u00f3tido, mientras exhiben propiedades farmacol\u00f3gicas o toxicol\u00f3gicas distintas. En consecuencia, los m\u00e9todos bioanal\u00edticos sensibles y selectivos son esenciales para apoyar los estudios farmacocin\u00e9ticos, toxicocin\u00e9ticos, de biodistribuci\u00f3n y de biomarcadores (1\u20133).   <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En Kymos, apoyamos el bioan\u00e1lisis de productos terap\u00e9uticos de \u00e1cidos nucleicos utilizando metodolog\u00edas basadas en biolog\u00eda molecular y espectrometr\u00eda de masas, desarrollando m\u00e9todos anal\u00edticos adecuados para el prop\u00f3sito tanto para estudios precl\u00ednicos como cl\u00ednicos.<\/span><\/p>\n<h2><strong>Enfoques bioanal\u00edticos para productos terap\u00e9uticos de \u00e1cidos nucleicos<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">La estrategia anal\u00edtica depende tanto de la modalidad terap\u00e9utica como de los objetivos de cada estudio. Dado que ninguna tecnolog\u00eda \u00fanica puede responder a todas las preguntas anal\u00edticas, a menudo se combinan t\u00e9cnicas anal\u00edticas complementarias para abordar diferentes puntos finales bioanal\u00edticos. En Kymos, estos enfoques incluyen:  <\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Cuantificaci\u00f3n de biomarcadores utilizando PCR cuantitativa en tiempo real (qPCR) de alta sensibilidad, con detecci\u00f3n de hasta 1 pg\/mL.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Cuantificaci\u00f3n de oligonucle\u00f3tidos terap\u00e9uticos utilizando ELISA de hibridaci\u00f3n, qPCR y LC-MS\/MS.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Cuantificaci\u00f3n de ADN, ARNm, siRNA, apt\u00e1meros y antagomiRs.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">An\u00e1lisis de expresi\u00f3n g\u00e9nica utilizando el m\u00e9todo \u0394\u0394Ct.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Detecci\u00f3n de ADN o ARN viral y bacteriano.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Estudios de biodistribuci\u00f3n para productos terap\u00e9uticos y vacunas basados en ADN y ARN.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">An\u00e1lisis de ADN humano residual para evaluar la eficiencia de descelularizaci\u00f3n de aloinjertos.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\">Si bien la qPCR sigue siendo el m\u00e9todo de elecci\u00f3n para muchas aplicaciones de biomarcadores y expresi\u00f3n g\u00e9nica, la creciente complejidad de los oligonucle\u00f3tidos terap\u00e9uticos ha impulsado la adopci\u00f3n de tecnolog\u00edas anal\u00edticas complementarias que proporcionan una mayor especificidad molecular y caracterizaci\u00f3n de metabolitos.<\/span><\/p>\n<h2><strong>LC-MS\/MS: ampliando la caja de herramientas anal\u00edticas<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Los avances recientes en la cromatograf\u00eda l\u00edquida acoplada a la espectrometr\u00eda de masas en t\u00e1ndem (LC-MS\/MS) han ampliado significativamente la caja de herramientas anal\u00edticas disponibles para los oligonucle\u00f3tidos terap\u00e9uticos (2\u20134). A diferencia de los ensayos ELISA de hibridaci\u00f3n, la LC-MS\/MS identifica directamente los analitos seg\u00fan su masa molecular y patrones de fragmentaci\u00f3n caracter\u00edsticos, lo que permite una cuantificaci\u00f3n precisa del compuesto original junto con la discriminaci\u00f3n de metabolitos estrechamente relacionados. En contraste con los m\u00e9todos basados en hibridaci\u00f3n, la LC-MS\/MS proporciona detecci\u00f3n molecular directa, lo que permite no solo una cuantificaci\u00f3n precisa, sino tambi\u00e9n la confirmaci\u00f3n estructural del analito. Este nivel adicional de especificidad es particularmente valioso al analizar oligonucle\u00f3tidos qu\u00edmicamente modificados o al distinguir metabolitos estrechamente relacionados que pueden no diferenciarse utilizando solo ensayos basados en sondas.   <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Esta capacidad es particularmente valiosa porque los oligonucle\u00f3tidos terap\u00e9uticos con frecuencia sufren degradaci\u00f3n mediada por exonucleasas, produciendo metabolitos acortados como las especies N\u22121 que pueden contribuir a la eficacia o seguridad. La LC-MS\/MS tambi\u00e9n es muy adecuada para oligonucle\u00f3tidos qu\u00edmicamente modificados, incluidos los oligonucle\u00f3tidos fosforotioato y las mol\u00e9culas conjugadas con ligando, proporcionando una alta especificidad anal\u00edtica y confianza en la identificaci\u00f3n del analito (1\u20134). <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Los m\u00e9todos LC-MS\/MS en Kymos apoyan el an\u00e1lisis de oligonucle\u00f3tidos terap\u00e9uticos en plasma y homogeneizados de tejidos. La hibridaci\u00f3n de perlas magn\u00e9ticas secuencia-espec\u00edfica permite la purificaci\u00f3n selectiva de la muestra antes del an\u00e1lisis cuantitativo por LC-MS\/MS en rangos de concentraci\u00f3n t\u00edpicamente entre 1 y 1000 ng\/mL. <\/span><\/p>\n<h2><strong>Hibridaci\u00f3n de perlas magn\u00e9ticas: la clave para una preparaci\u00f3n selectiva de muestras<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">La preparaci\u00f3n eficiente de la muestra es fundamental para un bioan\u00e1lisis exitoso por LC-MS\/MS. Las matrices biol\u00f3gicas contienen prote\u00ednas, fosfol\u00edpidos y \u00e1cidos nucleicos end\u00f3genos que pueden interferir con la detecci\u00f3n espectrom\u00e9trica de masas. Para superar estos desaf\u00edos, Kymos emplea la hibridaci\u00f3n de perlas magn\u00e9ticas secuencia-espec\u00edfica antes del an\u00e1lisis por LC-MS\/MS (1,2).  <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Las part\u00edculas magn\u00e9ticas se funcionalizan con sondas de oligonucle\u00f3tidos de captura que son complementarias a la secuencia terap\u00e9utica de inter\u00e9s. Las sondas de captura se inmovilizan en la superficie de la perla magn\u00e9tica, t\u00edpicamente a trav\u00e9s de interacciones biotina-estreptavidina, asegurando una uni\u00f3n estable y altamente selectiva durante todo el proceso de extracci\u00f3n. Despu\u00e9s de la hibridaci\u00f3n, un separador magn\u00e9tico a\u00edsla los complejos perla-objetivo mientras se elimina la matriz biol\u00f3gica restante. Las prote\u00ednas, los fosfol\u00edpidos y otros componentes de la matriz end\u00f3gena se eliminan eficientemente durante los pasos de lavado posteriores, y la eluci\u00f3n controlada libera el oligonucle\u00f3tido purificado para el an\u00e1lisis por LC-MS\/MS.   <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Este flujo de trabajo es r\u00e1pido, altamente selectivo y compatible con plataformas automatizadas de manipulaci\u00f3n de l\u00edquidos, lo que lo hace adecuado para estudios de alto rendimiento. En comparaci\u00f3n con los m\u00e9todos de extracci\u00f3n convencionales, la hibridaci\u00f3n de perlas magn\u00e9ticas ofrece varias ventajas: <\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Alta especificidad de secuencia.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Purificaci\u00f3n eficiente de matrices biol\u00f3gicas complejas.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Reducci\u00f3n de los efectos de matriz y la supresi\u00f3n i\u00f3nica.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Excelente reproducibilidad y baja contaminaci\u00f3n cruzada de muestras.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Compatibilidad con flujos de trabajo automatizados de alto rendimiento.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Discriminaci\u00f3n precisa de metabolitos estrechamente relacionados, incluidos los productos de degradaci\u00f3n N\u22121 (1,2,4).<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\">Al combinar el enriquecimiento selectivo con la detecci\u00f3n por LC-MS\/MS altamente espec\u00edfica, este flujo de trabajo integrado permite la cuantificaci\u00f3n robusta de oligonucle\u00f3tidos terap\u00e9uticos en matrices biol\u00f3gicas desafiantes, apoyando estudios farmacocin\u00e9ticos, de biodistribuci\u00f3n y de metabolismo.<\/span><\/p>\n<\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1536\" height=\"1024\" title=\"LC-MS_MS Bioanalysis Workflow\" src=\"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/LC-MS_MS-Bioanalysis-Workflow.png\" data-orig-src=\"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/LC-MS_MS-Bioanalysis-Workflow.png\" alt class=\"lazyload img-responsive wp-image-47618\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271536%27%20height%3D%271024%27%20viewBox%3D%270%200%201536%201024%27%3E%3Crect%20width%3D%271536%27%20height%3D%271024%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/LC-MS_MS-Bioanalysis-Workflow-200x133.png 200w, https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/LC-MS_MS-Bioanalysis-Workflow-400x267.png 400w, https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/LC-MS_MS-Bioanalysis-Workflow-600x400.png 600w, https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/LC-MS_MS-Bioanalysis-Workflow-800x533.png 800w, https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/LC-MS_MS-Bioanalysis-Workflow-1200x800.png 1200w, https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/LC-MS_MS-Bioanalysis-Workflow.png 1536w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1200px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-2\"><p>&nbsp;<\/p>\n<h2><strong>Apoyando la pr\u00f3xima generaci\u00f3n de productos terap\u00e9uticos de \u00e1cidos nucleicos<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Los medicamentos basados en \u00e1cidos nucleicos contin\u00faan evolucionando, y las metodolog\u00edas bioanal\u00edticas tambi\u00e9n deben avanzar para abordar su creciente complejidad. En lugar de reemplazar t\u00e9cnicas establecidas como la qPCR o el ELISA de hibridaci\u00f3n, la LC-MS\/MS complementa estos enfoques al proporcionar una especificidad molecular mejorada y discriminaci\u00f3n de metabolitos (2\u20134). <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Combinando la experiencia en biolog\u00eda molecular con capacidades avanzadas de espectrometr\u00eda de masas, Kymos ofrece soluciones bioanal\u00edticas adaptadas a cada modalidad terap\u00e9utica y estudio. La integraci\u00f3n de t\u00e9cnicas anal\u00edticas complementarias permite una caracterizaci\u00f3n m\u00e1s completa de los oligonucle\u00f3tidos terap\u00e9uticos, apoyando estudios farmacocin\u00e9ticos, de biodistribuci\u00f3n y de metabolismo, al tiempo que proporciona los datos fiables necesarios para acelerar el desarrollo de la pr\u00f3xima generaci\u00f3n de medicamentos basados en \u00e1cidos nucleicos. <\/span><\/p>\n<h3><strong>Referencias<\/strong><\/h3>\n<ol>\n<li>Rooney M, Ji QC, Leung K, et al. <em>Cromatograf\u00eda l\u00edquida de hibridaci\u00f3n-espectrometr\u00eda de masas en t\u00e1ndem: un m\u00e9todo bioanal\u00edtico alternativo para la cuantificaci\u00f3n de oligonucle\u00f3tidos antisentido en muestras de plasma y tejido.<\/em> Analytical Chemistry. 2020;92(15):10239-10247. <\/li>\n<li>Yuan L. <em>Cromatograf\u00eda l\u00edquida de hibridaci\u00f3n-espectrometr\u00eda de masas para el bioan\u00e1lisis cuantitativo de oligonucle\u00f3tidos: el pr\u00f3ximo cambio de paradigma.<\/em> Journal of Chromatography A. 2026;1766:466575.<\/li>\n<li>Yuan L. Bioan\u00e1lisis de oligonucle\u00f3tidos. En: Ahuja S, Dong MW, editores.  <em>Especificaci\u00f3n de sustancias y productos farmac\u00e9uticos: desarrollo y validaci\u00f3n de m\u00e9todos anal\u00edticos.<\/em> Elsevier; 2025. p. 209-243. <\/li>\n<li>Gilar M, Biba M, DeLano M, et al. <em>Bioan\u00e1lisis de oligonucle\u00f3tidos por LC-MS: efectos de los reactivos de emparejamiento i\u00f3nico y avances recientes en estrategias anal\u00edticas libres de emparejamiento i\u00f3nico.<\/em> Molecules. 2022;27(23):8875. <\/li>\n<li>Agencia Europea de Medicamentos. <em>Directriz sobre la validaci\u00f3n de m\u00e9todos bioanal\u00edticos.<\/em> EMA; 2011.<\/li>\n<li>Resolve Mass Spectrometry. <em>Bioan\u00e1lisis LC-MS para oligonucle\u00f3tidos.<\/em> Disponible en: <a href=\"https:\/\/resolvemass.ca\/lc-ms-bioanalysis-for-oligonucleotides\/\" data-wpel-link=\"external\">https:\/\/resolvemass.ca\/lc-ms-bioanalysis-for-oligonucleotides\/<\/a> (consultado en julio de 2026).<\/li>\n<\/ol>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":47608,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[181],"tags":[],"class_list":["post-47625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioanalisis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bioan\u00e1lisis LC-MS\/MS para \u00c1cidos Nucleicos - Kymos Group<\/title>\n<meta name=\"description\" content=\"Descubra c\u00f3mo la LC-MS\/MS y la hibridaci\u00f3n de perlas magn\u00e9ticas secuencia-espec\u00edfica apoyan el bioan\u00e1lisis de oligonucle\u00f3tidos terap\u00e9uticos desde estudios precl\u00ednicos hasta cl\u00ednicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bioan\u00e1lisis LC-MS\/MS para \u00c1cidos Nucleicos - Kymos Group\" \/>\n<meta property=\"og:description\" content=\"Descubra c\u00f3mo la LC-MS\/MS y la hibridaci\u00f3n de perlas magn\u00e9ticas secuencia-espec\u00edfica apoyan el bioan\u00e1lisis de oligonucle\u00f3tidos terap\u00e9uticos desde estudios precl\u00ednicos hasta cl\u00ednicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/\" \/>\n<meta property=\"og:site_name\" content=\"Kymos\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-24T06:49:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-24T06:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/NUAC-LCMSMS-Header-Article.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sandra Magdaleno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:site\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Magdaleno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/\"},\"author\":{\"name\":\"Sandra Magdaleno\",\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/#\\\/schema\\\/person\\\/b0ed444c71c4c8afa6f4ae674967c999\"},\"headline\":\"Bioan\u00e1lisis de \u00c1cidos Nucleicos: Ampliando las capacidades anal\u00edticas con LC-MS\\\/MS\",\"datePublished\":\"2026-07-24T06:49:02+00:00\",\"dateModified\":\"2026-07-24T06:53:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/\"},\"wordCount\":2136,\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/NUAC-LCMSMS-Header-Article.png\",\"articleSection\":[\"Bioan\u00e1lisis\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/\",\"url\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/\",\"name\":\"Bioan\u00e1lisis LC-MS\\\/MS para \u00c1cidos Nucleicos - Kymos Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/NUAC-LCMSMS-Header-Article.png\",\"datePublished\":\"2026-07-24T06:49:02+00:00\",\"dateModified\":\"2026-07-24T06:53:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/#\\\/schema\\\/person\\\/b0ed444c71c4c8afa6f4ae674967c999\"},\"description\":\"Descubra c\u00f3mo la LC-MS\\\/MS y la hibridaci\u00f3n de perlas magn\u00e9ticas secuencia-espec\u00edfica apoyan el bioan\u00e1lisis de oligonucle\u00f3tidos terap\u00e9uticos desde estudios precl\u00ednicos hasta cl\u00ednicos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/NUAC-LCMSMS-Header-Article.png\",\"contentUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/NUAC-LCMSMS-Header-Article.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kymos.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bioan\u00e1lisis de \u00c1cidos Nucleicos: Ampliando las capacidades anal\u00edticas con LC-MS\\\/MS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kymos.com\\\/es\\\/\",\"name\":\"Kymos Group\",\"description\":\"Kymos Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kymos.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kymos.com\\\/es\\\/#\\\/schema\\\/person\\\/b0ed444c71c4c8afa6f4ae674967c999\",\"name\":\"Sandra Magdaleno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g\",\"caption\":\"Sandra Magdaleno\"},\"url\":\"https:\\\/\\\/kymos.com\\\/es\\\/news\\\/author\\\/sandra-magdaleno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bioan\u00e1lisis LC-MS\/MS para \u00c1cidos Nucleicos - Kymos Group","description":"Descubra c\u00f3mo la LC-MS\/MS y la hibridaci\u00f3n de perlas magn\u00e9ticas secuencia-espec\u00edfica apoyan el bioan\u00e1lisis de oligonucle\u00f3tidos terap\u00e9uticos desde estudios precl\u00ednicos hasta cl\u00ednicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/","og_locale":"es_ES","og_type":"article","og_title":"Bioan\u00e1lisis LC-MS\/MS para \u00c1cidos Nucleicos - Kymos Group","og_description":"Descubra c\u00f3mo la LC-MS\/MS y la hibridaci\u00f3n de perlas magn\u00e9ticas secuencia-espec\u00edfica apoyan el bioan\u00e1lisis de oligonucle\u00f3tidos terap\u00e9uticos desde estudios precl\u00ednicos hasta cl\u00ednicos.","og_url":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/","og_site_name":"Kymos","article_published_time":"2026-07-24T06:49:02+00:00","article_modified_time":"2026-07-24T06:53:55+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/NUAC-LCMSMS-Header-Article.png","type":"image\/png"}],"author":"Sandra Magdaleno","twitter_card":"summary_large_image","twitter_creator":"@KymosGroup","twitter_site":"@KymosGroup","twitter_misc":{"Escrito por":"Sandra Magdaleno","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/#article","isPartOf":{"@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/"},"author":{"name":"Sandra Magdaleno","@id":"https:\/\/kymos.com\/es\/#\/schema\/person\/b0ed444c71c4c8afa6f4ae674967c999"},"headline":"Bioan\u00e1lisis de \u00c1cidos Nucleicos: Ampliando las capacidades anal\u00edticas con LC-MS\/MS","datePublished":"2026-07-24T06:49:02+00:00","dateModified":"2026-07-24T06:53:55+00:00","mainEntityOfPage":{"@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/"},"wordCount":2136,"image":{"@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/NUAC-LCMSMS-Header-Article.png","articleSection":["Bioan\u00e1lisis"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/","url":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/","name":"Bioan\u00e1lisis LC-MS\/MS para \u00c1cidos Nucleicos - Kymos Group","isPartOf":{"@id":"https:\/\/kymos.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/#primaryimage"},"image":{"@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/NUAC-LCMSMS-Header-Article.png","datePublished":"2026-07-24T06:49:02+00:00","dateModified":"2026-07-24T06:53:55+00:00","author":{"@id":"https:\/\/kymos.com\/es\/#\/schema\/person\/b0ed444c71c4c8afa6f4ae674967c999"},"description":"Descubra c\u00f3mo la LC-MS\/MS y la hibridaci\u00f3n de perlas magn\u00e9ticas secuencia-espec\u00edfica apoyan el bioan\u00e1lisis de oligonucle\u00f3tidos terap\u00e9uticos desde estudios precl\u00ednicos hasta cl\u00ednicos.","breadcrumb":{"@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/#primaryimage","url":"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/NUAC-LCMSMS-Header-Article.png","contentUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2026\/07\/NUAC-LCMSMS-Header-Article.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/kymos.com\/es\/news\/bioanalisis-de-acidos-nucleicos-ampliando-las-capacidades-analiticas-con-lc-ms-ms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kymos.com\/es\/"},{"@type":"ListItem","position":2,"name":"Bioan\u00e1lisis de \u00c1cidos Nucleicos: Ampliando las capacidades anal\u00edticas con LC-MS\/MS"}]},{"@type":"WebSite","@id":"https:\/\/kymos.com\/es\/#website","url":"https:\/\/kymos.com\/es\/","name":"Kymos Group","description":"Kymos Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kymos.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/kymos.com\/es\/#\/schema\/person\/b0ed444c71c4c8afa6f4ae674967c999","name":"Sandra Magdaleno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g","caption":"Sandra Magdaleno"},"url":"https:\/\/kymos.com\/es\/news\/author\/sandra-magdaleno\/"}]}},"_links":{"self":[{"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/posts\/47625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/comments?post=47625"}],"version-history":[{"count":3,"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/posts\/47625\/revisions"}],"predecessor-version":[{"id":47631,"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/posts\/47625\/revisions\/47631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/media\/47608"}],"wp:attachment":[{"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/media?parent=47625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/categories?post=47625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kymos.com\/es\/wp-json\/wp\/v2\/tags?post=47625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}