{"id":28405,"date":"2025-11-07T08:38:16","date_gmt":"2025-11-07T07:38:16","guid":{"rendered":"https:\/\/kymos.com\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/"},"modified":"2025-12-03T19:05:26","modified_gmt":"2025-12-03T18:05:26","slug":"biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd","status":"publish","type":"post","link":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/","title":{"rendered":"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit und PK\/PD"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1170px + 20px );margin-left: calc(-20px \/ 2 );margin-right: calc(-20px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:10px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:10px;--awb-width-medium:100%;--awb-spacing-right-medium:10px;--awb-spacing-left-medium:10px;--awb-width-small:100%;--awb-spacing-right-small:10px;--awb-spacing-left-small:10px;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><span style=\"font-size: 14pt;\">Obwohl die Entwicklung von Biosimilars in der Vergangenheit schwierig, kostspielig und zeitaufwendig war, stellen sie die L\u00f6sung dar, um den Zugang von Patienten zu lebensrettenden Biologika zu verbessern. Traditionell galten best\u00e4tigende Phase-III-Studien zur vergleichenden Wirksamkeit und Sicherheit (CES) als Standardvoraussetzung f\u00fcr die Zulassung, doch dies hat sich k\u00fcrzlich ge\u00e4ndert. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Im Jahr 2025 ver\u00f6ffentlichten sowohl die US-amerikanische Arzneimittelbeh\u00f6rde FDA als auch die Europ\u00e4ische Arzneimittel-Agentur EMA wichtige Aktualisierungen, die best\u00e4tigen, dass in den meisten F\u00e4llen keine best\u00e4tigenden Phase-III-Studien mehr erforderlich sein werden. Stattdessen werden robuste analytische Vergleichbarkeitsdaten, untermauert durch pharmakokinetische (PK) und gegebenenfalls pharmakodynamische (PD) Studien, der erforderliche Standard f\u00fcr die Zulassung von Biosimilars sein. <\/span><\/p>\n<h2><strong>Wichtigste Erkenntnisse  <\/strong><\/h2>\n<ul>\n<li><span style=\"font-size: 14pt;\">EMA und FDA verzichten f\u00fcr die meisten Biosimilars auf die kostspieligen Wirksamkeitsstudien der Phase III.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Analytische Vergleichbarkeit, PK\/PD-Studien und Immunogenit\u00e4tstests bilden heute den Kern der Biosimilar-Entwicklung.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Die globalen Regulierungsbeh\u00f6rden stimmen sich ab, um den Patientenzugang zu erleichtern und die Entwicklung von Biosimilars zu beschleunigen.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Dies er\u00f6ffnet Entwicklern die M\u00f6glichkeit, Kosten und Entwicklungszeiten zu reduzieren, erfordert aber gleichzeitig robuste Analysen sowie eine intelligentere und schnellere Entwicklungsplanung.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\">In diesem Artikel fassen wir zusammen, was diese regulatorischen \u00c4nderungen f\u00fcr Biosimilar-Entwickler bedeuten, warum analytische Vergleichbarkeit und PK\/PD-Studien jetzt im Fokus stehen und wie die Kymos Group Unternehmen dabei unterst\u00fctzen kann, diesen neuen Entwicklungsweg zu beschreiten.<\/p>\n<p><\/span><\/p>\n<h2><strong>Die regulatorische \u00c4nderung: Angleichung von EMA und FDA<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Laut dem <em>Entwurf des Reflexionspapiers der EMA zu einem ma\u00dfgeschneiderten klinischen Ansatz in der Biosimilar-Entwicklung<\/em> erm\u00f6glicht der Nachweis einer hohen \u00c4hnlichkeit in Struktur, Funktion und Pharmakokinetik (PK) durch umfassende Studien die Schlussfolgerung auf die klinische Wirksamkeit. Daher sind Vergleichbarkeitsdaten f\u00fcr Struktur, Funktion und PK die Hauptvoraussetzung f\u00fcr die Zulassung von Biosimilars. Vergleichende klinische Wirksamkeitsstudien (CES) sind nur dann erforderlich, wenn der Wirkmechanismus des Wirkstoffs unzureichend verstanden ist oder wenn identifizierte strukturelle und funktionelle Unterschiede die klinischen Ergebnisse beeinflussen k\u00f6nnten.  <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Ebenso hat die FDA k\u00fcrzlich erstmals einen Antrag auf Befreiung von klinischen Wirksamkeitsstudien f\u00fcr monoklonale Antik\u00f6rper-Biosimilars genehmigt. Dies geschah zeitgleich mit der Ver\u00f6ffentlichung der FDA-Leitlinie zur <em>vergleichenden analytischen Bewertung und anderen qualit\u00e4tsbezogenen \u00dcberlegungen<\/em> , die eine umfassende und detaillierte Beschreibung der analytischen Anforderungen zum Nachweis der nahtlosen Vergleichbarkeit zwischen einem Biosimilar und seinem Referenzprodukt enth\u00e4lt. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">In der Praxis bedeutet dies, dass CES-Studien nicht mehr standardm\u00e4\u00dfig erforderlich sind. Stattdessen erwarten die Beh\u00f6rden nun von den Entwicklern, dass sie sich auf einen umfassenden Evidenzansatz st\u00fctzen, der analytische Daten, funktionelle Assays, PK\/PD-Studien und Immunogenit\u00e4tstests umfasst, um die Biosimilarit\u00e4t nachzuweisen. Neben der EMA und der FDA \u00fcberarbeiten auch andere Regulierungsbeh\u00f6rden wie die WHO oder Health Canada ihre Leitlinien, um unn\u00f6tige klinische Studien zu reduzieren und so einen harmonisierten globalen Rahmen zu schaffen.  <\/p>\n<p><\/span><\/p>\n<h2><strong>Von Phase III bis hin zu Analytik und PK\/PD<br \/><\/strong><\/h2>\n<h3><strong>Warum Phase-III-Studien neu bewertet werden<\/p>\n<p><\/strong><\/h3>\n<p><span style=\"font-size: 14pt;\">Gro\u00dfe CES-Studien waren in der Vergangenheit zeit- und ressourcenintensiv und erforderten Hunderte von Patienten, die kostspielige Beschaffung von Vergleichspr\u00e4paraten sowie lange Nachbeobachtungszeitr\u00e4ume. Die regulatorische Erfahrung zeigt jedoch, dass Produkte, die die Biosimilarit\u00e4tsstandards erf\u00fcllen, in Phase III selten klinisch relevante Unterschiede aufweisen. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Aus diesem Grund setzt sich der neue Standard f\u00fcr die Entwicklung von Biosimilars wie folgt zusammen:<\/span><\/p>\n<h3><\/h3>\n<p><span style=\"font-size: 14pt;\"><strong>Analytische Vergleichbarkeit<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Eine umfassende physikalisch-chemische und funktionelle Charakterisierung ist die Grundlage. Entwickler m\u00fcssen: <\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Beurteilung der Prim\u00e4r- und Quart\u00e4rstruktur, posttranslationaler Modifikationen und produktbezogener Varianten.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Verwenden Sie orthogonale, hochmoderne Analysemethoden.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Um die Variabilit\u00e4t zu verstehen, sollten mehrere Chargen sowohl des Referenzprodukts als auch des Biosimilars getestet werden.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Wenden Sie einen risikobasierten Ansatz an, um kritische Qualit\u00e4tsmerkmale (CQAs) zu identifizieren und diese mit der klinischen Leistung zu verkn\u00fcpfen.<\/span><\/li>\n<\/ul>\n<h3><span style=\"font-size: 14pt;\"><strong>PK- und PD-Studien<\/p>\n<p><\/strong><\/span><\/h3>\n<p><span style=\"font-size: 14pt;\">Pharmakokinetische Studien am Menschen sind weiterhin unerl\u00e4sslich und werden h\u00e4ufig als Crossover-Studien mit Einzeldosis durchgef\u00fchrt, um Absorption und Elimination zwischen Biosimilar und Referenzprodukt zu vergleichen. Pharmakodynamische Endpunkte k\u00f6nnen verwendet werden, sofern ein validierter Surrogatmarker verf\u00fcgbar ist. Immunogenit\u00e4tsdaten werden typischerweise parallel zu den pharmakokinetischen Daten erhoben.  <\/span><\/p>\n<h3><span style=\"font-size: 14pt;\"><strong>Immunogenit\u00e4tsbewertung<\/p>\n<p><\/strong><\/span><\/h3>\n<p><span style=\"font-size: 14pt;\">Bindende und neutralisierende Antik\u00f6rper gegen das Medikament (ADAs, NAbs) m\u00fcssen gemessen werden, um Immunreaktionen auszuschlie\u00dfen, die die Wirksamkeit oder Sicherheit beeintr\u00e4chtigen k\u00f6nnten. Die aktuellen Leitlinien empfehlen ein gestuftes Vorgehen: Screening auf bindende Antik\u00f6rper, Best\u00e4tigungstests und gegebenenfalls Charakterisierung der neutralisierenden Aktivit\u00e4t. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Zusammen bilden diese drei Teile die \u201eGesamtheit der Beweise\u201c, die erforderlich sind, um Biosimilarit\u00e4t ohne die Notwendigkeit gro\u00dfer Wirksamkeitsstudien nachzuweisen.<\/p>\n<p><\/span><\/p>\n<h2><strong>Was dies f\u00fcr Biosimilar-Entwickler bedeutet<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Diese regulatorische \u00c4nderung er\u00f6ffnet neue M\u00f6glichkeiten und Chancen f\u00fcr Biosimilar-Entwickler, weckt aber auch in bestimmten Bereichen h\u00f6here Erwartungen. Einerseits wird der Wegfall obligatorischer Phase-III-Studien die Entwicklung beschleunigen und die Marktteilnahme im Biosimilar-Bereich erweitern. Andererseits erfordert sie h\u00f6here analytische Anforderungen, sorgf\u00e4ltige Planung und eine enge Abstimmung mit den Zulassungsbeh\u00f6rden.  <\/span><\/p>\n<h3><strong>Gelegenheiten<\/strong><\/h3>\n<ul>\n<li><span style=\"font-size: 14pt;\"><strong>Geringere Kosten und k\u00fcrzere Entwicklungszeiten:<\/strong> Durch den Wegfall von Phase-III-Studien kann die Entwicklungszeit um mehrere Jahre verk\u00fcrzt werden.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Gr\u00f6\u00dfere Marktteilnahme:<\/strong> Kleinere und mittelst\u00e4ndische biopharmazeutische Unternehmen k\u00f6nnen nun im Biosimilar-Bereich konkurrieren.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Regulatorische Klarheit:<\/strong> Die Harmonisierung globaler Richtlinien erm\u00f6glicht einen besser vorhersehbaren Entwicklungspfad.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Pr\u00e4zedenzf\u00e4lle aus der Praxis:<\/strong> Mehrere neuere Biosimilars wurden bereits ohne Phase-III-Studien zugelassen, was zeigt, dass optimierte Zulassungsverfahren nicht nur theoretisch sind, sondern bereits von den Regulierungsbeh\u00f6rden umgesetzt werden.<\/span><\/li>\n<\/ul>\n<h3><strong>Neue Anforderungen<\/strong><\/h3>\n<ul>\n<li><span style=\"font-size: 14pt;\"><strong>H\u00f6here analytische Standards:<\/strong> Sensible, orthogonale Methoden und umfassende Risikobewertungen sind obligatorisch.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Fr\u00fchzeitige Planung:<\/strong> Es wird empfohlen, vor Beginn der Zulassungsstudien ein vorher vereinbartes \u00c4hnlichkeitsbewertungsprotokoll zu erstellen.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Strenge Fertigungskontrollen:<\/strong> Die Konsistenz der kommerziellen Chargen ist entscheidend f\u00fcr die Untermauerung von \u00c4hnlichkeitsbehauptungen.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Einbindung der Regulierungsbeh\u00f6rden:<\/strong> Es wird empfohlen, fr\u00fchzeitig wissenschaftliche Beratungsgespr\u00e4che mit der EMA oder der FDA zu f\u00fchren, um die Studiendesigns abzustimmen und \u00dcberraschungen zu vermeiden.\n<p><\/span><\/li>\n<\/ul>\n<h2><strong>Wann Phase III m\u00f6glicherweise noch erforderlich ist<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Obwohl die Standarderwartung nun \u201ekeine klinischen Studien\u201c lautet, gibt es weiterhin Situationen, in denen klinische Wirksamkeitsstudien erforderlich sein k\u00f6nnen. Phase-III-Studien k\u00f6nnen weiterhin f\u00fcr Produkte mit unklaren oder komplexen Wirkmechanismen oder in F\u00e4llen, in denen analytische Daten und funktionelle Assays die klinische Leistung nicht ausreichend vorhersagen, notwendig sein. Ebenso k\u00f6nnen unerwartete Immunogenit\u00e4tssignale w\u00e4hrend PK-Studien zus\u00e4tzliche Wirksamkeits- und Sicherheitsdaten erforderlich machen.  <\/p>\n<p><\/span><\/p>\n<h2><strong>Wie die Kymos Group helfen kann<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Die Kymos Group bietet ein umfassendes Leistungsspektrum zur Unterst\u00fctzung von Biosimilar-Entwicklern in dieser neuen regulatorischen Situation:<\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\"><strong>Analytische Vergleichbarkeit:<\/strong> Umfassende CMC-Charakterisierung, einschlie\u00dflich physikochemischer, funktioneller und Wirkst\u00e4rkebestimmungen gem\u00e4\u00df GMP. Erfahren Sie mehr \u00fcber unsere CMC-Analysedienstleistungen. <\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Bioanalytik &amp; PK-Studien:<\/strong> GLP-konforme PK- und Immunogenit\u00e4tspr\u00fcfung (ADA, NAb) aus unseren Laboren in Spanien und Deutschland. Entdecken Sie unsere M\u00f6glichkeiten zur Immunogenit\u00e4tspr\u00fcfung. <\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Integrierte L\u00f6sungen:<\/strong> Partnerschaften mit spezialisierten klinischen Einheiten erm\u00f6glichen es uns, vollst\u00e4ndige PK\/PD-Studien durchzuf\u00fchren, die die klinische Durchf\u00fchrung mit der hauseigenen Bioanalytik kombinieren.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><strong>Regulatorische Expertise:<\/strong> Unsere Teams konzipieren zweckorientierte Studien, die den Richtlinien der EMA, FDA und ICH entsprechen und sicherstellen, dass Ihre Ergebnisse zur Einreichung bereit sind.\n<p><\/span><\/li>\n<\/ul>\n<h2><strong>Schlussfolgerungen<\/strong><\/h2>\n<p><span style=\"font-size: 14pt;\">Der Markt f\u00fcr Biosimilars hat sich in den letzten Jahren rasant entwickelt, und dieser Wandel markiert einen Paradigmenwechsel in ihrer Entwicklung. Indem die Bedeutung umfangreicher Phase-III-Studien reduziert wird, setzen die Zulassungsbeh\u00f6rden verst\u00e4rkt auf einen wissenschaftlich fundierten und effizienzorientierten Ansatz mit Fokus auf fundierte Analysen und intelligente Entwicklungsplanung. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Das neue Umfeld f\u00fcr Biosimilars er\u00f6ffnet Entwicklern neue Chancen und unterstreicht die Bedeutung der Zusammenarbeit mit vertrauensw\u00fcrdigen Analysepartnern wie Kymos. Unsere europ\u00e4ischen Labore bieten umfassende analytische Vergleichbarkeit, Bioanalysen und PK\/PD-Studien und erf\u00fcllen alle erforderlichen Standards. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Gemeinsam erm\u00f6glichen uns diese St\u00e4rken, Biosimilar-Entwickler zu unterst\u00fctzen, die neue Erwartungen erf\u00fcllen und ihre Markteinf\u00fchrungszeit verk\u00fcrzen m\u00fcssen, w\u00e4hrend sie gleichzeitig die regulatorischen Anforderungen erf\u00fcllen.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Nehmen Sie noch heute Kontakt mit uns auf, um zu besprechen, wie wir Ihr Biosimilar-Programm unterst\u00fctzen und Ihnen helfen k\u00f6nnen, die neuesten regulatorischen Neuerungen optimal zu nutzen.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":28406,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[254,266],"tags":[67],"class_list":["post-28405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioanalyse","category-cmc","tag-carles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit<\/title>\n<meta name=\"description\" content=\"Erfahren Sie mehr \u00fcber die j\u00fcngsten Ver\u00e4nderungen in der Biosimilar-Entwicklung und dar\u00fcber, wie analytische Vergleichbarkeit und PK\/PD zum neuen Standard geworden sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie mehr \u00fcber die j\u00fcngsten Ver\u00e4nderungen in der Biosimilar-Entwicklung und dar\u00fcber, wie analytische Vergleichbarkeit und PK\/PD zum neuen Standard geworden sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/\" \/>\n<meta property=\"og:site_name\" content=\"Kymos\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T07:38:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T18:05:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kymos.com\/wp-content\/uploads\/2025\/11\/Biosimilar-Development-Article-Header.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sandra Magdaleno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:site\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Magdaleno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/\"},\"author\":{\"name\":\"Sandra Magdaleno\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/b0ed444c71c4c8afa6f4ae674967c999\"},\"headline\":\"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit und PK\\\/PD\",\"datePublished\":\"2025-11-07T07:38:16+00:00\",\"dateModified\":\"2025-12-03T18:05:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/\"},\"wordCount\":1441,\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Biosimilar-Development-Article-Header.png\",\"keywords\":[\"carles\"],\"articleSection\":[\"Bioanalyse\",\"CMC\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/\",\"name\":\"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Biosimilar-Development-Article-Header.png\",\"datePublished\":\"2025-11-07T07:38:16+00:00\",\"dateModified\":\"2025-12-03T18:05:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/b0ed444c71c4c8afa6f4ae674967c999\"},\"description\":\"Erfahren Sie mehr \u00fcber die j\u00fcngsten Ver\u00e4nderungen in der Biosimilar-Entwicklung und dar\u00fcber, wie analytische Vergleichbarkeit und PK\\\/PD zum neuen Standard geworden sind.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Biosimilar-Development-Article-Header.png\",\"contentUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Biosimilar-Development-Article-Header.png\",\"width\":1600,\"height\":900,\"caption\":\"Biosimilar Development Article Header\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kymos.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit und PK\\\/PD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/\",\"name\":\"Kymos Group\",\"description\":\"Kymos Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kymos.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/b0ed444c71c4c8afa6f4ae674967c999\",\"name\":\"Sandra Magdaleno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g\",\"caption\":\"Sandra Magdaleno\"},\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/author\\\/sandra-magdaleno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit","description":"Erfahren Sie mehr \u00fcber die j\u00fcngsten Ver\u00e4nderungen in der Biosimilar-Entwicklung und dar\u00fcber, wie analytische Vergleichbarkeit und PK\/PD zum neuen Standard geworden sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/","og_locale":"de_DE","og_type":"article","og_title":"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit","og_description":"Erfahren Sie mehr \u00fcber die j\u00fcngsten Ver\u00e4nderungen in der Biosimilar-Entwicklung und dar\u00fcber, wie analytische Vergleichbarkeit und PK\/PD zum neuen Standard geworden sind.","og_url":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/","og_site_name":"Kymos","article_published_time":"2025-11-07T07:38:16+00:00","article_modified_time":"2025-12-03T18:05:26+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/kymos.com\/wp-content\/uploads\/2025\/11\/Biosimilar-Development-Article-Header.png","type":"image\/png"}],"author":"Sandra Magdaleno","twitter_card":"summary_large_image","twitter_creator":"@KymosGroup","twitter_site":"@KymosGroup","twitter_misc":{"Verfasst von":"Sandra Magdaleno","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/#article","isPartOf":{"@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/"},"author":{"name":"Sandra Magdaleno","@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/b0ed444c71c4c8afa6f4ae674967c999"},"headline":"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit und PK\/PD","datePublished":"2025-11-07T07:38:16+00:00","dateModified":"2025-12-03T18:05:26+00:00","mainEntityOfPage":{"@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/"},"wordCount":1441,"image":{"@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2025\/11\/Biosimilar-Development-Article-Header.png","keywords":["carles"],"articleSection":["Bioanalyse","CMC"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/","url":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/","name":"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit","isPartOf":{"@id":"https:\/\/kymos.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/#primaryimage"},"image":{"@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2025\/11\/Biosimilar-Development-Article-Header.png","datePublished":"2025-11-07T07:38:16+00:00","dateModified":"2025-12-03T18:05:26+00:00","author":{"@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/b0ed444c71c4c8afa6f4ae674967c999"},"description":"Erfahren Sie mehr \u00fcber die j\u00fcngsten Ver\u00e4nderungen in der Biosimilar-Entwicklung und dar\u00fcber, wie analytische Vergleichbarkeit und PK\/PD zum neuen Standard geworden sind.","breadcrumb":{"@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/#primaryimage","url":"https:\/\/kymos.com\/wp-content\/uploads\/2025\/11\/Biosimilar-Development-Article-Header.png","contentUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2025\/11\/Biosimilar-Development-Article-Header.png","width":1600,"height":900,"caption":"Biosimilar Development Article Header"},{"@type":"BreadcrumbList","@id":"https:\/\/kymos.com\/de\/news\/biosimilar-entwicklung-von-phase-iii-zur-analytischen-vergleichbarkeit-und-pk-pd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kymos.com\/de\/"},{"@type":"ListItem","position":2,"name":"Biosimilar-Entwicklung: Von Phase III zur analytischen Vergleichbarkeit und PK\/PD"}]},{"@type":"WebSite","@id":"https:\/\/kymos.com\/de\/#website","url":"https:\/\/kymos.com\/de\/","name":"Kymos Group","description":"Kymos Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kymos.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/b0ed444c71c4c8afa6f4ae674967c999","name":"Sandra Magdaleno","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc2f5bf2cac304990fdc84e9a3ed0b47c89ed981aaa966dfb2f3c3f39f531df6?s=96&d=mm&r=g","caption":"Sandra Magdaleno"},"url":"https:\/\/kymos.com\/de\/news\/author\/sandra-magdaleno\/"}]}},"_links":{"self":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts\/28405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/comments?post=28405"}],"version-history":[{"count":0,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts\/28405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/media\/28406"}],"wp:attachment":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/media?parent=28405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/categories?post=28405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/tags?post=28405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}