{"id":28092,"date":"2023-06-19T14:34:46","date_gmt":"2023-06-19T12:34:46","guid":{"rendered":"https:\/\/kymos.com\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/"},"modified":"2023-06-19T14:34:46","modified_gmt":"2023-06-19T12:34:46","slug":"arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie","status":"publish","type":"post","link":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/","title":{"rendered":"Arzneimittel f\u00fcr neuartige Therapien: Erste Plattform f\u00fcr adeno-assoziierte Viren in der Gentherapie"},"content":{"rendered":"<p>Kymos hat sich mit der VIRAL VECTOR PRODUCTION UNIT \u2013 einer Kooperation zwischen der Autonomen Universit\u00e4t Barcelona und dem Forschungsinstitut Vall d\u2019Hebron \u2013 zusammengeschlossen, um die Gentherapie ma\u00dfgeblich voranzubringen. Gemeinsam entwickeln wir eine hochmoderne Technologieplattform f\u00fcr Gentherapie-Assays, insbesondere f\u00fcr adeno-assoziierte Viren (AAV). <\/p>\n<p>Im Rahmen des CDTI-Projekts IDI-20230061, das Kymos am 27. Januar 2023 zugewiesen wurde, verfolgt diese Kooperation zwei zentrale Ziele. Erstens soll die erste technologische Testplattform zur Charakterisierung und Definition der Qualit\u00e4tsmerkmale von Gentherapeutika gegen adeno-assoziierte Viren entwickelt werden. Zweitens strebt das Projekt die Einf\u00fchrung eines umfassenden Charakterisierungs- und Qualit\u00e4tskontrollservices in einem regulierten und validierten Umfeld an. Durch das Erreichen dieser Ziele soll die Entwicklungszeit neuer Gentherapeutika deutlich verk\u00fcrzt werden.   <\/p>\n<p>Die strategische Bedeutung dieser Forschung hat die Unterst\u00fctzung des CARLOS III HEALTH INSTITUTE (ISCIII) und des CENTER FOR TECHNOLOGICAL AND INDUSTRIAL DEVELOPMENT (CDTI) nach sich gezogen. Sie wurde in das Strategische Projekt \u201eVanguard\u201c zur wirtschaftlichen Erholung und Transformation im Gesundheitswesen aufgenommen \u2013 ein wichtiger Bestandteil des umfassenderen Plans \u201eWiederaufbau, Transformation und Resilienz\u201c, der durch Mittel von NextGenerationEU gef\u00f6rdert wird. Zur weiteren Unterst\u00fctzung dieser Forschung erhielt das Projekt zudem F\u00f6rdermittel aus dem TORRES QUEVEDO-Zuschuss mit der Vertragsnummer PTQ2021-012177 vom 1. November 2022.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kymos hat sich mit der VIRAL VECTOR PRODUCTION UNIT \u2013  [&#8230;]<\/p>\n","protected":false},"author":7,"featured_media":28096,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[254,266],"tags":[67],"class_list":["post-28092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioanalyse","category-cmc","tag-carles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ATMPs: Arzneimittel f\u00fcr neuartige Therapien | Kymos-Gruppe<\/title>\n<meta name=\"description\" content=\"Pressemitteilung \u00fcber die Erforschung und Entwicklung der ersten technologischen Testplattform f\u00fcr adenoassoziierte Viren in der Gentherapie durch Kymos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATMPs: Arzneimittel f\u00fcr neuartige Therapien | Kymos-Gruppe\" \/>\n<meta property=\"og:description\" content=\"Pressemitteilung \u00fcber die Erforschung und Entwicklung der ersten technologischen Testplattform f\u00fcr adenoassoziierte Viren in der Gentherapie durch Kymos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/\" \/>\n<meta property=\"og:site_name\" content=\"Kymos\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-19T12:34:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kymos.com\/wp-content\/uploads\/2023\/06\/Captura-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1397\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carles Celma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:site\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carles Celma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/\"},\"author\":{\"name\":\"Carles Celma\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/3d86e112b87df4b5c1304ce33368ef23\"},\"headline\":\"Arzneimittel f\u00fcr neuartige Therapien: Erste Plattform f\u00fcr adeno-assoziierte Viren in der Gentherapie\",\"datePublished\":\"2023-06-19T12:34:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/\"},\"wordCount\":213,\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Captura-2.jpg\",\"keywords\":[\"carles\"],\"articleSection\":[\"Bioanalyse\",\"CMC\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/\",\"name\":\"ATMPs: Arzneimittel f\u00fcr neuartige Therapien | Kymos-Gruppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Captura-2.jpg\",\"datePublished\":\"2023-06-19T12:34:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/3d86e112b87df4b5c1304ce33368ef23\"},\"description\":\"Pressemitteilung \u00fcber die Erforschung und Entwicklung der ersten technologischen Testplattform f\u00fcr adenoassoziierte Viren in der Gentherapie durch Kymos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Captura-2.jpg\",\"contentUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Captura-2.jpg\",\"width\":1397,\"height\":720,\"caption\":\"ATMPs: Project collaboration between Kymos and UPV\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kymos.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arzneimittel f\u00fcr neuartige Therapien: Erste Plattform f\u00fcr adeno-assoziierte Viren in der Gentherapie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/\",\"name\":\"Kymos Group\",\"description\":\"Kymos Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kymos.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/3d86e112b87df4b5c1304ce33368ef23\",\"name\":\"Carles Celma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g\",\"caption\":\"Carles Celma\"},\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/author\\\/dr-carles-celma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ATMPs: Arzneimittel f\u00fcr neuartige Therapien | Kymos-Gruppe","description":"Pressemitteilung \u00fcber die Erforschung und Entwicklung der ersten technologischen Testplattform f\u00fcr adenoassoziierte Viren in der Gentherapie durch Kymos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/","og_locale":"de_DE","og_type":"article","og_title":"ATMPs: Arzneimittel f\u00fcr neuartige Therapien | Kymos-Gruppe","og_description":"Pressemitteilung \u00fcber die Erforschung und Entwicklung der ersten technologischen Testplattform f\u00fcr adenoassoziierte Viren in der Gentherapie durch Kymos.","og_url":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/","og_site_name":"Kymos","article_published_time":"2023-06-19T12:34:46+00:00","og_image":[{"width":1397,"height":720,"url":"https:\/\/kymos.com\/wp-content\/uploads\/2023\/06\/Captura-2.jpg","type":"image\/jpeg"}],"author":"Carles Celma","twitter_card":"summary_large_image","twitter_creator":"@KymosGroup","twitter_site":"@KymosGroup","twitter_misc":{"Verfasst von":"Carles Celma","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/#article","isPartOf":{"@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/"},"author":{"name":"Carles Celma","@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/3d86e112b87df4b5c1304ce33368ef23"},"headline":"Arzneimittel f\u00fcr neuartige Therapien: Erste Plattform f\u00fcr adeno-assoziierte Viren in der Gentherapie","datePublished":"2023-06-19T12:34:46+00:00","mainEntityOfPage":{"@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/"},"wordCount":213,"image":{"@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2023\/06\/Captura-2.jpg","keywords":["carles"],"articleSection":["Bioanalyse","CMC"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/","url":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/","name":"ATMPs: Arzneimittel f\u00fcr neuartige Therapien | Kymos-Gruppe","isPartOf":{"@id":"https:\/\/kymos.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/#primaryimage"},"image":{"@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2023\/06\/Captura-2.jpg","datePublished":"2023-06-19T12:34:46+00:00","author":{"@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/3d86e112b87df4b5c1304ce33368ef23"},"description":"Pressemitteilung \u00fcber die Erforschung und Entwicklung der ersten technologischen Testplattform f\u00fcr adenoassoziierte Viren in der Gentherapie durch Kymos.","breadcrumb":{"@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/#primaryimage","url":"https:\/\/kymos.com\/wp-content\/uploads\/2023\/06\/Captura-2.jpg","contentUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2023\/06\/Captura-2.jpg","width":1397,"height":720,"caption":"ATMPs: Project collaboration between Kymos and UPV"},{"@type":"BreadcrumbList","@id":"https:\/\/kymos.com\/de\/news\/arzneimittel-fuer-neuartige-therapien-erste-plattform-fuer-adeno-assoziierte-viren-in-der-gentherapie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kymos.com\/de\/"},{"@type":"ListItem","position":2,"name":"Arzneimittel f\u00fcr neuartige Therapien: Erste Plattform f\u00fcr adeno-assoziierte Viren in der Gentherapie"}]},{"@type":"WebSite","@id":"https:\/\/kymos.com\/de\/#website","url":"https:\/\/kymos.com\/de\/","name":"Kymos Group","description":"Kymos Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kymos.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/3d86e112b87df4b5c1304ce33368ef23","name":"Carles Celma","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7ec8bcf3304288056fadfac1c80186a100e5bc223991385f6f2e5e4c8a55099?s=96&d=mm&r=g","caption":"Carles Celma"},"url":"https:\/\/kymos.com\/de\/news\/author\/dr-carles-celma\/"}]}},"_links":{"self":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts\/28092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/comments?post=28092"}],"version-history":[{"count":0,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts\/28092\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/media\/28096"}],"wp:attachment":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/media?parent=28092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/categories?post=28092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/tags?post=28092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}