{"id":27325,"date":"2020-05-18T10:57:45","date_gmt":"2020-05-18T08:57:45","guid":{"rendered":"https:\/\/kymos.com\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/"},"modified":"2020-05-18T10:57:45","modified_gmt":"2020-05-18T08:57:45","slug":"immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet","status":"publish","type":"post","link":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/","title":{"rendered":"Immunologie: Gemeinsam f\u00fcr die n\u00e4chste Pandemie ger\u00fcstet"},"content":{"rendered":"<h3><span style=\"font-size: 14pt;\">Die Immunologie ist angesichts der zahlreichen Herausforderungen der COVID-19-Pandemie aktueller denn je. Die Welt wartet gespannt auf neue Therapien und Impfstoffe, um diese Krankheit zu bek\u00e4mpfen und so ein St\u00fcck Normalit\u00e4t in unser Leben zur\u00fcckzubringen.   <\/span><\/h3>\n<div class=\"blog-content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><span style=\"font-size: 14pt;\">Dr. Carles Morte, Immunologe bei KYMOS, erl\u00e4utert seine Zukunftsaussichten f\u00fcr vielversprechende neue Gen- und Zelltherapien sowie monoklonale Antik\u00f6rper gegen Viruserkrankungen und andere Krankheiten. Wir sprechen mit ihm \u00fcber die notwendige technische Bewertung, da das immer komplexer werdende Immunsystem zunehmend zum therapeutischen Ziel wird. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u201eIn den kommenden Jahren werden wir die Entwicklung neuer biologischer Therapien erleben, bei denen die Immunogenit\u00e4t eine wichtige Rolle spielt. Unser Team verf\u00fcgt \u00fcber das Fachwissen und die umfassende Erfahrung, um diese neuen Herausforderungen zu meistern.\u201c<\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Aktuelle Herausforderungen bei der \u00dcberwachung und Analyse neuer pharmazeutischer Biologika sowie Gen- und Zelltherapien<\/strong><\/span><br \/>\n<span style=\"font-size: 14pt;\">Das Immunsystem ist ein hochkomplexer und \u00e4u\u00dferst wichtiger Bestandteil unserer Krankheitsabwehr. Daher m\u00fcssen bei der Entwicklung neuer Gen- und Zelltherapien verschiedene Aspekte ber\u00fccksichtigt werden. <\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Arbeiten mit zellul\u00e4ren Systemen oder In-vivo-Reaktionen<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Ungleichgewicht des Immunsystems durch mehrere Ausl\u00f6ser (vom Medikament selbst und vom Vektor)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Patientenspezifische, bereits bestehende Immunogenit\u00e4t<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Zellul\u00e4re (T-Zell-vermittelte) und angeborene Immunantworten<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\">Carles leitet ein Team mit umfassender immunologischer Erfahrung aus der akademischen Forschung, der pharmazeutischen Industrie und Auftragsforschungsinstituten (CROs). Dank dieser Expertise verf\u00fcgt das Team \u00fcber das einzigartige Know-how, selbst die anspruchsvollsten technischen Projekte mithilfe verschiedener Analyseverfahren wie ELISA, Elektrochemilumineszenz, Durchflusszytometrie, ELISPOT oder zellbasierter Assays erfolgreich zu meistern. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Was unterscheidet Carles und sein Team von anderen CROs?<\/strong><\/span><br \/>\n<span style=\"font-size: 14pt;\">Das Expertenteam von Dr. Morte verf\u00fcgt \u00fcber umfangreiche Erfahrung in der Messung des Vorhandenseins von Antik\u00f6rpern und neutralisierenden Antik\u00f6rpern gegen verschiedene Medikamente, von kleinen Peptiden bis hin zu gro\u00dfen Proteinen wie Toxinen und Hormonen.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Das Team arbeitet \u00fcblicherweise an internationalen Projekten, die ein hohes Ma\u00df an Fachwissen erfordern, wie beispielsweise die Durchf\u00fchrung von Wirkungsassays f\u00fcr Biologika f\u00fcr mehrere Kunden in China und S\u00fcdkorea. Die Abteilung arbeitet au\u00dferdem mit zellul\u00e4ren Systemen, um die neutralisierende Wirkung von Antik\u00f6rpern zu bestimmen, was den Einsatz komplexerer analytischer Plattformen erfordert. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u201eKYMOS bietet eine umfassende Analyse von Biologika, die vollst\u00e4ndig in unserem Hauptlabor zentralisiert ist \u2013 von der physikalisch-chemischen Charakterisierung bis zur Marktfreigabe. Unsere Flexibilit\u00e4t und unser Verst\u00e4ndnis f\u00fcr die Bed\u00fcrfnisse unserer Kunden sind entscheidend, um deren Erwartungen zu erf\u00fcllen und zu \u00fcbertreffen.\u201c  <\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Wie wird sich der globale Markt f\u00fcr Biologika voraussichtlich in Zukunft entwickeln?<\/strong><\/span><br \/>\n<span style=\"font-size: 14pt;\">Infolge der COVID-19-Pandemie sind die Menschen besser denn je dar\u00fcber informiert, wie das Immunsystem vor Viren und anderen Krankheiten sch\u00fctzt. Wir k\u00f6nnen daher mit einer noch gr\u00f6\u00dferen Anzahl von Medikamenten rechnen, die auf das Immunsystem abzielen, wie beispielsweise Zytokin-neutralisierende monoklonale Antik\u00f6rper zur Blockierung viraler Effekte, neue Impfstoffe sowie andere Biosimilars. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Diagnostische Systeme, die Immunogenit\u00e4t und immunvermittelte Reaktionen messen, sind unerl\u00e4sslich und erfordern Entwicklung, Erprobung und Validierung, die nur hochspezialisierte Labore mit einem hohen Ma\u00df an Fachwissen und Erfahrung, wie KYMOS, leisten k\u00f6nnen.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u201eDies ist nicht die letzte neue Infektionskrankheit, mit der wir uns auseinandersetzen m\u00fcssen, aber gemeinsam k\u00f6nnen wir daran arbeiten, uns wirksam auf die n\u00e4chste vorzubereiten.\u201c<\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">KYMOS ist ein GLP\/GMP-zertifiziertes, GCP-konformes, von der EMA und der FDA inspiziertes europ\u00e4isches Auftragslabor, das sich auf die Bioanalyse gro\u00dfer Molek\u00fcle spezialisiert hat. Hier finden Sie weitere Informationen zu den Dienstleistungen von KYMOS im <a href=\"https:\/\/kymos.com\/de\/dienstleistungen\/praeklinische-und-klinische-dienstleistungen\/bioanalytik-und-immunogenitaet-von-biologika-und-biosimilars\/\" data-wpel-link=\"internal\">Bereich Bioanalyse und Immunogenit\u00e4t von Biologika und Biosimilars<\/a> sowie <a href=\"https:\/\/kymos.com\/de\/dienstleistungen\/cmc-analyse-und-qualitaetskontrolle\/zellbasierte-und-potenz-assays\/\" data-wpel-link=\"internal\">zu zellbasierten Therapien.<\/a> <a href=\"mailto:info@kymos.com\" data-wpel-link=\"internal\">Sie<\/a> k\u00f6nnen uns auch unter <a href=\"mailto:info@kymos.com?subject=Neue%20Instrumente%20bei%20Kymos\" data-wpel-link=\"internal\">commercial@kymos.com<\/a> kontaktieren. <\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Immunologie ist angesichts der zahlreichen Herausforderungen der COVID-19-Pandemie aktueller  [&#8230;]<\/p>\n","protected":false},"author":6,"featured_media":27327,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[254],"tags":[],"class_list":["post-27325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioanalyse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Immunologie: Vorbereitung auf die n\u00e4chste Pandemie | Kymos-Gruppe<\/title>\n<meta name=\"description\" content=\"Bleiben Sie \u00fcber die neuesten Forschungsergebnisse und Entwicklungen im Bereich der Immunologie informiert. Erfahren Sie, wie die Kymos Group Ihnen Wissen und Erfahrung vermitteln kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immunologie: Vorbereitung auf die n\u00e4chste Pandemie | Kymos-Gruppe\" \/>\n<meta property=\"og:description\" content=\"Bleiben Sie \u00fcber die neuesten Forschungsergebnisse und Entwicklungen im Bereich der Immunologie informiert. Erfahren Sie, wie die Kymos Group Ihnen Wissen und Erfahrung vermitteln kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/\" \/>\n<meta property=\"og:site_name\" content=\"Kymos\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T08:57:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Joan Puig de Dou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:site\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joan Puig de Dou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/\"},\"author\":{\"name\":\"Joan Puig de Dou\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/264c93ce9dcf43caa9d634aeafab965c\"},\"headline\":\"Immunologie: Gemeinsam f\u00fcr die n\u00e4chste Pandemie ger\u00fcstet\",\"datePublished\":\"2020-05-18T08:57:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/\"},\"wordCount\":599,\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Carles-Morte_Immunology_Short-e1658232189298.png\",\"articleSection\":[\"Bioanalyse\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/\",\"name\":\"Immunologie: Vorbereitung auf die n\u00e4chste Pandemie | Kymos-Gruppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Carles-Morte_Immunology_Short-e1658232189298.png\",\"datePublished\":\"2020-05-18T08:57:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/264c93ce9dcf43caa9d634aeafab965c\"},\"description\":\"Bleiben Sie \u00fcber die neuesten Forschungsergebnisse und Entwicklungen im Bereich der Immunologie informiert. Erfahren Sie, wie die Kymos Group Ihnen Wissen und Erfahrung vermitteln kann.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Carles-Morte_Immunology_Short-e1658232189298.png\",\"contentUrl\":\"https:\\\/\\\/kymos.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Carles-Morte_Immunology_Short-e1658232189298.png\",\"width\":800,\"height\":444,\"caption\":\"immunology carles morte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kymos.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immunologie: Gemeinsam f\u00fcr die n\u00e4chste Pandemie ger\u00fcstet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/\",\"name\":\"Kymos Group\",\"description\":\"Kymos Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kymos.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#\\\/schema\\\/person\\\/264c93ce9dcf43caa9d634aeafab965c\",\"name\":\"Joan Puig de Dou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g\",\"caption\":\"Joan Puig de Dou\"},\"description\":\"Active in the pharmaceutical marketing for over 30 years President of CataloniaBIO&amp;HealthTech CEO and Qualified Person at Kymos Leader of Kymos team, guaranteeing a trustable, ethical and scientific correct editorial publications. Experience Joan Puig de Dou started his career at Laboratorios Menarini first as scientist later as Qualified Person and finally as Operations General Manager. 2010 he entered Kymos where he became CEO in 2015. 2022 Joan Puig de Dou was elected as president of CataloniaBio&amp;HealthTech to represent the Catalonian biotech industry nationally and internationally. Expertise Joan Puig de Dou has extensive experience in writing scientific content adopting a didactic approach that fits any reader\u2019s level of expertise. He publishes regularely on Kymos\u2019 webpage, social media and in the specialized press. Education He graduated from Universitat de Barcelona as Pharmacist and from IESE Business School\u2019s Programa Diecci\u00f3n General (PDG) Want to know him better? Read his interview in PharmaBoardrooom in January 2019 and more about his presidency of CataloniaBio at Parc Sc\u00edentific de Barcelona.\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/news\\\/author\\\/joan-puig-de-dou\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immunologie: Vorbereitung auf die n\u00e4chste Pandemie | Kymos-Gruppe","description":"Bleiben Sie \u00fcber die neuesten Forschungsergebnisse und Entwicklungen im Bereich der Immunologie informiert. Erfahren Sie, wie die Kymos Group Ihnen Wissen und Erfahrung vermitteln kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/","og_locale":"de_DE","og_type":"article","og_title":"Immunologie: Vorbereitung auf die n\u00e4chste Pandemie | Kymos-Gruppe","og_description":"Bleiben Sie \u00fcber die neuesten Forschungsergebnisse und Entwicklungen im Bereich der Immunologie informiert. Erfahren Sie, wie die Kymos Group Ihnen Wissen und Erfahrung vermitteln kann.","og_url":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/","og_site_name":"Kymos","article_published_time":"2020-05-18T08:57:45+00:00","og_image":[{"width":800,"height":444,"url":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","type":"image\/png"}],"author":"Joan Puig de Dou","twitter_card":"summary_large_image","twitter_creator":"@KymosGroup","twitter_site":"@KymosGroup","twitter_misc":{"Verfasst von":"Joan Puig de Dou","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/#article","isPartOf":{"@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/"},"author":{"name":"Joan Puig de Dou","@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/264c93ce9dcf43caa9d634aeafab965c"},"headline":"Immunologie: Gemeinsam f\u00fcr die n\u00e4chste Pandemie ger\u00fcstet","datePublished":"2020-05-18T08:57:45+00:00","mainEntityOfPage":{"@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/"},"wordCount":599,"image":{"@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","articleSection":["Bioanalyse"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/","url":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/","name":"Immunologie: Vorbereitung auf die n\u00e4chste Pandemie | Kymos-Gruppe","isPartOf":{"@id":"https:\/\/kymos.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/#primaryimage"},"image":{"@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/#primaryimage"},"thumbnailUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","datePublished":"2020-05-18T08:57:45+00:00","author":{"@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/264c93ce9dcf43caa9d634aeafab965c"},"description":"Bleiben Sie \u00fcber die neuesten Forschungsergebnisse und Entwicklungen im Bereich der Immunologie informiert. Erfahren Sie, wie die Kymos Group Ihnen Wissen und Erfahrung vermitteln kann.","breadcrumb":{"@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/#primaryimage","url":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","contentUrl":"https:\/\/kymos.com\/wp-content\/uploads\/2021\/11\/Carles-Morte_Immunology_Short-e1658232189298.png","width":800,"height":444,"caption":"immunology carles morte"},{"@type":"BreadcrumbList","@id":"https:\/\/kymos.com\/de\/news\/immunologie-gemeinsam-fuer-die-naechste-pandemie-geruestet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kymos.com\/de\/"},{"@type":"ListItem","position":2,"name":"Immunologie: Gemeinsam f\u00fcr die n\u00e4chste Pandemie ger\u00fcstet"}]},{"@type":"WebSite","@id":"https:\/\/kymos.com\/de\/#website","url":"https:\/\/kymos.com\/de\/","name":"Kymos Group","description":"Kymos Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kymos.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/kymos.com\/de\/#\/schema\/person\/264c93ce9dcf43caa9d634aeafab965c","name":"Joan Puig de Dou","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/263d7ff1c7891f5821a5075a1a362a1e513db5931dc882455e887fe1c1ccf924?s=96&d=mm&r=g","caption":"Joan Puig de Dou"},"description":"Active in the pharmaceutical marketing for over 30 years President of CataloniaBIO&amp;HealthTech CEO and Qualified Person at Kymos Leader of Kymos team, guaranteeing a trustable, ethical and scientific correct editorial publications. Experience Joan Puig de Dou started his career at Laboratorios Menarini first as scientist later as Qualified Person and finally as Operations General Manager. 2010 he entered Kymos where he became CEO in 2015. 2022 Joan Puig de Dou was elected as president of CataloniaBio&amp;HealthTech to represent the Catalonian biotech industry nationally and internationally. Expertise Joan Puig de Dou has extensive experience in writing scientific content adopting a didactic approach that fits any reader\u2019s level of expertise. He publishes regularely on Kymos\u2019 webpage, social media and in the specialized press. Education He graduated from Universitat de Barcelona as Pharmacist and from IESE Business School\u2019s Programa Diecci\u00f3n General (PDG) Want to know him better? Read his interview in PharmaBoardrooom in January 2019 and more about his presidency of CataloniaBio at Parc Sc\u00edentific de Barcelona.","url":"https:\/\/kymos.com\/de\/news\/author\/joan-puig-de-dou\/"}]}},"_links":{"self":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts\/27325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/comments?post=27325"}],"version-history":[{"count":0,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/posts\/27325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/media\/27327"}],"wp:attachment":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/media?parent=27325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/categories?post=27325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/tags?post=27325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}