{"id":37368,"date":"2021-08-31T16:52:00","date_gmt":"2021-08-31T14:52:00","guid":{"rendered":"https:\/\/kymos.com\/rechtliches\/"},"modified":"2026-08-04T11:22:38","modified_gmt":"2026-08-04T09:22:38","slug":"rechtliches","status":"publish","type":"page","link":"https:\/\/kymos.com\/de\/rechtliches\/","title":{"rendered":"Rechtliches"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container fusion-parallax-none hundred-percent-fullwidth non-hundred-percent-height-scrolling lazyload\" style=\"--awb-background-blend-mode:multiply;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:var(--awb-custom_color_4);--awb-background-size:cover;--awb-flex-wrap:wrap;\" data-bg=\"https:\/\/kymos.com\/wp-content\/uploads\/2021\/09\/KYMOS-FACILITIES_GMP_GLP-Archive_20210623-BCN-0484-e1658319056929.jpg\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"width:calc( 100% + 20px ) !important;max-width:calc( 100% + 20px ) !important;margin-left: calc(-20px \/ 2 );margin-right: calc(-20px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:10px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:10px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:10px;--awb-spacing-left-medium:10px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:10px;--awb-spacing-left-small:10px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:var(--awb-color1);\"><h1 class=\"fusion-title-heading title-heading-center\" style=\"margin:0;\">Rechtliches<\/h1><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-bottom:100px;--awb-margin-bottom:100px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1170px + 20px );margin-left: calc(-20px \/ 2 );margin-right: calc(-20px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:10px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:10px;--awb-width-medium:100%;--awb-spacing-right-medium:10px;--awb-spacing-left-medium:10px;--awb-width-small:100%;--awb-spacing-right-small:10px;--awb-spacing-left-small:10px;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color5);--awb-title-color:#82988c;--awb-content-color:#555555;--awb-icon-box-color:var(--awb-color1);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-toggle-active-accent-color:var(--awb-color8);--awb-title-font-family:var(--awb-typography2-font-family);--awb-title-font-weight:var(--awb-typography2-font-weight);--awb-title-font-style:var(--awb-typography2-font-style);--awb-title-font-size:16px;--awb-title-letter-spacing:var(--awb-typography2-letter-spacing);--awb-title-line-height:var(--awb-typography2-line-height);--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-37368-1\"><div class=\"fusion-panel panel-default panel-777b541bbe852021f fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_777b541bbe852021f\"><a aria-expanded=\"false\" aria-controls=\"777b541bbe852021f\" role=\"button\" data-toggle=\"collapse\" data-target=\"#777b541bbe852021f\" href=\"#777b541bbe852021f\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Unternehmensinformationen<\/span><\/a><\/h4><\/div><div id=\"777b541bbe852021f\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_777b541bbe852021f\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>In \u00dcbereinstimmung mit dem spanischen Gesetz 34\/2002 \u00fcber Dienste der Informationsgesellschaft und des elektronischen Handels sowie mit allen anderen Vorschriften f\u00fcr juristische Personen informieren wir hiermit, dass:<\/p>\n<ul>\n<li>KYMOS GROUP, S.L. mit USt-IdNr. B70843693 wurde am 6. <sup>M\u00e4rz<\/sup> 2024 mittels \u00f6ffentlicher Urkunde, ausgestellt vom Notar Javier Garc\u00eda Ru\u00edz unter der Protokollnummer 708, gegr\u00fcndet und am 16. <sup>April<\/sup> 2024 im Handelsregister von Barcelona, Spanien, unter Band 49237, Seite 203, Blatt B-612804, Eintrag 1, eingetragen. Der eingetragene Firmensitz des Unternehmens ist Ronda Can Fatj\u00f3 5, Geb\u00e4ude D, 08290 Cerdanyola del Vall\u00e8s, Barcelona, Spanien. Sollten Sie uns kontaktieren m\u00fcssen, k\u00f6nnen Sie entweder eine schriftliche Mitteilung an unsere eingetragene Adresse senden, die Telefonnummer +34 935 481 848 anrufen, ein Fax an +34 931 702 999 senden oder eine E-Mail an <a href=\"mailto:legal@kymos.com?subject=Corporate%20Information\" data-wpel-link=\"internal\">legal@kymos.com<\/a><strong><strong>.<\/strong><\/strong> <\/li>\n<li>KYMOS, S.L.U. ist eine hundertprozentige Tochtergesellschaft der KYMOS GROUP, S.L. mit USt-IdNr. ESB62170337 und wurde am 27. <sup>Januar<\/sup> 2000 mittels \u00f6ffentlicher Urkunde, ausgestellt vom Notar Xavier Roca Ferrer unter der Protokollnummer 260, gegr\u00fcndet und am 16. <sup>Februar<\/sup> 2000 im Handelsregister von Barcelona, Spanien, unter Band 32286, Seite 58, Blatt B-205499, Eintrag 1, eingetragen. Der eingetragene Firmensitz des Unternehmens ist Ronda Can Fatj\u00f3 5, Geb\u00e4ude D, 08290 Cerdanyola del Vall\u00e8s, Barcelona, Spanien. Sollten Sie uns kontaktieren m\u00fcssen, k\u00f6nnen Sie entweder eine schriftliche Mitteilung an unsere eingetragene Adresse senden, die Telefonnummer +34 935 481 848 anrufen, ein Fax an +34 931 702 999 senden oder eine E-Mail an <a href=\"mailto:legal@kymos.com?subject=Corporate%20Information\" data-wpel-link=\"internal\">legal@kymos.com<\/a><strong><strong>.<\/strong><\/strong> <\/li>\n<li>PHARMAPROGRESS Srl ist eine hundertprozentige Tochtergesellschaft der KYMOS GROUP, S.L., eingetragen im Handelsregister von Ancona, Italien, am 11. <sup>Mai<\/sup> 1999, unter der Nummer REA AN-151873 und USt-IdNr. IT01564160420. Der eingetragene Firmensitz des Unternehmens ist Via Emilia Romagna 28-30-32, 60030 Monsano, Ancona, Italien. Sollten Sie uns kontaktieren m\u00fcssen, k\u00f6nnen Sie entweder eine schriftliche Mitteilung an unsere eingetragene Adresse senden, die Telefonnummer +39 071 7499919 anrufen oder eine E-Mail an <a href=\"mailto:info@pharmaprogress.com\" data-wpel-link=\"internal\">info@pharmaprogress.com<\/a> oder an die registrierte PEC <a href=\"mailto:laboratoriochimico@pec.pharmaprogress.com\" data-wpel-link=\"internal\">laboratoriochimico@pec.pharmaprogress.com<\/a> senden.<\/li>\n<li>PROLYTIC GmbH ist eine hundertprozentige Tochtergesellschaft der KYMOS GROUP, S.L., eingetragen im Handelsregister Frankfurt\/Main, Deutschland, unter der Nummer 56529 und USt-IdNr. DE 226546121. Der eingetragene Firmensitz des Unternehmens ist Weism\u00fcllerstra\u00dfe 45, 60314 Frankfurt\/Main, Deutschland. Sollten Sie uns kontaktieren m\u00fcssen, k\u00f6nnen Sie entweder eine schriftliche Mitteilung an unsere eingetragene Adresse senden, die Telefonnummer +49 69 348723410 anrufen oder eine E-Mail an <a href=\"mailto:info@prolytic.de\" data-wpel-link=\"internal\">info@prolytic.de<\/a> senden. Gesch\u00e4ftsf\u00fchrer: Joan Puig de Dou. <\/li>\n<li>PARTICLE ANALYTICAL ApS ist eine hundertprozentige Tochtergesellschaft der KYMOS GROUP, S.L., registriert im d\u00e4nischen Zentralen Unternehmensregister unter der Registrierungsnummer (CVR) 25194934. Der eingetragene Firmensitz des Unternehmens ist Agern Alle 3, DK-2970 H\u00f8rsholm, D\u00e4nemark. Sollten Sie uns kontaktieren m\u00fcssen, k\u00f6nnen Sie eine schriftliche Korrespondenz an unsere eingetragene Adresse senden, uns unter +45 45 76 30 60 anrufen oder eine E-Mail an <a href=\"mailto:info@particle.dk\" data-wpel-link=\"internal\">info@particle.dk<\/a> senden.<\/li>\n<li>KYMOS Yuhan Hoesa ist ein Unternehmen, das am 11. Dezember 2025 gegr\u00fcndet und unter der Nummer 839-88-03795 registriert wurde. Der eingetragene Firmensitz des Unternehmens ist 37F ASEM Tower, 517 Yeongdong-Daero, Gangnam-gu, 06164 Seoul, Korea. Sollten Sie uns kontaktieren m\u00fcssen, k\u00f6nnen Sie eine schriftliche Korrespondenz an unsere eingetragene Adresse senden, uns unter +82 02 6001 3883 anrufen oder eine E-Mail an <a href=\"mailto:legal@kymos.com\" data-wpel-link=\"internal\">legal@kymos.com<\/a> senden.  <\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-14ca57abd65766cec fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_14ca57abd65766cec\"><a aria-expanded=\"false\" aria-controls=\"14ca57abd65766cec\" role=\"button\" data-toggle=\"collapse\" data-target=\"#14ca57abd65766cec\" href=\"#14ca57abd65766cec\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Ethikkodex<\/span><\/a><\/h4><\/div><div id=\"14ca57abd65766cec\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_14ca57abd65766cec\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><strong>I.- SCHREIBEN DES VORSITZENDEN DES VERWALTUNGSRATS <\/strong><\/p>\n<p>Seit der Gr\u00fcndung von KYMOS, S.L. (\u201eKYMOS GROUP\u201c oder \u201edas Unternehmen\u201c) im Jahr 2001 durch eine Gruppe von Wissenschaftlern mit umfassender Erfahrung in den Bereichen Forschung, Entwicklung und Qualit\u00e4tskontrolle der pharmazeutischen Industrie, begann ein spannender Weg, der bis heute andauert und t\u00e4glich mit neuen Mitarbeitern w\u00e4chst, die denselben Innovations- und Verbesserungsgeist wie die Gr\u00fcnder besitzen und deren Werte und ethische Prinzipien darin bestehen, integer zu handeln und Menschen, die Umwelt und die geltende Gesetzgebung zu respektieren.<\/p>\n<p>Die legislativen und sozialen Ver\u00e4nderungen, die in den letzten Jahren in unserem Umfeld aufgetreten sind, haben uns dazu veranlasst, die Implementierung dieses Verhaltenskodex in unserem Unternehmen zu f\u00f6rdern, der zum h\u00f6chsten regulatorischen Instrument in der Regulierungsstruktur des Unternehmens geworden ist. Dieser Verhaltenskodex enth\u00e4lt die ethischen Prinzipien, die das Unternehmen in allen Bereichen seiner T\u00e4tigkeit anwendet, und stellt unser Engagement dar, die Gesetze und die in diesen Gesetzen verteidigten ethischen Werte einzuhalten. Dieser Kodex soll ein Schl\u00fcsselwerkzeug sein, damit wir weiterhin verantwortungsbewusst, integer, gesetzes- und menschenrechtskonform, transparent und aufmerksam gegen\u00fcber jeder unlauteren Praxis bleiben.  <\/p>\n<p>Teil der KYMOS GROUP zu sein, bedeutet, sich voll und ganz den Werten dieses Verhaltenskodex zu verpflichten, der klare Prinzipien festlegt, die das Handeln unserer Mitarbeiter leiten sollen.<\/p>\n<p>Die Aktion\u00e4re, Direktoren und Mitarbeiter der KYMOS GROUP sowie ihrer Tochtergesellschaften m\u00fcssen sich an diesen Verhaltenskodex halten und freiwillig die Verpflichtung eingehen, alle ihre Aktivit\u00e4ten dem Geist seiner Bestimmungen anzupassen.<\/p>\n<p>Dar\u00fcber hinaus werden Kunden, Mitarbeiter und Lieferanten des Unternehmens gebeten, sich zur Einhaltung der ethischen Prinzipien dieses Kodex zu verpflichten, falls sie keinen eigenen Verhaltenskodex mit gleichwertigen Bestimmungen besitzen.<\/p>\n<p>Das Unternehmen hat Ma\u00dfnahmen ergriffen, um die strikte Einhaltung dieses Verhaltenskodex zu gew\u00e4hrleisten, und wir werden stets aufmerksam sein gegen\u00fcber jeder Praxis, die ein Engagement f\u00fcr ethisches Handeln gef\u00e4hrden k\u00f6nnte. Ebenso bitten wir unsere Mitarbeiter, dass dieselbe Sorgfalt, dieselben Werte und dasselbe Engagement ihr t\u00e4gliches Handeln leiten. <\/p>\n<p>In meinem Namen und im Namen des Verwaltungsrats des Unternehmens m\u00f6chte ich mich im Voraus f\u00fcr das Engagement aller Mitarbeiter von KYMOS bei der Einhaltung dieses Verhaltenskodex bedanken.<\/p>\n<p>Mit freundlichen Gr\u00fc\u00dfen,<\/p>\n<p>Joan Puig Corcoy<\/p>\n<p>Vorsitzender des Verwaltungsrats<strong> <\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>II.- ZIELE UND ANWENDUNGSBEREICH: <\/strong><strong> <\/strong><\/p>\n<p>Ziel dieses Verhaltenskodex ist es, die Einhaltung der Gesetze und der Werte des Unternehmens zu gew\u00e4hrleisten und die Begehung von Straftaten zum Nutzen des Unternehmens und der Gesellschaft insgesamt zu vermeiden und abzulehnen.<\/p>\n<p>Sein Inhalt ist nicht nur deklaratorisch, sondern f\u00fcr seine Aktion\u00e4re, sein Leitungsorgan, seine Gesch\u00e4ftsf\u00fchrung und alle Personen, die Teil der KYMOS GROUP sowie ihrer Tochtergesellschaften sind, bindend und beabsichtigt nicht, die geltenden gesetzlichen Bestimmungen zu ersetzen oder zu substituieren.<\/p>\n<p>Die Aktion\u00e4re und Direktoren der KYMOS GROUP sind Garanten f\u00fcr die Einhaltung der Verpflichtungen dieses Verhaltenskodex. Dar\u00fcber hinaus sind die Verantwortlichen jedes Gesch\u00e4ftsbereichs des Unternehmens daf\u00fcr verantwortlich, die Einhaltung und Anwendung desselben in ihren jeweiligen Verantwortungsbereichen sicherzustellen. <\/p>\n<p>Beim Beginn ihres Arbeitsverh\u00e4ltnisses mit der KYMOS GROUP oder einer ihrer Tochtergesellschaften erhalten alle Personen eine Kopie des Verhaltenskodex, den sie lesen m\u00fcssen, um den Inhalt seiner Regeln zu akzeptieren.<\/p>\n<p>Der Verhaltenskodex wird auch auf der Website des Unternehmens ver\u00f6ffentlicht.<\/p>\n<p>Von allen Personen, die die KYMOS GROUP bilden, wird ein Verhalten erwartet, das mit den Prinzipien und Werten des Verhaltenskodex \u00fcbereinstimmt. Sollte eine Person Kenntnis davon haben, dass die Prinzipien des Kodex oder die geltende Gesetzgebung verletzt werden, kann sie dies \u00fcber das interne Informationssystem melden, das das Unternehmen zur Verf\u00fcgung stellt. <\/p>\n<p><strong>III.- AKTION\u00c4RE:<\/strong><\/p>\n<p>(i) \u00dcben Sie ihre Stimmrechte in den Hauptversammlungen informiert und verantwortungsbewusst aus und fordern Sie dabei stets die ethische Leistung des Unternehmens, um die wirksame Anwendung des Verhaltenskodex zu gew\u00e4hrleisten.<\/p>\n<p>(ii) Ernennen Sie als Direktoren Personen, die die Bedingungen einer angemessenen Vorbereitung und Erfahrung erf\u00fcllen und die eine professionelle, ethische und verantwortungsbewusste Aus\u00fcbung ihrer Gesch\u00e4ftsf\u00fchrung gew\u00e4hrleisten.<\/p>\n<p><strong>IV.- DIREKTOREN UND MANAGER:<\/strong><\/p>\n<p>Bei der Aus\u00fcbung ihrer Verwaltungs-, Leitungs- und F\u00fchrungsaufgaben m\u00fcssen sie:<\/p>\n<p>(i) Eine professionelle, ethische und verantwortungsbewusste Aus\u00fcbung ihrer T\u00e4tigkeit gem\u00e4\u00df den Werten guter Unternehmensf\u00fchrung und Transparenz gew\u00e4hrleisten.<\/p>\n<p>(ii) Den Verhaltenskodex einhalten und durchsetzen und zu diesem Zweck bekannt machen, verbreiten und geeignete Mechanismen zur Gew\u00e4hrleistung seiner Anwendung schaffen.<\/p>\n<p>(iii) Die Aktion\u00e4re genau und p\u00fcnktlich \u00fcber die Situation und die Perspektiven des Unternehmens informieren.<\/p>\n<p>(iv) Die effektive Beteiligung der Aktion\u00e4re an der Hauptversammlung f\u00f6rdern, insbesondere durch Erleichterung der Aus\u00fcbung ihrer Informations- und Stimmrechte.<\/p>\n<p>(v) Die allgemein anerkannten Rechnungslegungsstandards und -prinzipien einhalten und durchsetzen sowie interne und externe Kontroll- und Risikomanagementsysteme einrichten, die den Merkmalen des Unternehmens entsprechen.<\/p>\n<p>(vi) Die B\u00fccher und Aufzeichnungen des Unternehmens genau und ehrlich f\u00fchren, um Informationen zu erhalten und bewusste und verantwortungsvolle Entscheidungen treffen zu k\u00f6nnen.<\/p>\n<p>(vii) Den Wirtschaftspr\u00fcfern des Unternehmens alle Informationen und Erkl\u00e4rungen zur Verf\u00fcgung stellen, die sie zur Durchf\u00fchrung ihrer Arbeit ben\u00f6tigen.<\/p>\n<p><strong>V.- ACHTUNG DER GELTENDEN GESETZLICHKEIT UND DER SEKTORALEN VORSCHRIFTEN<\/strong><\/p>\n<ul>\n<li>KYMOS akzeptiert keine Handlungen, die nicht streng gesetzeskonform sind, unabh\u00e4ngig vom verfolgten Zweck. Tochtergesellschaften und Mitarbeiter von KYMOS m\u00fcssen stets im Rahmen der Legalit\u00e4t handeln und die geltenden Vorschriften strikt und ausnahmslos respektieren. <\/li>\n<li>Das Unternehmen wird die h\u00f6chsten Sicherheits- und Wirksamkeitsstandards einhalten und die Qualit\u00e4t und Sicherheit seiner Gesch\u00e4ftst\u00e4tigkeit stets gem\u00e4\u00df den Standards der Guten Herstellungspraxis (\u201eGMP\u201c), der Guten Klinischen Praxis (\u201eGCP\u201c) und der Guten Laborpraxis (\u201eGLP\u201c) gew\u00e4hrleisten, sofern anwendbar.<\/li>\n<\/ul>\n<p><strong>VI.- ALLGEMEINE MENSCHENRECHTE<\/strong><\/p>\n<ul>\n<li>Verpflichtung zur Allgemeinen Erkl\u00e4rung der Menschenrechte:<\/li>\n<\/ul>\n<p>Alle Mitarbeiter, Direktoren und Manager m\u00fcssen die in der von der Generalversammlung der Vereinten Nationen verabschiedeten Allgemeinen Erkl\u00e4rung der Menschenrechte festgelegten Prinzipien respektieren.<\/p>\n<p><strong>VII.- ARBEITSRECHTE. GLEICHSTELLUNGSPOLITIK. NICHTDISKRIMINIERUNG<\/strong>. <strong>RICHTLINIE ZUR VERHINDERUNG SEXUELLER BEL\u00c4STIGUNG.<\/strong><\/p>\n<ul>\n<li>Das Unternehmen unterst\u00fctzt die Prinzipien der Internationalen Arbeitsorganisation und verteidigt den Schutz der Arbeitnehmerrechte und die Achtung der Menschenw\u00fcrde. Jeder hat das Recht, seine Arbeit freiwillig und ohne Zwang auszu\u00fcben. Die KYMOS GROUP lehnt Zwangsarbeit oder N\u00f6tigung, jede Form von Sklaverei oder Kinderarbeit vollst\u00e4ndig ab und schlie\u00dft keine Vertr\u00e4ge mit Unternehmen ab, die diese Verpflichtungen nicht erf\u00fcllen.  <\/li>\n<li>Alle Mitglieder verpflichten sich, allen Personen, sowohl intern als auch extern, eine w\u00fcrdevolle Behandlung zukommen zu lassen und fordern von ihren Kunden und Lieferanten, dass deren Handlungen von denselben hier aufgef\u00fchrten Prinzipien und Werten geleitet werden.<\/li>\n<li>Die KYMOS GROUP respektiert die individuellen Rechte des Einzelnen und setzt sich f\u00fcr ein positives und inklusives Arbeitsumfeld ein, das frei von jeglicher Art von Einsch\u00fcchterung und Bel\u00e4stigung ist, und verpflichtet sich, Chancengleichheit in allen Bereichen zu f\u00f6rdern.<\/li>\n<li>Der Missbrauch von Autorit\u00e4t zur Aus\u00fcbung unangemessenen Drucks, Drohungen oder Kontrolle \u00fcber einen Kollegen oder Mitarbeiter ist verboten. Im Umgang mit Kollegen sollten Mitarbeiter aufgeschlossen, ehrlich und h\u00f6flich zueinander sein und mit Respekt behandelt werden. <\/li>\n<li>Es wird keine Diskriminierung einer Person aufgrund ihres Alters, ihrer Ideologie, ihrer nationalen oder sozialen Herkunft, ihrer wirtschaftlichen Lage, ihrer Religion oder \u00dcberzeugung, ihrer Zugeh\u00f6rigkeit zu einer ethnischen Gruppe, Rasse oder Nation, ihrer Sprache, ihres Geschlechts, ihrer sexuellen Orientierung, ihrer famili\u00e4ren Situation, Krankheit oder Behinderung zugelassen.<\/li>\n<li> Die Vereinigungsfreiheit und das Streikrecht werden respektiert und es wird sichergestellt, dass keine Bel\u00e4stigung am Arbeitsplatz stattfindet.<\/li>\n<li>Jede feindselige oder dem\u00fctigende Handlung gegen\u00fcber einer Person ist zu vermeiden.<\/li>\n<li>Die KYMOS GROUP verpflichtet sich, allen Mitarbeitern ein sicheres Umfeld zu bieten, frei von Diskriminierung jeglicher Art und frei von Bel\u00e4stigung am Arbeitsplatz, einschlie\u00dflich sexueller Bel\u00e4stigung. Die KYMOS GROUP wird eine Null-Toleranz-Politik f\u00fcr jede Form sexueller Bel\u00e4stigung am Arbeitsplatz anwenden, alle Vorf\u00e4lle ernst nehmen und alle Anschuldigungen sexueller Bel\u00e4stigung unverz\u00fcglich untersuchen. Zu diesem Zweck hat das Unternehmen eine Richtlinie zur Verhinderung sexueller Bel\u00e4stigung, die den Mitarbeitern zur Verf\u00fcgung gestellt wird.  <\/li>\n<li>Sollte ein Mitarbeiter Kenntnis von einem Verhalten oder einer Handlung erhalten, die die oben genannten Prinzipien oder vergleichbare Prinzipien nicht respektiert, wird er dies unverz\u00fcglich mitteilen, damit das Unternehmen handeln und diese inakzeptablen Verhaltensweisen beseitigen kann.<\/li>\n<\/ul>\n<p><strong>VIII.- HYGIENE UND SICHERHEIT AM ARBEITSPLATZ:<\/strong><\/p>\n<ul>\n<li>Arbeitssicherheit hat f\u00fcr die KYMOS GROUP oberste Priorit\u00e4t, die die geltenden Vorschriften zur Pr\u00e4vention von Arbeitsrisiken jederzeit respektiert und einh\u00e4lt.<\/li>\n<li> Die Mitarbeiter werden gebeten, die Schutz- und Sicherheitsvorschriften einzuhalten, ihre eigene Sicherheit zu gew\u00e4hrleisten und die Verwendung von Pr\u00e4ventionsmitteln von ihren Untergebenen zu verlangen.<\/li>\n<li> Eines der Hauptziele des Unternehmens ist es, die Hygiene, Sicherheit und Gesundheit seiner Mitarbeiter, insbesondere in seinen Industrieanlagen, zu gew\u00e4hrleisten.<\/li>\n<\/ul>\n<p><strong>IX.- INTERESSENKONFLIKTE. <\/strong><\/p>\n<p>Ein Interessenkonflikt liegt vor, wenn die privaten Interessen von Mitarbeitern, Direktoren oder Managern nicht mit denen des Unternehmens \u00fcbereinstimmen, ihre Pflichten beeintr\u00e4chtigen oder sie dazu veranlassen, aus anderen Gr\u00fcnden als der Erf\u00fcllung der dem Unternehmen zugewiesenen Verantwortlichkeiten zu handeln. Bei jeder Entscheidung sind Mitarbeiter, Manager oder Direktoren verpflichtet, zum Wohle des Unternehmens zu handeln und nicht aufgrund partikularer Interessen, und sich jeder Operation oder Entscheidung zu enthalten, wenn sie sich in einer Interessenkonfliktsituation befinden. <\/p>\n<ol>\n<li><strong> NUTZUNG DER UNTERNEHMENSEIGENEN VERM\u00d6GENSWERTE <\/strong><\/li>\n<\/ol>\n<p>Das Unternehmen stellt seinen Mitarbeitern die notwendigen Verm\u00f6genswerte zur Verf\u00fcgung, um ihre Aufgaben ordnungsgem\u00e4\u00df zu erf\u00fcllen, aber Mitarbeiter sollten diese Verm\u00f6genswerte niemals unangemessen oder unrechtm\u00e4\u00dfig verwenden, um einen Vorteil f\u00fcr sich selbst oder das Unternehmen zu erzielen.<\/p>\n<p>Ebenso d\u00fcrfen Computer und Computersysteme ausschlie\u00dflich f\u00fcr die Entwicklung der Arbeitst\u00e4tigkeit verwendet werden, es sei denn, dies wurde vom Unternehmen ausdr\u00fccklich genehmigt.<\/p>\n<p><strong>XI.- UMWELTSCHUTZ UND NACHHALTIGE ENTWICKLUNG<\/strong><\/p>\n<p>F\u00fcr die KYMOS GROUP sind soziale Verantwortung, Gesundheit und Sicherheit sowie Umweltschutz oberste Priorit\u00e4ten. Der Umweltschutz und die nachhaltige Entwicklung sind Teil des Engagements der KYMOS GROUP, und das Unternehmen verpflichtet sich, seine Gesch\u00e4ftst\u00e4tigkeit unter Achtung und Schutz seiner Umwelt und nachhaltigem Wachstum auszurichten. <\/p>\n<p><strong>XII.- ST\u00c4DTEBAULICHE ORDNUNG:<\/strong><\/p>\n<p>Das Unternehmen wird seine Stadtplanungspolitik auf der Grundlage der Achtung des Gesetzes und der st\u00e4dtebaulichen Ordnung aufbauen.<\/p>\n<p><strong>XIII.- KUNDEN, LIEFERANTEN UND WETTBEWERBER:<\/strong><\/p>\n<p>(i) Alle Kunden werden unabh\u00e4ngig von der Gr\u00f6\u00dfe ihres Gesch\u00e4fts auf die gleiche ethische und professionelle Weise behandelt.<\/p>\n<p>(ii) Die KYMOS GROUP w\u00e4hlt ihre Lieferanten nach objektiven Kriterien hinsichtlich der Qualit\u00e4t ihres Produkts oder ihrer Dienstleistung, des Preises, des Rufs sowie ihrer Umwelt- und Sozialleistung aus. Alle Mitarbeiter des Unternehmens werden sich bem\u00fchen, herzliche und professionelle Beziehungen zu Lieferanten zu pflegen. <\/p>\n<p>(iii) Die KYMOS GROUP st\u00fctzt ihr Handeln auf dem Markt auf die Prinzipien des freien Wettbewerbs und der Chancengleichheit, f\u00f6rdert die vertragliche Treu und Glauben und schlie\u00dft unrechtm\u00e4\u00dfige Vereinbarungen oder Handlungen aus, die darauf abzielen, einen Vorteil, einen unlauteren oder unrechtm\u00e4\u00dfigen Vorteil gegen\u00fcber Kunden, Lieferanten, Wettbewerbern und anderen Marktteilnehmern zu erzielen.<\/p>\n<p>(iv) Im Verh\u00e4ltnis zu Wettbewerbern werden alle Vereinbarungen, die den freien Wettbewerb einschr\u00e4nken k\u00f6nnten, und Gesch\u00e4ftspraktiken, die den geltenden Rechtsrahmen nicht respektieren, abgelehnt.<\/p>\n<p>(v) Wettbewerber werden nicht herabgew\u00fcrdigt oder in irref\u00fchrender oder unfairer Weise beschrieben, noch werden ihre Produkte oder ihr Image diskreditiert.<\/p>\n<p><strong>XIV.- POLITISCHE AKTIVIT\u00c4TEN<\/strong><\/p>\n<p>Die Politik des Unternehmens ist es, keine Beitr\u00e4ge an politische Parteien zu leisten.<\/p>\n<p><strong>XV.- VERTRAULICHE INFORMATIONEN: <\/strong><\/p>\n<ul>\n<li>Die Offenlegung vertraulicher Informationen, Gesch\u00e4ftsgeheimnisse oder Know-how des Unternehmens oder seiner Lieferanten oder Kunden an Dritte, sei es absichtlich oder versehentlich, kann die Wettbewerbsf\u00e4higkeit der KYMOS GROUP oder ihrer Kunden und Lieferanten ernsthaft beeintr\u00e4chtigen und gegen die mit ihnen geschlossenen Vertraulichkeitsvereinbarungen versto\u00dfen. <\/li>\n<li>Es ist unerl\u00e4sslich, dass alle Mitarbeiter der KYMOS GROUP die unterzeichneten Vertraulichkeitsvereinbarungen respektieren und jede Situation, in der beabsichtigt ist, Informationen au\u00dferhalb des Unternehmens oder seiner Lieferanten oder Kunden zu verbreiten, sorgf\u00e4ltig pr\u00fcfen. Die Mitarbeiter werden die Regeln zur Aufbewahrung und Vernichtung von Dokumenten sowie die Regeln zur Computersicherheit respektieren. <\/li>\n<li>Niemals d\u00fcrfen sensible Informationen an Dritte weitergegeben werden, insbesondere solche, die Kunden betreffen, ohne R\u00fccksprache mit der Gesch\u00e4ftsleitung. Andererseits muss die Gesch\u00e4ftsleitung \u00fcber jeden Vertraulichkeitsbruch informiert werden. <\/li>\n<li>Jeder Mitarbeiter oder Kollaborateur des Unternehmens muss die Gesch\u00e4ftsleitung im Voraus informieren, wenn er beabsichtigt, Informationen oder Daten des Unternehmens durch die Ver\u00f6ffentlichung eines Artikels, durch die Absolvierung eines Lehrkurses oder auf andere Weise zu verbreiten oder offenzulegen.<\/li>\n<li>Fotos aus dem Inneren des Unternehmens d\u00fcrfen ohne ausdr\u00fcckliche Genehmigung der Gesch\u00e4ftsleitung nicht gemacht und\/oder verbreitet werden.<\/li>\n<\/ul>\n<p><strong>XVI.- KORRUPTIONSVERH\u00dcTUNG:<\/strong><\/p>\n<p>(i) Die KYMOS GROUP und ihre Direktoren und Mitarbeiter werden niemals ihre pers\u00f6nlichen Beziehungen oder finanziellen Mittel nutzen, um die Entscheidungen eines \u00f6ffentlichen Beamten oder eines privaten Unternehmens zu beeinflussen.<\/p>\n<p>(ii) Die KYMOS GROUP st\u00fctzt ihre Beziehungen zum \u00f6ffentlichen und privaten Sektor, national und international, auf die Prinzipien der Transparenz und Chancengleichheit und schlie\u00dft jede illegale Handlung aus, die darauf abzielt, einen Vorteil gegen\u00fcber Dritten zu erzielen.<\/p>\n<p>(iii) Es ist strengstens verboten, Zahlungen, Gef\u00e4lligkeiten, Geschenke oder Vorrechte, Belohnungen oder Gratifikationen anzubieten oder zu leisten, die die Entscheidungen von unter anderem Beamten der \u00f6ffentlichen Verwaltung, Fachleuten, Lieferanten, Kunden, Stiftungen oder Verb\u00e4nden, seien es juristische Personen oder Einzelpersonen, beeinflussen k\u00f6nnen, um einen Vorteil zu erlangen oder zu erhalten und\/oder einen ungerechtfertigten Vorteil zu sichern.<\/p>\n<p>(iv) Mitarbeiter sind verpflichtet, auf m\u00f6gliche Situationen der Nichteinhaltung in Korruptionsangelegenheiten zu achten, sei es im Unternehmen oder bei Kunden oder Lieferanten, und solche Verst\u00f6\u00dfe \u00fcber das interne Informationssystem zu melden.<\/p>\n<p>(v) Mitarbeiter d\u00fcrfen keine Vorteile von Dritten oder Institutionen fordern oder annehmen.<\/p>\n<p>(vi) Die Annahme von Geschenken durch Mitarbeiter ist nur zul\u00e4ssig, wenn sie einen unbedeutenden wirtschaftlichen Wert haben, einer \u00fcblichen gesch\u00e4ftlichen Aufmerksamkeit entsprechen und keine Vorschriften verletzen. Es sollte kein Geschenk, keine Gef\u00e4lligkeit oder Unterhaltung angeboten oder angenommen werden, wenn dies den Empf\u00e4nger beeinflusst oder zu beeinflussen scheint. Bei einem Angebot eines Geschenks, dessen Wert etwa 50 Euro \u00fcbersteigt, muss eine Genehmigung der Gesch\u00e4ftsleitung eingeholt werden, oder wenn es bereits erhalten wurde, muss dies f\u00fcr die entsprechende Entscheidung mitgeteilt werden.  <\/p>\n<p><strong>XVII.- FINANZOPERATIONEN:<\/strong><\/p>\n<p>(i) Jede im Unternehmen durchgef\u00fchrte Transaktion oder Operation muss mit dem Unternehmenszweck in Verbindung stehen und ordnungsgem\u00e4\u00df genehmigt, dokumentiert und registriert werden, und es muss ein ausgewogenes Verh\u00e4ltnis zwischen dem gezahlten wirtschaftlichen Betrag und der erhaltenen Dienstleistung oder dem gekauften Produkt bestehen.<\/p>\n<p>(ii) Die wirtschaftlich-finanziellen Informationen \u2013 insbesondere die Jahresabschl\u00fcsse \u2013 werden die Realit\u00e4t der wirtschaftlichen, verm\u00f6gensrechtlichen und rechtlichen Situation des Unternehmens getreu widerspiegeln und die Transparenz im Gesch\u00e4ftsleben gew\u00e4hrleisten.<\/p>\n<p>(iii) Mitarbeiter der KYMOS GROUP d\u00fcrfen keine Barzahlungen annehmen.<\/p>\n<p>(iv) Mitarbeiter und F\u00fchrungskr\u00e4fte sind wachsam gegen\u00fcber jedem Verdacht auf Geldw\u00e4sche durch einen Kunden, Lieferanten oder Mitarbeiter des Unternehmens und werden dies im Falle eines Auftretens unverz\u00fcglich \u00fcber das interne Informationssystem mitteilen.<\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>XVIII.- PRIVILEGIERTE INFORMATIONEN:<\/strong><\/p>\n<ul>\n<li>Die Nutzung privilegierter Informationen des Unternehmens oder Dritter f\u00fcr jegliche Art von Gesch\u00e4ft ist strengstens untersagt.<\/li>\n<\/ul>\n<p><strong>XIX.- GEISTIGES EIGENTUM:<\/strong><\/p>\n<p>(i) Das Unternehmen respektiert die geistigen Eigentumsrechte Dritter. Daher ist es nicht gestattet, Materialien oder G\u00fcter zu verwenden, die durch geistige Eigentumsrechte Dritter gesch\u00fctzt sind. Ohne die vorherige schriftliche Genehmigung des Eigent\u00fcmers ist das Kopieren oder die vollst\u00e4ndige oder teilweise Reproduktion von immateriellen Verm\u00f6genswerten Dritter nicht gestattet, ebenso wenig die Umwandlung oder \u00c4nderung, vollst\u00e4ndig oder teilweise, der Import oder die Verbreitung dieser Verm\u00f6genswerte. In allen F\u00e4llen m\u00fcssen die geistigen Eigentumsrechte Dritter respektiert werden.   <\/p>\n<p>(ii) Die Gesch\u00e4ftsgeheimnisse des Unternehmens und die Dritter m\u00fcssen gesch\u00fctzt werden.<\/p>\n<p>(iii) Computerprogramme, f\u00fcr die das Unternehmen keine Nutzungslizenz oder Eigentumsrechte besitzt, d\u00fcrfen nicht auf den Ger\u00e4ten installiert werden.<\/p>\n<p>(iv) Kein Mitarbeiter darf Erfindungen beanspruchen oder die Registrierung von Patenten, Marken oder anderen geistigen Eigentumsrechten beantragen, die direkt oder indirekt aus den vom Unternehmen f\u00fcr sich selbst oder zum Nutzen seiner Kunden durchgef\u00fchrten Aktivit\u00e4ten stammen.<\/p>\n<p><strong>XX.- SICHERHEIT DER INFORMATIONSTECHNOLOGIE:<\/strong><\/p>\n<p>(i) Neue Technologien d\u00fcrfen nicht dazu verwendet werden, Verhaltensweisen auszuf\u00fchren, die der Gesch\u00e4ftsethik widersprechen. Das Unternehmen wird auf allen Ebenen den ordnungsgem\u00e4\u00dfen Einsatz von Informationstechnologie gew\u00e4hrleisten. <\/p>\n<p>(ii) Das Unternehmen verf\u00fcgt \u00fcber einen Standard, der die Nutzung der unternehmenseigenen technologischen Ressourcen durch interne oder externe Benutzer regelt. Er beschreibt die Handlungen, die verboten sind, weil sie ein Risiko f\u00fcr die Sicherheit der Systeme und der Informationswerte der Kunden und Dritter darstellen. <\/p>\n<p>(iii) Die Nutzung der IT-Ressourcen des Unternehmens impliziert die Akzeptanz dieser Standards.<\/p>\n<p>(iv) Jeder erkannte Sicherheitsvorfall muss dem Sicherheitsbeauftragten gemeldet werden.<\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>XXI.- RECHT AUF PRIVATSPH\u00c4RE UND SCHUTZ PERSONENBEZOGENER DATEN:<\/strong><\/p>\n<p>(i) Das Unternehmen und seine Mitarbeiter m\u00fcssen sich stets des grundlegenden Prinzips der korrekten Nutzung und des Schutzes personenbezogener Daten aller Mitglieder des Unternehmens und der Dritten, mit denen sie in Beziehung stehen, bewusst sein und die Privatsph\u00e4re, Vertraulichkeit und Sicherheit personenbezogener Informationen, zu denen sie aufgrund ihrer spezifischen Funktionen Zugang haben k\u00f6nnten, respektieren. Zu diesem Zweck m\u00fcssen sowohl das Unternehmen als auch die Mitarbeiter die jeweils geltenden Vorschriften zum Schutz personenbezogener Daten strikt einhalten. Kein Mitarbeiter oder Manager darf ohne Genehmigung auf Daten aus einer Datei zugreifen.   <\/p>\n<p>(ii) Personenbezogene Daten d\u00fcrfen nur in dem Umfang und so lange erhoben und gespeichert werden, wie dies zur Erf\u00fcllung eines legitimen Zwecks erforderlich ist, und d\u00fcrfen nur f\u00fcr den Zweck verwendet werden, f\u00fcr den sie erhoben wurden. Das Unternehmen wird \u00fcber die entsprechenden Richtlinien, internen Mechanismen und Genehmigungen verf\u00fcgen, die die Einhaltung der geltenden gesetzlichen Bestimmungen zum Schutz personenbezogener Daten gew\u00e4hrleisten. <\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>XXII.- PR\u00c4VENTIONS- UND KONTROLLPOLITIK<\/strong><\/p>\n<p>(i) Die KYMOS GROUP verf\u00fcgt \u00fcber eine Pr\u00e4ventions- und Kontrollpolitik, die darauf abzielt, die Begehung von Straftaten zu verhindern. Diese Politik wird angewendet, um das Auftreten krimineller Handlungen im Unternehmen zu verhindern und sicherzustellen, dass sie real und effektiv umgesetzt wird. <\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>XXIII.- DAS INTERNE INFORMATIONSSYSTEM.<\/strong><\/p>\n<p>(i) Gem\u00e4\u00df dem Gesetz 2\/2023 vom 20. Februar, das den Schutz von Personen regelt, die Verst\u00f6\u00dfe gegen Vorschriften melden, und den Kampf gegen Korruption, hat das Unternehmen ein internes Informationssystem implementiert, um Informationen \u00fcber Folgendes zu kommunizieren:<\/p>\n<p>&#8211; Alle Handlungen oder Unterlassungen, die Verst\u00f6\u00dfe gegen das Recht der Europ\u00e4ischen Union darstellen k\u00f6nnen.<\/p>\n<p>&#8211; Handlungen oder Unterlassungen, die eine schwere oder sehr schwere strafrechtliche oder administrative \u00dcbertretung darstellen k\u00f6nnen. In jedem Fall gelten alle schweren oder sehr schweren strafrechtlichen oder administrativen \u00dcbertretungen, die einen wirtschaftlichen Verlust f\u00fcr die Staatskasse und die Sozialversicherung bedeuten, als eingeschlossen. <\/p>\n<p>(ii) Alle Personen, die die KYMOS GROUP bilden, haben die Pflicht, \u00fcber das interne Informationssystem jede der vorgenannten Handlungen oder Unterlassungen mitzuteilen. Das interne Informationssystem ist \u00fcber die Anwendung \u201eBizneo\u201c und \u00fcber die Kymos-Website: www.kymos.com zug\u00e4nglich. <\/p>\n<p>(iii) Jede zu diesem Zweck erhobene Forderung wird \u00fcber das interne Informationssystem bearbeitet.<\/p>\n<p>Beschwerden k\u00f6nnen auch per Post gesendet werden, wobei auf dem Umschlag der vertrauliche Charakter der Mitteilung anzugeben ist, zu H\u00e4nden der f\u00fcr das interne Informationssystem zust\u00e4ndigen Person an:<\/p>\n<p>KYMOS GROUP SL<\/p>\n<p>Ronda Can Fatj\u00f3 5-D<\/p>\n<p>08290 Cerdanyola del Vall\u00e9s (Barcelona).<\/p>\n<p>(iv) Das interne Informationssystem gew\u00e4hrleistet die Vertraulichkeit der Identit\u00e4t des Informanten und jeder in der Mitteilung genannten dritten Partei sowie der bei der Verwaltung und Bearbeitung derselben durchgef\u00fchrten Ma\u00dfnahmen und den Datenschutz, indem es den Zugriff durch unbefugtes Personal verhindert. Ebenso erm\u00f6glicht es die Einreichung von Mitteilungen schriftlich oder m\u00fcndlich oder beides. <\/p>\n<p>(v) Das interne Informationssystem verf\u00fcgt \u00fcber ein Verfahren zur Verwaltung der erhaltenen Informationen und legt Garantien f\u00fcr den Schutz der Informanten fest.<\/p>\n<p>Meldungen k\u00f6nnen anonym erfolgen, es wird jedoch empfohlen, dass sich die meldende Person identifiziert, mit der vollen Garantie, dass die Vertraulichkeit vollst\u00e4ndig gew\u00e4hrleistet ist.<\/p>\n<p>Alle Mitteilungen werden streng vertraulich behandelt und entsprechen den Datenschutzbestimmungen.<\/p>\n<p>(vi) Andererseits m\u00fcssen alle externen Mitteilungen, die ein Mitarbeiter, Lieferant, Kunde oder Dritter, der mit der Kymos Group in Verbindung steht, in Bezug auf Handlungen oder Unterlassungen, die Verst\u00f6\u00dfe darstellen k\u00f6nnen, machen m\u00f6chte, \u00fcber die zu diesem Zweck eingerichtete E-Mail-Adresse erfolgen, die wie folgt lautet: <a href=\"mailto:ethicalcode@kymos.com\" data-wpel-link=\"internal\">ethicalcode@kymos.com<\/a><\/p>\n<p>(vii) Sollte schlie\u00dflich ein Mitarbeiter in einem Gerichtsverfahren angeklagt werden, muss er den Compliance Officer dar\u00fcber informieren, und das Unternehmen wird pr\u00fcfen, ob in dieser Hinsicht Pr\u00e4ventions- oder Ma\u00dfnahmen erforderlich sind, falls diese Anschuldigung mit den Interessen oder dem Ruf des Unternehmens kollidiert.<\/p>\n<p><strong>XXIV.- DER COMPLIANCE OFFICER. <\/strong><\/p>\n<p>Der Compliance Officer als das f\u00fcr die \u00dcberwachung und Koordination der \u00dcberwachungs- und Kontrollpolitik des Unternehmens mit den Verantwortlichen der einzelnen Bereiche zust\u00e4ndige Organ.<\/p>\n<p><strong>XXV.- STRAFVERFAHREN: <\/strong><\/p>\n<p>Die Nichteinhaltung der geltenden Vorschriften und des Verhaltenskodex stellt eine Straftat dar, deren Einstufung und Sanktionierung gem\u00e4\u00df den Bestimmungen der anwendbaren Vorschriften und der f\u00fcr das Unternehmen geltenden Tarifvertr\u00e4ge erfolgt.<\/p>\n<p><strong>XXVI.- REGELM\u00c4SSIGE \u00dcBERPR\u00dcFUNG DES VERHALTENSKODEX:<\/strong><\/p>\n<p>Dieser Verhaltenskodex wird \u00fcberpr\u00fcft und aktualisiert, um \u00c4nderungen oder Verbesserungen aufzunehmen, die als angemessen erachtet werden, um ihn an legislative \u00c4nderungen, \u00c4nderungen in der Struktur des Unternehmens oder seiner T\u00e4tigkeit anzupassen oder wenn Bereiche identifiziert werden, die generell verbessert werden k\u00f6nnen.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-b2ffc1108740f1e84 fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_b2ffc1108740f1e84\"><a aria-expanded=\"false\" aria-controls=\"b2ffc1108740f1e84\" role=\"button\" data-toggle=\"collapse\" data-target=\"#b2ffc1108740f1e84\" href=\"#b2ffc1108740f1e84\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Ethik-Kanal<\/span><\/a><\/h4><\/div><div id=\"b2ffc1108740f1e84\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_b2ffc1108740f1e84\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Potenzielle ethische oder rechtliche Fragen, die unser Gesch\u00e4ft betreffen, k\u00f6nnen gemeldet werden durch:<\/p>\n<ul>\n<li>Besuch des folgenden Links: <a href=\"https:\/\/centinela.lefebvre.es\/public\/concept\/1914579?access=w7WNl3QRhC16BCNysm8G%2FHa4TUzaG7eJwHlOB9eAgiM%3D\" data-wpel-link=\"external\">MELDUNG ETHISCHER \/ RECHTLICHER VERST\u00d6SSE<\/a><\/li>\n<li>Schreiben an: Ethical Code Dpt (Ronda Can Fatj\u00f3 5, Geb\u00e4ude D, 08290 Cerdanyola del Vall\u00e8s, Barcelona, Spanien)<\/li>\n<li>Telefonischer R\u00fcckruf: Geben Sie Ihre Kontaktnummer <a href=\"#form_anchor_legal\">in diesem Formular an.<\/a><\/li>\n<\/ul>\n<p>Niemand wird f\u00fcr eine in gutem Glauben erfolgte Meldung einer Beschwerde oder eines Anliegens Vergeltungsma\u00dfnahmen ausgesetzt.<\/p>\n<p>\u00dcber dieses Medium eingereichte Mitteilungen werden in \u00dcbereinstimmung mit den Bedingungen, Grunds\u00e4tzen und Garantien behandelt, die in der <a href=\"https:\/\/kymos.com\/wp-content\/uploads\/2026\/08\/COM-POL-CORPO.02.01-Corporate-Internal-Information-System-Policy.pdf\" data-wpel-link=\"external\">Unternehmensrichtlinie des internen Informationssystems<\/a> festgelegt sind.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-06c18022e11d9059d fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_06c18022e11d9059d\"><a aria-expanded=\"false\" aria-controls=\"06c18022e11d9059d\" role=\"button\" data-toggle=\"collapse\" data-target=\"#06c18022e11d9059d\" href=\"#06c18022e11d9059d\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Datenschutzrichtlinie<\/span><\/a><\/h4><\/div><div id=\"06c18022e11d9059d\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_06c18022e11d9059d\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<h4>1. Informationen \u00fcber den Verantwortlichen f\u00fcr die Verarbeitung der personenbezogenen Daten, die KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen \u00fcber die offizielle Website des Unternehmens zur Verf\u00fcgung gestellt werden.<\/h4>\n<p>Diese Datenschutzrichtlinie legt die Grundlagen fest, auf denen KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen die ihnen zur Verf\u00fcgung gestellten personenbezogenen Daten verarbeiten.<\/p>\n<p>Gem\u00e4\u00df den Bestimmungen der Datenschutz-Grundverordnung EU 2016\/679 vom 27. April 2016 informiert KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen die Nutzer dieses sozialen Netzwerks \u00fcber die Datenschutzrichtlinie bez\u00fcglich der Verarbeitung und des Datenschutzes solcher Nutzer, die freiwillig auf die offizielle Website von KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen zugreifen und sich dort anmelden.<\/p>\n<p>Allein durch den Besuch und das Durchsuchen dieser Website, die Eigentum von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen ist, werden keine Daten automatisch erfasst, die die Nutzer identifizieren. Es werden jedoch bestimmte Informationen gesammelt und in unseren Systemen aufgezeichnet, wie zum Beispiel die Art des Internetbrowsers, das Betriebssystem, die IP-Adresse, von der aus auf die Webseite zugegriffen wird, mit dem Ziel, die Navigation des Nutzers und die Verwaltung der Website selbst zu verbessern. Ebenso kann die Website Cookies und \u00e4hnliche Technologien verwenden, deren Verwendung in der Cookie-Richtlinie beschrieben ist. <\/p>\n<h4>2. Minderj\u00e4hrige oder gesch\u00e4ftsunf\u00e4hige Personen<\/h4>\n<p>Der Zugang und die Registrierung im sozialen Netzwerk und auf den offiziellen Websites von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen ist f\u00fcr Personen unter sechzehn (16) Jahren verboten. F\u00fcr den Fall, dass der potenzielle Nutzer eine gesch\u00e4ftsunf\u00e4hige Person ist, weist KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen auf die Notwendigkeit der Zustimmung der f\u00fcr die elterliche Sorge verantwortlichen Person oder des gesetzlichen Vertreters der gesch\u00e4ftsunf\u00e4higen Person hin, um auf die offiziellen Websites von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen zuzugreifen und diese zu nutzen. Das Unternehmen wird ausdr\u00fccklich von jeglicher Verantwortung befreit, die sich aus dem Zugang und der Nutzung seiner offiziellen Website durch Minderj\u00e4hrige und Gesch\u00e4ftsunf\u00e4hige ergeben kann, wobei deren gesetzliche Vertreter unter solchen Umst\u00e4nden die alleinigen Verantwortlichen sind. <\/p>\n<h4>3. Identifizierung des Verantwortlichen f\u00fcr die Verarbeitung personenbezogener Daten<\/h4>\n<p>Der Nutzer wird hiermit dar\u00fcber informiert, dass KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen mit Sitz in Parc Tecnol\u00f2gic del Vall\u00e8s, Ronda Can Fatj\u00f3 5, Geb\u00e4ude D. 08290 Cerdanyola del Vall\u00e8s, Barcelona, Spanien, der Verantwortliche f\u00fcr die Verarbeitung der Datei ist, die die personenbezogenen Daten des Nutzers enth\u00e4lt, die als Folge der Nutzung und Registrierung auf der Website, die Eigentum von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen ist, gesammelt und gespeichert werden.<\/p>\n<h4>4. Zwecke, f\u00fcr die die bereitgestellten personenbezogenen Daten bestimmt sind. Rechtsgrundlage. Hinweise an Nutzer.  <\/h4>\n<p>Die personenbezogenen Daten, die der Nutzer freiwillig KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen \u00fcber ihre offizielle Website zur Verf\u00fcgung stellt, werden in eine Datenverarbeitungsdatei unter der Verantwortung von KYMOS SL aufgenommen, mit dem Zweck, dem Nutzer Informationen \u00fcber KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen anzubieten, mit dem Nutzer Vertr\u00e4ge abzuschlie\u00dfen, sowie den Versand von Newslettern an abonnierte Nutzer, den Austausch von Informationen mit KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen und anderen Nutzern sowie die Herstellung von Kommunikation mit Dritten.<\/p>\n<p>Rechtsgrundlage: Die Rechtsgrundlage f\u00fcr die Verarbeitung personenbezogener Daten ist je nach den verschiedenen verfolgten Zwecken die Durchf\u00fchrung des Vertrags, wenn es um die Vertragsabwicklung geht, oder die Erf\u00fcllung Ihres Interesses an den Dienstleistungen von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen. In anderen F\u00e4llen ist die Rechtsgrundlage f\u00fcr die Datenverarbeitung Ihre ausdr\u00fcckliche Zustimmung, die erteilt wird, damit wir ein Angebot f\u00fcr Sie personalisieren und kommunizieren k\u00f6nnen, wenn Sie ein Angebot anfordern, oder Ihre ausdr\u00fcckliche Zustimmung, wenn keine fr\u00fchere vertragliche Beziehung besteht. <\/p>\n<p>\u00dcber die offiziellen Websites von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen kann der Nutzer Texte, Bilder, Videos und andere Arten von Informationen und\/oder Inhalten teilen, die ebenfalls dieser Richtlinie gem\u00e4\u00df ihren Regeln unterliegen. Der Nutzer ist daf\u00fcr verantwortlich, die geltende Gesetzgebung, diese Richtlinie und ihre Regeln zu respektieren. Der Nutzer darf nur personenbezogene Daten, Bilder, Informationen und andere Inhalte auf den offiziellen Websites von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen ver\u00f6ffentlichen, wenn er den Rechtstitel \u00fcber solche Ver\u00f6ffentlichungen besitzt oder die erforderliche Genehmigung Dritter erhalten hat.  <\/p>\n<p>KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen sind allein berechtigt, von den offiziellen Websites ohne vorherige Mitteilung oder Genehmigung des Nutzers alle vom Nutzer ver\u00f6ffentlichten Inhalte zu l\u00f6schen, die gegen die geltende Gesetzgebung und die Regeln dieser Richtlinie versto\u00dfen.<\/p>\n<p>Der Nutzer wird darauf hingewiesen, dass alle Informationen und Inhalte, die auf den offiziellen Websites von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen und in diesem sozialen Netzwerk ver\u00f6ffentlicht werden k\u00f6nnen, von den \u00fcbrigen Nutzern der offiziellen Website und der Social-Network-Plattform zur Kenntnis genommen werden k\u00f6nnen. Folglich k\u00f6nnen alle Informationen und vom Nutzer auf den offiziellen Websites von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen ver\u00f6ffentlichten Inhalte aufgrund der eigenen rechtlichen Natur des Dienstes an die \u00fcbrigen Nutzer weitergegeben werden. <\/p>\n<h4>5. \u00dcbermittlung oder Weitergabe personenbezogener Daten<\/h4>\n<p>Der Nutzer, der das Intranet nutzen m\u00f6chte, erh\u00e4lt eine E-Mail mit einem Benutzernamen und einem Passwort, um in den professionellen Bereich eintreten zu k\u00f6nnen.<\/p>\n<p>Personenbezogene Daten der Nutzer der offiziellen Website werden nicht an Dritte weitergegeben, au\u00dfer gegebenenfalls an zust\u00e4ndige Beh\u00f6rden im Rahmen der Aus\u00fcbung ihrer Aufgaben. Ausnahmsweise kann die Website gem\u00e4\u00df der Cookie-Richtlinie und mit Einwilligung des Nutzers Cookies von Drittanbietern verwenden. Wir informieren au\u00dferdem dar\u00fcber, dass wir die E-Mail-Marketingplattform \u201eMailchimp\u201c f\u00fcr den Versand unseres Newsletters nutzen; deren Datenschutzerkl\u00e4rung finden Sie unter folgendem Link: <a href=\"https:\/\/mailchimp.com\/legal\/privacy\/\" data-wpel-link=\"external\">https:\/\/mailchimp.com\/legal\/privacy\/<\/a>  <\/p>\n<h4>6. Von Nutzern bereitgestellte Lebensl\u00e4ufe<\/h4>\n<p>F\u00fcr die Zwecke der Bestimmungen der geltenden Gesetzgebung zum Datenschutz sind die Daten, die uns Lebensl\u00e4ufe zur Verf\u00fcgung stellen, f\u00fcr die Bearbeitung jeder Bewerbung erforderlich, und deren Eigent\u00fcmer stimmen zu, dass ihre personenbezogenen Daten und ihr Lebenslauf, einschlie\u00dflich E-Mail-Adresse, in die Datei aufgenommen werden, f\u00fcr die KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen verantwortlich sind, um eine solche Bewerbung zu pr\u00fcfen und\/oder umzusetzen sowie zu analysieren. Diese Daten werden f\u00fcr einen Zeitraum von einem Jahr aufbewahrt, nach dessen Ablauf KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen zu deren vollst\u00e4ndiger Vernichtung \u00fcbergehen werden.<\/p>\n<h4>7. Andere Dienstleister<\/h4>\n<p>KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen weisen den Nutzer darauf hin, dass sie nur f\u00fcr die Vertraulichkeit, Sicherheit und Datenverarbeitung gem\u00e4\u00df dieser Richtlinie in Bezug auf die personenbezogenen Daten verantwortlich sind und garantieren, die vom Nutzer \u00fcber die offiziellen Websites erhoben wurden. Sie \u00fcbernehmen keine Verantwortung f\u00fcr die Verarbeitung und sp\u00e4tere Nutzung der personenbezogenen Daten, die von Dritten mit Zugang zum sozialen Netzwerk ausgef\u00fchrt werden k\u00f6nnen, sowie von Dritten, die Dienste der Informationsgesellschaft erbringen und Zugang zu solchen Daten haben k\u00f6nnen, Dritten, die ihre T\u00e4tigkeit aus\u00fcben oder aus\u00fcben m\u00f6chten, Dritten, die Hyperlinks im sozialen Netzwerk einrichten, und denjenigen Verantwortlichen, zu denen KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen die auf ihren offiziellen Websites registrierten Nutzer durch die Nutzung von Hyperlinks weiterleiten.<\/p>\n<h4>8. Datenqualit\u00e4t<\/h4>\n<p>KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen warnen den Nutzer, dass ohne rechtliche Vertretung kein Nutzer die Identit\u00e4t einer anderen Person verwenden und deren personenbezogene Daten mitteilen darf. Dementsprechend muss der Nutzer stets best\u00e4tigen, dass die bereitgestellten Daten nur seiner eigenen Identit\u00e4t angeh\u00f6ren. Diese Daten m\u00fcssen angemessen, geeignet, aktuell, genau und wahrheitsgem\u00e4\u00df sein. In jedem Fall muss der Nutzer die Privatsph\u00e4re Dritter respektieren, unabh\u00e4ngig davon, ob diese Parteien bei diesem sozialen Netzwerk oder bei KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen registrierte Nutzer sind oder nicht.   <\/p>\n<p>Solange wir nicht anders informiert werden, gehen wir davon aus, dass die bereitgestellten Daten nicht ge\u00e4ndert wurden, dass Sie sich verpflichten, uns \u00fcber jede \u00c4nderung zu informieren, und dass wir Ihre Zustimmung haben, sie f\u00fcr die genannten Zwecke zu verwenden.<\/p>\n<h4>9. Aus\u00fcbung der Rechte auf Zugang, Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung, Widerspruch gegen die Verarbeitung und automatisierte Entscheidungsfindung sowie des Rechts auf Daten\u00fcbertragbarkeit:<\/h4>\n<p>KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen informieren den Nutzer hiermit \u00fcber die M\u00f6glichkeit, seine Rechte auf Auskunft, Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung, Widerspruch gegen die Verarbeitung und automatisierte Entscheidungsfindung sowie das Recht auf Daten\u00fcbertragbarkeit durch ein schriftliches Antragsformular auszu\u00fcben, das an KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen mit Sitz in PARC TECNOL\u00d2GIC DEL VALL\u00c8S. RONDA CAN FATJ\u00d3, 7B. 08290 CERDANYOLA DEL VALL\u00c8S, BARCELONA, SPANIEN gerichtet ist, oder durch Senden einer E-Mail an <a href=\"https:\/\/kymos.com\/%22mailto:\" data-wpel-link=\"external\">gdpr@kymos.com<\/a>. Zu diesem Zweck muss der Antragsteller an KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen die oben genannte schriftliche Mitteilung senden, in der er den Antrag oder das Recht angibt, das er aus\u00fcbt, und eine Kopie seines Personalausweises oder eines g\u00fcltigen Dokuments beif\u00fcgt, das seine Identit\u00e4t nachweist, wobei er ausdr\u00fccklich seinen Benutzernamen auf den offiziellen Websites von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen im sozialen Netzwerk angibt, um eindeutig identifiziert zu werden.   <\/p>\n<p>Wir erinnern Sie an Ihr Recht, eine Beschwerde bei der spanischen Datenschutzbeh\u00f6rde einzureichen, wenn Sie der Ansicht sind, dass ein Versto\u00df gegen die geltenden Datenschutzbestimmungen vorliegt, indem Sie an diese Beh\u00f6rde unter C \/ Jorge Juan, Nummer 6, 28001 &#8211; Madrid schreiben oder \u00fcber die Website: <a href=\"https:\/\/www.agpd.es\/\" data-wpel-link=\"external\">https:\/\/www.agpd.es<\/a><\/p>\n<h4>10. Sicherheit<\/h4>\n<p>Ihre Daten werden mit einem Schutzniveau verarbeitet, das den geltenden Vorschriften zum Schutz personenbezogener Daten entspricht.<\/p>\n<h4>11. Aufbewahrungsfrist Ihrer personenbezogenen Daten<\/h4>\n<p>Die bereitgestellten personenbezogenen Daten werden aufbewahrt, sofern deren L\u00f6schung nicht vom Dateninhaber beantragt wird, solange sie zur Erf\u00fcllung der vertraglichen Beziehung, zur Beantwortung von Anfragen oder Konsultationen oder solange Sie Ihr Interesse an unseren Dienstleistungen aufrechterhalten, und in jedem Fall f\u00fcr die Zeit, die zur Erf\u00fcllung der jeweils geltenden gesetzlichen Verpflichtungen gem\u00e4\u00df der Art der Daten erforderlich ist.<\/p>\n<h4>12. Weitere interessante Informationen<\/h4>\n<p>KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen k\u00f6nnen die vorliegende Richtlinie jederzeit \u00e4ndern und\/oder ersetzen. Wir empfehlen unseren Nutzern, diese Richtlinie regelm\u00e4\u00dfig einzusehen, um auf dem Laufenden zu bleiben. <\/p>\n<p>Der Nutzer kann das Unternehmen \u00fcber den internen Textdienst im sozialen Netzwerk oder \u00fcber die folgenden Kontaktdaten kontaktieren:<\/p>\n<p>KYMOS GROUP SL,<\/p>\n<p>Parc Tecnol\u00f2gic del Vall\u00e8s<\/p>\n<p>Ronda Can Fantj\u00f3 5, Geb\u00e4ude D. 08290 Cerdanyola del Vall\u00e8s<\/p>\n<p>Barcelona. Spanien <\/p>\n<p>E-Mail: <strong><a href=\"mailto:legal@kymos.com?subject=LOPD\" data-wpel-link=\"internal\">legal@kymos.com<\/a><\/strong><\/p>\n<p>Der Nutzer kann auch andere Regeln und Richtlinien einsehen, die der rechtliche Inhaber des sozialen Netzwerks ver\u00f6ffentlicht hat.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ec2b9a5b6955f2148 fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ec2b9a5b6955f2148\"><a aria-expanded=\"false\" aria-controls=\"ec2b9a5b6955f2148\" role=\"button\" data-toggle=\"collapse\" data-target=\"#ec2b9a5b6955f2148\" href=\"#ec2b9a5b6955f2148\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Cookie-Richtlinie<\/span><\/a><\/h4><\/div><div id=\"ec2b9a5b6955f2148\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_ec2b9a5b6955f2148\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Ein Cookie ist eine Datei, die beim Besuch bestimmter Websites auf Ihren Computer heruntergeladen wird. Cookies erm\u00f6glichen es einer Website unter anderem, Informationen \u00fcber einen Nutzer, seinen Computer und sein Surfverhalten zu speichern und abzurufen. Je nach den enthaltenen Informationen und Ihrer Computernutzung k\u00f6nnen Cookies dazu verwendet werden, den Nutzer wiederzuerkennen. Der Browser des Nutzers speichert Cookies nur w\u00e4hrend der aktuellen Sitzung auf der Festplatte. Sie belegen minimalen Speicherplatz und schaden Ihrem Computer nicht. Cookies enthalten keinerlei personenbezogene Daten, und die meisten werden nach Beendigung der Browsersitzung von der Festplatte gel\u00f6scht (sogenannte Session-Cookies). Die meisten Browser akzeptieren Cookies standardm\u00e4\u00dfig und bieten unabh\u00e4ngig davon Sicherheitseinstellungen, die tempor\u00e4re oder dauerhafte Cookies zulassen oder verhindern.    <\/p>\n<p>Ohne Ihre ausdr\u00fcckliche Zustimmung \u2013 durch Aktivierung von Cookies in Ihrem Browser \u2013 wird KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen die in den Cookies gespeicherten Daten nicht mit Ihren personenbezogenen Daten verkn\u00fcpfen, die Sie zum Zeitpunkt der Registrierung angegeben haben.<\/p>\n<p>Welche Arten von Cookies werden auf dieser Website verwendet?<\/p>\n<ul>\n<li>Technische Cookies: Diese erm\u00f6glichen es dem Benutzer, auf einer Webseite, Plattform oder Anwendung zu surfen und die verschiedenen Optionen oder Dienste zu nutzen, die dort vorhanden sind, wie zum Beispiel die Kontrolle des Datenverkehrs und der Datenkommunikation, die Identifizierung der Sitzung, den Zugriff auf gesch\u00fctzte Bereiche, das Speichern der Elemente einer Bestellung, die Durchf\u00fchrung des Kaufvorgangs, die Anmeldung oder Teilnahme an einer Veranstaltung, die Nutzung von Sicherheitselementen beim Surfen, das Speichern von Inhalten f\u00fcr die Video- oder Audio\u00fcbertragung oder das Teilen von Inhalten \u00fcber soziale Netzwerke.<\/li>\n<li>Personalisierungs-Cookies: Diese Cookies erm\u00f6glichen es dem Benutzer, auf den Dienst mit einigen allgemeinen, im Benutzerendger\u00e4t vordefinierten Merkmalen zuzugreifen, wie beispielsweise Sprache, Browsertyp, \u00fcber den auf den Dienst zugegriffen wird, regionale Konfiguration, von der aus auf den Dienst zugegriffen wird usw.<\/li>\n<li>Analyse-Cookies: Diese Cookies, die von uns oder Drittanbietern verarbeitet werden, erm\u00f6glichen es uns, die Anzahl der Nutzer zu erfassen und so die Nutzung unserer Dienste statistisch auszuwerten. Dadurch wird Ihr Navigationsverhalten auf unserer Website analysiert, um unser Produkt- und Dienstleistungsangebot zu verbessern. <\/li>\n<li>Cookies von Drittanbietern: Die Website von KYMOS GROUP kann Dienste von Drittanbietern nutzen, die im Auftrag von KYMOS GROUP Informationen zu statistischen Zwecken, zur Nutzung der Website durch den Nutzer und zur Bereitstellung anderer Dienste im Zusammenhang mit der Aktivit\u00e4t der Website und anderen Internetdiensten sammeln.<\/li>\n<\/ul>\n<p>Diese Website verwendet insbesondere die folgenden Cookies von Google, Inc. mit Sitz in den Vereinigten Staaten, 1600 Amphitheatre Parkway, Mountain View, Kalifornien 94043:<\/p>\n<p>a) <a href=\"https:\/\/www.google.com\/analytics\/terms\/us.html\" data-wpel-link=\"external\">Google Analytics<\/a> : Dies ist ein Webanalysedienst, der Informationen, einschlie\u00dflich der IP-Adresse des Nutzers, erfasst. Diese Daten werden von Google gem\u00e4\u00df den auf der Website Google.com festgelegten Bedingungen \u00fcbermittelt, verarbeitet und gespeichert. Dies schlie\u00dft die m\u00f6gliche Weitergabe dieser Informationen an Dritte ein, sei es aufgrund gesetzlicher Bestimmungen oder wenn diese Dritten die Daten im Auftrag von Google verarbeiten. <\/p>\n<p>b) <a href=\"https:\/\/support.google.com\/ds\/answer\/2839090?hl=en\" data-wpel-link=\"external\">DoubleClick<\/a>: verwendet Cookies, um Werbung zu verbessern, indem nach jeder Impression, jedem Klick oder einer anderen Aktivit\u00e4t, die zu einem Aufruf unserer Server f\u00fchrt, ein Cookie an den Browser gesendet wird. Wenn der Browser das Cookie akzeptiert, wird das Cookie im Browser gespeichert. <\/p>\n<p>c) <a href=\"https:\/\/support.google.com\/tagmanager\/answer\/6102821?hl=en\" data-wpel-link=\"external\">Google Tag Manager<\/a> : Mit diesem System k\u00f6nnen Sie Tags und Code-Snippets auf Ihrer Website oder mobilen App schnell und einfach aktualisieren. Sobald das Tag-Manager-Snippet hinzugef\u00fcgt wurde, k\u00f6nnen Sie die Tags \u00fcber eine webbasierte Benutzeroberfl\u00e4che konfigurieren, ohne zus\u00e4tzlichen Code \u00e4ndern und bereitstellen zu m\u00fcssen. Dadurch werden Fehler reduziert und Sie m\u00fcssen nicht mehr bei jeder \u00c4nderung einen Entwickler hinzuziehen.  <\/p>\n<p>d) <a href=\"https:\/\/support.google.com\/optimize\/answer\/6262388?hl=en\" data-wpel-link=\"external\">GA Audiences<\/a>: Eine Remarketing-Zielgruppe ist eine Liste von Cookies oder mobilen Werbe-IDs, die eine Gruppe von Nutzern repr\u00e4sentiert, die Sie erneut ansprechen m\u00f6chten, weil sie wahrscheinlich konvertieren werden.<\/p>\n<p>Dar\u00fcber hinaus verwendet diese Website die folgenden Cookies von Drupal: `<\/p>\n<p>a) <a href=\"https:\/\/www.acquia.com\/about-us\/legal\/privacy-policy\" data-wpel-link=\"external\">has_js<\/a> : Gibt an, ob JavaScript aktiviert ist, damit Drupal Operationen effizienter durchf\u00fchren und so die Benutzererfahrung verbessern kann.<\/p>\n<p>b) <a href=\"https:\/\/www.acquia.com\/about-us\/legal\/privacy-policy\" data-wpel-link=\"external\">Cookie-Zustimmung<\/a> : Gibt an, ob die Cookie-Richtlinien akzeptiert werden.<\/p>\n<p>Der Nutzer akzeptiert durch die Nutzung dieser Website die Verarbeitung der erhobenen Daten in der oben beschriebenen Weise und zu den oben genannten Zwecken. Er nimmt au\u00dferdem zur Kenntnis, dass er die Verarbeitung dieser Daten ablehnen kann, indem er die Verwendung von Cookies in seinen Browsereinstellungen deaktiviert. Beachten Sie jedoch, dass die Deaktivierung von Cookies die Nutzung einiger Funktionen der Website einschr\u00e4nken kann.  <\/p>\n<p>Sofern Sie die Einstellungen Ihres Browsers nicht angepasst haben, erstellt unser System Cookies, sobald Sie unsere Website besuchen. Beachten Sie, dass alle Internetbrowser die \u00c4nderung dieser Konfiguration erm\u00f6glichen. Weitere Informationen zur Anpassung Ihrer Cookie-Einstellungen in den folgenden Browsern finden Sie unter dem entsprechenden Link:  <\/p>\n<h4>Internet Explorer<\/h4>\n<p><a href=\"https:\/\/support.microsoft.com\/kb\/196955\" data-wpel-link=\"external\">https:\/\/support.microsoft.com\/kb\/196955<\/a><\/p>\n<p><a href=\"https:\/\/www.allaboutcookies.org\/es\/administrar-las-cookies\/internet-explorer7-plus.html\" data-wpel-link=\"external\">https:\/\/www.allaboutcookies.org\/es\/administrar-las-cookies\/internet-explorer7-plus.html<\/a><\/p>\n<p><a href=\"https:\/\/www.allaboutcookies.org\/es\/administrar-las-cookies\/internet-explorer8-plus.html\" data-wpel-link=\"external\">https:\/\/www.allaboutcookies.org\/es\/administrar-las-cookies\/internet-explorer8-plus.html<\/a><\/p>\n<p><a href=\"https:\/\/www.allaboutcookies.org\/es\/administrar-las-cookies\/internet-explorer9-plus.html\" data-wpel-link=\"external\">https:\/\/www.allaboutcookies.org\/es\/administrar-las-cookies\/internet-explorer9-plus.html<\/a><\/p>\n<p><a href=\"https:\/\/support.microsoft.com\/es-es\/help\/17442\/windows-internet-explorer-delete-manage-cookies\" data-wpel-link=\"external\">https:\/\/support.microsoft.com\/es-es\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/a><\/p>\n<h4>Firefox<\/h4>\n<p><a href=\"https:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-sitios-web-rastrear-preferencias%22%20%5Co%20%22Abre%20ventana%20nueva%22%20%5Ct%20%22_blank\" data-wpel-link=\"external\">https:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-sitios-web-rastrear-preferencias<br \/>\n <\/a><\/p>\n<h4>Chrom<\/h4>\n<p><a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?co=GENIE.Platform=Desktop&#038;hl=es%22%20%5Co%20%22Abre%20ventana%20nueva%22%20%5Ct%20%22_blank\" data-wpel-link=\"external\">https:\/\/support.google.com\/chrome\/answer\/95647?co=GENIE.Platform%3DDesktop&#038;hl=es<\/a><\/p>\n<h4>Safari<\/h4>\n<p><a href=\"https:\/\/support.apple.com\/kb\/ph21411?locale=es_ES\" data-wpel-link=\"external\">https:\/\/support.apple.com\/kb\/ph21411?locale=es_ES<\/a><\/p>\n<p><a href=\"https:\/\/support.apple.com\/es-es\/HT201265%22%20%5Co%20%22Abre%20ventana%20nueva%22%20%5Ct%20%22_blank\" data-wpel-link=\"external\">https:\/\/support.apple.com\/es-es\/HT201265<\/a><\/p>\n<h4>\u00c4nderungen der Cookie-Richtlinie<\/h4>\n<p>Wir aktualisieren m\u00f6glicherweise die Cookie-Richtlinie unserer Website. Daher empfehlen wir Ihnen, diese Richtlinie bei jedem Besuch unserer Website zu lesen, um sich dar\u00fcber zu informieren, wie und warum wir Cookies verwenden. Die Cookie-Richtlinie wurde zuletzt am 10. Juli 2018 aktualisiert. <\/p>\n<p>Wenn Sie Fragen zu dieser Cookie-Richtlinie haben, k\u00f6nnen Sie Kymos Group unter der folgenden Adresse kontaktieren: <strong><a href=\"mailto:legal@kymos.com?subject=Cookies\" data-wpel-link=\"internal\">legal@kymos.com<\/a><\/strong>.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-961d9d7858e801128 fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_961d9d7858e801128\"><a aria-expanded=\"false\" aria-controls=\"961d9d7858e801128\" role=\"button\" data-toggle=\"collapse\" data-target=\"#961d9d7858e801128\" href=\"#961d9d7858e801128\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Rechte an geistigem und gewerblichem Eigentum<\/span><\/a><\/h4><\/div><div id=\"961d9d7858e801128\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_961d9d7858e801128\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Mit Ausnahme derjenigen Inhalte, die gemeinfrei sind und keinen Rechten Dritter unterliegen, besitzt KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen die Rechtstitel an allen geistigen und gewerblichen Schutzrechten in Bezug auf den Inhalt, das Design und den Quellcode dieser Website (einschlie\u00dflich, aber nicht beschr\u00e4nkt auf: Datenbanken, Bilder, Zeichnungen, Grafiken, Texte, Audio, Video und Software), und diese sind sowohl durch nationale als auch internationale Gesetze zum Schutz des geistigen und gewerblichen Eigentums gesch\u00fctzt.<\/p>\n<p>KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen \u00fcbernehmen keine Verantwortung f\u00fcr die Inhalte, die \u00fcber die Links folgen, die in jedem Fall in der Verantwortung der Eigent\u00fcmer der entsprechenden Webseiten liegen, die solchen Links folgen. Wenn ein Nutzer der Ansicht ist, dass ein Inhalt oder die Links Rechte Dritter verletzen k\u00f6nnten, informieren Sie bitte KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen, indem Sie eine E-Mail an die folgende Adresse senden: <strong><a href=\"mailto:legal@kymos.com\" data-wpel-link=\"internal\">legal@kymos.com<\/a><\/strong>. <\/p>\n<p>Die Marken, Symbole, Kennzeichen und Logos von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen, die auf der Website enthalten sind, werden von diesem Unternehmen gehalten und sind ordnungsgem\u00e4\u00df eingetragen.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-f9c9a5a77a2dbb432 fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f9c9a5a77a2dbb432\"><a aria-expanded=\"false\" aria-controls=\"f9c9a5a77a2dbb432\" role=\"button\" data-toggle=\"collapse\" data-target=\"#f9c9a5a77a2dbb432\" href=\"#f9c9a5a77a2dbb432\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Transparenzinformationen<\/span><\/a><\/h4><\/div><div id=\"f9c9a5a77a2dbb432\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_f9c9a5a77a2dbb432\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Gem\u00e4\u00df dem spanischen Gesetz 19\/2013 vom 9. Dezember \u00fcber Transparenz, Zugang zu \u00f6ffentlichen Informationen und gute Regierungsf\u00fchrung erkl\u00e4rt KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen, verschiedene Zusch\u00fcsse aus \u00f6ffentlichen Mitteln erhalten zu haben. Weitere Informationen sind auf dieser Website im Abschnitt <strong><a href=\"https:\/\/kymos.com\/de\/innovation\/\" data-wpel-link=\"internal\">\u00dcber uns \/ <\/a>Innovation<\/strong><em> zug\u00e4nglich.<\/em><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-2a4514d5d4de8a562 fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_2a4514d5d4de8a562\"><a aria-expanded=\"false\" aria-controls=\"2a4514d5d4de8a562\" role=\"button\" data-toggle=\"collapse\" data-target=\"#2a4514d5d4de8a562\" href=\"#2a4514d5d4de8a562\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Allgemeine Verkaufsbedingungen<\/span><\/a><\/h4><\/div><div id=\"2a4514d5d4de8a562\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_2a4514d5d4de8a562\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<h4>1. Geltungsbereich<\/h4>\n<p>Diese ALLGEMEINEN VERKAUFSBEDINGUNGEN gelten f\u00fcr alle Bestellungen, die von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen (nachfolgend \u201eKYMOS GROUP\u201c) und\/oder ihren verbundenen Unternehmen aufgegeben und vom KUNDEN und\/oder seinen verbundenen Unternehmen (jeweils einzeln auch als \u201ePartei\u201c oder gemeinsam als \u201eParteien\u201c bezeichnet) angenommen werden, f\u00fcr den Erwerb der Dienstleistungen der KYMOS GROUP (\u201edie Dienstleistungen\u201c) im Rahmen eines oder mehrerer Projekte.<\/p>\n<p>Der Begriff \u201eVerbundenes Unternehmen\u201c bezeichnet jede Einheit, Person, Firma oder Gesellschaft, die direkt oder indirekt \u00fcber einen oder mehrere Vermittler eine der Parteien beherrscht, von ihr beherrscht wird oder mit ihr unter gemeinsamer Beherrschung steht.<\/p>\n<p>Jede gleichwertige Bestimmung, die in einer zwischen KYMOS GROUP und dem KUNDEN geschlossenen g\u00fcltigen Vereinbarung enthalten ist, wie unter anderem Geheimhaltungsvereinbarungen, der Rahmendienstleistungsvertrag, technische Vereinbarungen, Arbeitsauftr\u00e4ge oder Angebote, hat Vorrang vor diesen ALLGEMEINEN VERKAUFSBEDINGUNGEN.<\/p>\n<h4>2. Vertraulichkeit<\/h4>\n<p>F\u00fcr die Dauer der Dienstleistungen und bis zu f\u00fcnf (5) Jahre nach deren Abschluss vereinbaren die Parteien, dass alle ausgetauschten Informationen von ihren Gesch\u00e4ftsf\u00fchrern, Mitarbeitern oder Beratern als vertraulich behandelt und nicht an andere Parteien weitergegeben werden, au\u00dfer: i) Informationen, die der anderen Partei bereits bekannt waren, ii) Informationen, die \u00f6ffentlich zug\u00e4nglich sind, iii) Informationen, die gesetzlich offengelegt werden m\u00fcssen, iv) Informationen, die den Beh\u00f6rden zu regulatorischen Zwecken offengelegt werden m\u00fcssen. Die Weitergabe des Namens und\/oder Logos der anderen Partei an Dritte mit dem alleinigen Zweck, diese als gesch\u00e4ftliche Referenz zu nennen, ist zul\u00e4ssig und f\u00e4llt nicht unter die in dieser Klausel vorgesehenen Vertraulichkeitspflichten.     <\/p>\n<h4>3. Dienstleistungen<\/h4>\n<p>KYMOS GROUP erbringt die Dienstleistungen in \u00dcbereinstimmung mit: i) diesen Allgemeinen Bedingungen und allen anderen zwischen den Parteien unterzeichneten Vereinbarungen, ii) allen von den Parteien genehmigten Protokollen; iii) den geltenden Gesetzen und Vorschriften, iv) unter Einhaltung der GLP-, GCP- und GMP-Anforderungen, sofern zwischen den Parteien vereinbart, und iv) allen anerkannten wissenschaftlichen Grunds\u00e4tzen und Praktiken in der wissenschaftlichen Gemeinschaft.     <\/p>\n<h4>4. Laufzeit der Dienstleistungen<\/h4>\n<p>4.1. Die von KYMOS GROUP ausgestellten Angebote gelten als vom KUNDEN angenommen, sobald Kymos i) das unterzeichnete Angebot; ii) ein Best\u00e4tigungsschreiben\/-E-Mail; iii) einen Arbeitsauftrag (WO), iv) eine Bestellung (PO); oder v) Proben zur Analyse erh\u00e4lt. Falls der Kunde eine WO-\/PO-Nummer f\u00fcr Rechnungszwecke ben\u00f6tigt, wird KYMOS GROUP keine Arbeiten beginnen, bis der Kunde KYMOS GROUP die entsprechende Nummer mitteilt.      <\/p>\n<p>4.2. Vor Beginn der Dienstleistungen stellt der KUNDE KYMOS GROUP alle relevanten und ausreichenden verf\u00fcgbaren Informationen \u00fcber das Projekt zur Verf\u00fcgung, damit KYMOS GROUP die Dienstleistungen ordnungsgem\u00e4\u00df erbringen kann. Der KUNDE stellt au\u00dferdem kostenlos eine ausreichende Menge an Proben, Standards und sonstigem spezifischem Material zur Verf\u00fcgung, das f\u00fcr die Durchf\u00fchrung der Dienstleistungen durch KYMOS GROUP erforderlich ist, einschlie\u00dflich der Menge f\u00fcr Wiederholungen, falls erforderlich. Eigentum und Verlustrisiko dieser Materialien verbleiben beim KUNDEN.  <\/p>\n<p>4.3. Die Dienstleistungen m\u00fcssen von KYMOS GROUP gem\u00e4\u00df dem entsprechenden Auftrag und allen zwischen den Parteien vereinbarten Protokollen durchgef\u00fchrt werden und sind fristgerecht zu erbringen. Falls KYMOS GROUP feststellt, dass die gesch\u00e4tzten Fristen nicht eingehalten werden k\u00f6nnen, benachrichtigt sie den KUNDEN und unternimmt alle Anstrengungen, um eine solche Verz\u00f6gerung zu minimieren. <\/p>\n<p>4.4. Falls die gesamten oder Teile der Dienstleistungen wiederholt werden m\u00fcssen, f\u00fchrt KYMOS GROUP diese so bald wie vern\u00fcnftigerweise m\u00f6glich auf eigene Kosten durch, sofern die Wiederholung auf ein Verschulden von KYMOS GROUP zur\u00fcckzuf\u00fchren ist, andernfalls auf Kosten des KUNDEN. Falls zwischen den Parteien ein Streit dar\u00fcber entsteht, ob ein Verschulden von KYMOS GROUP vorliegt, k\u00f6nnen die Parteien den Streit einem von beiden Parteien akzeptierten unabh\u00e4ngigen Pr\u00fcflabor vorlegen. Die Entscheidung des Labors ist endg\u00fcltig und bindend, au\u00dfer im Falle eines offensichtlichen wesentlichen Fehlers. Die Kosten f\u00fcr eine solche Laborpr\u00fcfung tr\u00e4gt die Partei, deren Ergebnisse das unabh\u00e4ngige Labor widersprochen hat.   <\/p>\n<p>4.5. Der KUNDE akzeptiert, dass aufgrund der Art der Dienstleistungen ein positives und n\u00fctzliches Ergebnis nicht garantiert werden kann, und verzichtet darauf, diesbez\u00fcglich Anspr\u00fcche, Forderungen oder Klagen gegen KYMOS GROUP zu erheben oder Verluste, Sch\u00e4den und Haftungsanspr\u00fcche gegen\u00fcber KYMOS GROUP in diesem Zusammenhang geltend zu machen.<\/p>\n<h4>5. Unterauftragsvergabe<\/h4>\n<p>KYMOS GROUP ist nicht berechtigt, alle oder einen Teil der Dienstleistungen ohne schriftliche Zustimmung des KUNDEN an Dritte zu vergeben, es sei denn, es handelt sich um ein verbundenes Unternehmen oder dies ist im Angebot oder im Auftrag des KUNDEN angegeben. Die Nutzung von Ger\u00e4ten, die Universit\u00e4ten, \u00f6ffentlichen Zentren oder Technologiezentren geh\u00f6ren, unter direkter Bedienung oder Aufsicht von Mitarbeitern der KYMOS GROUP gilt nicht als Unterauftragsvergabe. <\/p>\n<h4>6. Audit<\/h4>\n<p>Der KUNDE hat das Recht, die Einrichtungen von KYMOS GROUP einmal j\u00e4hrlich nach einer Vorank\u00fcndigung von drei\u00dfig (30) Arbeitstagen zu pr\u00fcfen, um die Einhaltung der Vorschriften und \u00fcbernommenen Verpflichtungen zu \u00fcberpr\u00fcfen. Dar\u00fcber hinaus akzeptiert KYMOS GROUP jede obligatorische Pr\u00fcfung durch die zust\u00e4ndigen Beh\u00f6rden in Bezug auf die vom KUNDEN beauftragten Dienstleistungen. <\/p>\n<h4>7. Ergebnisse und Erfindungen<\/h4>\n<p>Alle Ergebnisse und\/oder Erfindungen, mit Ausnahme von Innovationen, die KYMOS GROUP bei analytischen Methoden, Verfahren oder \u00c4hnlichem vornimmt, ob patentierbar oder nicht, die sich aus den erbrachten Dienstleistungen ergeben oder daraus resultieren, sind und bleiben alleiniges und ausschlie\u00dfliches Eigentum des KUNDEN.<\/p>\n<h4>8. Schadloshaltung<\/h4>\n<p>Jede Partei h\u00e4lt die andere Partei schadlos, verteidigt sie und stellt sie von jeglicher rechtlichen Haftung, Verlusten, Sch\u00e4den, Kosten oder Aufwendungen frei, einschlie\u00dflich angemessener Anwaltsgeb\u00fchren, die aus einer fahrl\u00e4ssigen Handlung, vors\u00e4tzlichem Fehlverhalten, Unterlassung oder Verletzung der Bestimmungen dieser ALLGEMEINEN VERKAUFSBEDINGUNGEN durch diese Partei resultieren. In keinem Fall \u00fcbersteigt jedoch die Gesamthaftung von Kymos Group, die sich aus diesen ALLGEMEINEN VERKAUFSBEDINGUNGEN ergibt oder damit zusammenh\u00e4ngt, das Dreifache (3) der Verg\u00fctung des KUNDEN f\u00fcr die entsprechenden Dienstleistungen. <\/p>\n<p>Der KUNDE h\u00e4lt KYMOS GROUP schadlos, verteidigt sie und stellt sie von jeglichen Anspr\u00fcchen Dritter frei, die eine Verletzung, widerrechtliche Aneignung oder missbr\u00e4uchliche Nutzung von Patenten, Gesch\u00e4ftsgeheimnissen oder anderen geistigen Eigentumsrechten in Bezug auf Produkte, Proben, Know-how und Verfahren geltend machen.<\/p>\n<h4>9. Versicherung<\/h4>\n<p>W\u00e4hrend der Dauer der Dienstleistungen unterhalten beide Parteien geeignete Versicherungspolicen, die allgemeine, zivilrechtliche und berufliche Haftpflichten abdecken.<\/p>\n<h4>10. Preise und Zahlungsbedingungen<\/h4>\n<p>10.1. Der KUNDE zahlt KYMOS GROUP f\u00fcr die Dienstleistungen gem\u00e4\u00df den Preisen und Bedingungen, die in den entsprechenden Angeboten f\u00fcr jedes Projekt festgelegt sind. Alle Betr\u00e4ge sind innerhalb von drei\u00dfig (30) Tagen zu zahlen, und KYMOS GROUP kann auf \u00fcberf\u00e4llige Betr\u00e4ge ohne berechtigten Grund die entsprechenden Zinsen erheben. <\/p>\n<p>10.2. Falls ein Teil einer Rechnung bestritten wird, zahlt der KUNDE den unbestrittenen Betrag unverz\u00fcglich. Beide Parteien bem\u00fchen sich nach Treu und Glauben, Differenzen oder Unstimmigkeiten in k\u00fcrzester Zeit zu kl\u00e4ren. Jede Verz\u00f6gerung des KUNDEN von mehr als sieben (7) Tagen bei der Einhaltung von Zahlungsterminen gegen\u00fcber KYMOS GROUP f\u00fchrt zu Verzugszinsen in H\u00f6he von 8 Prozentpunkten \u00fcber dem Referenzzinssatz der Europ\u00e4ischen Zentralbank (EZB).  <\/p>\n<p>10.3. KYMOS GROUP kann die Preise \u00fcberpr\u00fcfen, wenn berechtigte und objektive Gr\u00fcnde vorliegen, einschlie\u00dflich, aber nicht beschr\u00e4nkt auf zus\u00e4tzliche Tests, die nicht im Arbeitsauftrag enthalten sind, neue im Protokoll enthaltene Anforderungen oder eine erh\u00f6hte Komplexit\u00e4t des Projekts, die zum Zeitpunkt des Angebots nicht vorhersehbar war. Unter solchen Umst\u00e4nden legt KYMOS GROUP dem KUNDEN eine Preis\u00fcberpr\u00fcfung vor, und beide Parteien er\u00f6rtern diese nach Treu und Glauben, um eine Einigung zu erzielen. Falls innerhalb von f\u00fcnfzehn (15) Tagen keine Einigung erzielt werden kann, hat jede der Parteien das Recht, die Dienstleistungen zu beenden, vorausgesetzt, dass KYMOS GROUP alle erforderlichen Informationen \u00fcbertr\u00e4gt, damit der KUNDE das Projekt in dem Stadium fortsetzen kann, in dem es beendet wurde, und der KUNDE KYMOS GROUP unverz\u00fcglich alle ausstehenden Betr\u00e4ge im Zusammenhang mit den bis zum Beendigungsdatum erbrachten Dienstleistungen zahlt, die noch nicht in Rechnung gestellt wurden.  <\/p>\n<h4>11. Probenlagerung und Archivierung<\/h4>\n<p>11.1. KYMOS GROUP lagert oder veranlasst die Lagerung durch einen autorisierten Unterauftragnehmer nach Abschluss der Dienstleistungen aller Daten, Informationen, Ergebnisse und sonstiger relevanter Dokumentation im Zusammenhang mit den Dienstleistungen. Dem KUNDEN k\u00f6nnen nach Abschluss der Dienstleistungen Archivierungsgeb\u00fchren von KYMOS GROUP in Rechnung gestellt werden. <\/p>\n<p>11.2. KYMOS GROUP lagert die erhaltenen Proben und Standards unter den vom KUNDEN angegebenen spezifischen Bedingungen. Dem KUNDEN werden Probenlagerungsdienstleistungen in Rechnung gestellt, wenn dies im Arbeitsauftrag angegeben ist, und es werden ihm Probenlagerungsgeb\u00fchren von KYMOS GROUP f\u00fcr die nicht verwendeten oder verbleibenden Probenmengen nach Abschluss der Dienstleistungen in Rechnung gestellt. <\/p>\n<p>11.3. Der KUNDE kann jederzeit auf eigene Kosten von KYMOS GROUP verlangen, dass Dokumente oder Proben i) ordnungsgem\u00e4\u00df vernichtet, (ii) unverz\u00fcglich an den KUNDEN zur\u00fcckgegeben werden, es sei denn, KYMOS GROUP ist verpflichtet, Dokumente oder Proben aufzubewahren, um einschl\u00e4gige Vorschriften einhalten zu k\u00f6nnen.  <\/p>\n<h4>12. Beendigung<\/h4>\n<p>12.1. Jede Partei ist berechtigt, diese Vereinbarung durch schriftliche Mitteilung an die andere Partei zu beenden, falls: i) die andere Partei eine der Bestimmungen dieser Allgemeinen Bedingungen oder einer anderen Vereinbarung zwischen den Parteien wesentlich verletzt und diese Verletzung wesentlich ist und nicht innerhalb von drei\u00dfig (30) Tagen nach Erhalt einer schriftlichen Mitteilung der nicht s\u00e4umigen Partei, die die Behebung einer solchen Verletzung verlangt, behoben wird, ii) die andere Partei aus irgendeinem Grund ihre Gesch\u00e4ftst\u00e4tigkeit einstellt oder in Liquidation geht.  <\/p>\n<p>12.2. Der KUNDE hat das Recht, jeden genehmigten Arbeitsauftrag jederzeit zu stornieren, wenn ein berechtigter Grund vorliegt. In einem solchen Fall stellt KYMOS GROUP die laufenden Arbeiten innerhalb von f\u00fcnf (5) Arbeitstagen ein und stellt dem KUNDEN alle entstandenen Kosten und Aufwendungen sowie die Kosten aller wirtschaftlichen Verpflichtungen gegen\u00fcber Dritten in Rechnung, die nicht storniert werden k\u00f6nnen oder nicht erstattungsf\u00e4hig sind. Die bei Auftragsbest\u00e4tigung geleistete Anfangszahlung gilt jedoch als nicht erstattungsf\u00e4hig.  <\/p>\n<h4>13. H\u00f6here Gewalt<\/h4>\n<p>Keine Partei ist verantwortlich f\u00fcr Verz\u00f6gerungen, Nichtlieferungen, Nichterf\u00fcllung, Verluste, Kosten, Anspr\u00fcche oder die Nichterf\u00fcllung ganz oder teilweise, wenn diese durch Streiks, Krieg, Aufruhr, Revolution, Terrorismus, Embargos, Br\u00e4nde, \u00dcberschwemmungen, D\u00fcrren, Unf\u00e4lle, Aussperrungen, Maschinenausf\u00e4lle, Arbeitsniederlegungen, staatliche Verbote oder andere Ursachen au\u00dferhalb der Kontrolle einer Partei verursacht werden, vorausgesetzt, die betroffene Partei benachrichtigt die andere Partei unverz\u00fcglich und unternimmt alle zumutbaren Anstrengungen, um die Ursache und die Auswirkungen eines solchen Ereignisses zu beheben, zu beseitigen oder zu mildern. Wenn ein Ereignis h\u00f6herer Gewalt eine der Parteien l\u00e4nger als 3 Monate an der Erf\u00fcllung ihrer Verpflichtungen hindert, ist die andere Partei berechtigt, diese Vereinbarung zu k\u00fcndigen. <\/p>\n<h4>14. Fortbestehende Verpflichtungen<\/h4>\n<p>Bei Beendigung der Dienstleistungen aus irgendeinem Grund bleiben die erworbenen Rechte, Pflichten und Rechtsbehelfe der Parteien aus diesen Allgemeinen Bedingungen unber\u00fchrt, und diejenigen Bestimmungen, die fortbestehen oder in Kraft treten sollen, bleiben ungeachtet der Beendigung bestehen.<\/p>\n<h4>15. Abtretung<\/h4>\n<p>Au\u00dfer an ein verbundenes Unternehmen und nach vorheriger Mitteilung an die andere Partei d\u00fcrfen weder KYMOS GROUP noch der KUNDE eine Vereinbarung oder Forderung ohne Zustimmung der anderen Partei abtreten.<\/p>\n<h4>16. Abwerbeverbot<\/h4>\n<p>16.1 Beide Parteien vereinbaren, dass solange die Vereinbarung in Kraft ist und f\u00fcr einen Zeitraum von einem (1) Jahr nach ihrer Beendigung keine der Parteien bestehende Gesch\u00e4fte der anderen Partei und\/oder ihrer verbundenen Unternehmen oder Kunden oder Lieferanten dieser Partei und\/oder ihrer verbundenen Unternehmen auf eine andere Person, juristische Person oder einen Wettbewerber umlenken wird und in keiner Weise in die Beziehung zwischen einem Kunden, Lieferanten oder einer anderen Gesch\u00e4ftseinheit der anderen Partei eingreifen wird.<\/p>\n<p>16.2 Beide Parteien vereinbaren, dass solange die Vereinbarung in Kraft ist und f\u00fcr einen Zeitraum von einem (1) Jahr nach ihrer Beendigung keine der Parteien direkt oder indirekt eine Person dazu verleiten oder zu veranlassen versuchen wird, ihr Arbeitsverh\u00e4ltnis mit der anderen Partei zu beenden, und nicht in die Beziehungen zwischen den Vertretern, leitenden Angestellten, Beratern, Partnern, Joint-Venture-Partnern oder Aktion\u00e4ren der anderen Partei eingreifen wird, vorausgesetzt jedoch, dass eine allgemeine Stellenanzeige, auf die ein Mitarbeiter der anderen Partei reagiert, in keinem Fall als Versto\u00df gegen diese Klausel angesehen wird.<\/p>\n<h4>17. Salvatorische Klausel<\/h4>\n<p>Falls eine Bestimmung oder Klausel der Allgemeinen Bedingungen f\u00fcr ung\u00fcltig oder nicht durchsetzbar befunden wird, bleiben die \u00fcbrigen Bestimmungen davon unber\u00fchrt und sind im gesetzlich zul\u00e4ssigen Umfang g\u00fcltig und durchsetzbar.<\/p>\n<h4>18. Unabh\u00e4ngige Auftragnehmer<\/h4>\n<p>Die Parteien sind unabh\u00e4ngige Auftragnehmer, und unter keinen Umst\u00e4nden gelten eine Partei, ihre Mitarbeiter oder Vertreter als Vertreter, Mitarbeiter, Repr\u00e4sentanten oder Joint-Venture-Partner der anderen Partei. Keine Partei hat das Recht, im Namen oder f\u00fcr die andere Partei in irgendeiner Weise Vertr\u00e4ge abzuschlie\u00dfen oder Verpflichtungen einzugehen. <\/p>\n<h4>19. Datenschutz<\/h4>\n<p>Gem\u00e4\u00df den Bestimmungen der Verordnung (EU) 2016\/679 vom 27. April 2016 und des LSSICE 34\/2002 vom 11. Juli \u00fcber die Informationsgesellschaft und den elektronischen Gesch\u00e4ftsverkehr wird KYMOS GROUP die darin enthaltenen personenbezogenen Daten des KUNDEN zusammen mit den w\u00e4hrend der Laufzeit einer Vereinbarung zwischen den Parteien erhobenen Daten in eine unter ihrer Verantwortung erstellte Datei aufnehmen, um die Verwaltung dieser Vertragsbeziehung durchzuf\u00fchren und auch f\u00fcr den Versand von Gesch\u00e4ftsinformationen auf elektronischem oder postalischem Weg. Diese Verarbeitung dient den folgenden Zwecken und hat als Rechtsgrundlage den Versand von Gesch\u00e4fts- und Werbemitteilungen sowie die Verwaltung der Vertragsbeziehung mit DEM KUNDEN. Der KUNDE kann als Eigent\u00fcmer der Daten jederzeit seine Rechte auf Zugang, Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung, Widerspruch gegen die Verarbeitung und automatisierte Entscheidungsfindung sowie das Recht auf Daten\u00fcbertragbarkeit aus\u00fcben, indem er an die unter Ziffer 19 angegebene Adresse schreibt. Wir erinnern Sie an Ihr Recht, bei der spanischen Datenschutzbeh\u00f6rde Beschwerde einzulegen, falls Sie der Ansicht sind, dass gegen die geltenden Datenschutzbestimmungen versto\u00dfen wird, indem Sie an diese Beh\u00f6rde unter C \/ Jorge Juan, Nummer 6, 28001 &#8211; Madrid oder \u00fcber die Website <a href=\"https:\/\/www.agpd.es\/\" data-wpel-link=\"external\">www.agpd.es<\/a> schreiben.   <\/p>\n<h4>20. Mitteilungen<\/h4>\n<p>Jede Mitteilung, Anfrage, Forderung, Zustimmung oder sonstige Kommunikation, die erforderlich oder zul\u00e4ssig ist, muss schriftlich erfolgen und gilt als wirksam zugestellt, wenn sie pers\u00f6nlich \u00fcbergeben, per beglaubigtem Fax \u00fcbermittelt oder per Einschreiben versandt wird. Die angegebene Adresse f\u00fcr KYMOS GROUP SL und\/oder ihre verbundenen Unternehmen zur Aufmerksamkeit der Gesch\u00e4ftsleitung lautet wie folgt: Parc Tecnol\u00f2gic del Vall\u00e8s. Ronda Can Fatj\u00f3 5, Geb\u00e4ude D. 08290 Cerdanyola del Vall\u00e8s, Barcelona, Spanien. E-Mail <a href=\"mailto:legal@kymos.com\" data-wpel-link=\"internal\">legal@kymos.com<\/a>.   <\/p>\n<h4>21. Anwendbares Recht und Gerichtsstand<\/h4>\n<p>Alle Streitigkeiten, die im Zusammenhang mit diesen Allgemeinen Bedingungen entstehen und nicht g\u00fctlich beigelegt werden k\u00f6nnen, werden ausschlie\u00dflich von den Gerichten in Barcelona gem\u00e4\u00df den Gesetzen Spaniens entschieden, ohne Ber\u00fccksichtigung der Grunds\u00e4tze des Kollisionsrechts.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-710cd5eddcbf1453f fusion-toggle-no-divider fusion-toggle-boxed-mode\" style=\"--awb-title-color:#82988c;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_710cd5eddcbf1453f\"><a aria-expanded=\"false\" aria-controls=\"710cd5eddcbf1453f\" role=\"button\" data-toggle=\"collapse\" data-target=\"#710cd5eddcbf1453f\" href=\"#710cd5eddcbf1453f\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Allgemeine Einkaufsbedingungen<\/span><\/a><\/h4><\/div><div id=\"710cd5eddcbf1453f\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_710cd5eddcbf1453f\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<h4>1. Geltungsbereich<\/h4>\n<p>1.1. Diese ALLGEMEINEN EINKAUFSBEDINGUNGEN gelten f\u00fcr alle Bestellungen, die von KYMOS GROUP SL und\/oder ihren verbundenen Unternehmen (nachfolgend \u201eKYMOS GROUP\u201c genannt) ausgestellt und von ihren Lieferanten (nachfolgend \u201eLIEFERANT\u201c genannt) angenommen werden (jeder von ihnen einzeln als \u201ePartei\u201c oder gemeinsam als \u201eParteien\u201c bezeichnet), f\u00fcr den Kauf von Produkten oder Dienstleistungen des LIEFERANTEN. (\u201edas\/die Produkt\/e\u201c). <\/p>\n<p>1.2. Der Begriff \u201eVerbundenes Unternehmen\u201c bezeichnet jede Einheit, Person, Firma oder Gesellschaft, die direkt oder indirekt \u00fcber einen oder mehrere Vermittler eine der Parteien beherrscht, von ihr beherrscht wird oder mit ihr unter gemeinsamer Beherrschung steht.<\/p>\n<h4>2. Annahme<\/h4>\n<p>2.1. Die Annahme dieser ALLGEMEINEN EINKAUFSBEDINGUNGEN durch den LIEFERANTEN beinhaltet den sofortigen Verzicht auf seine eigenen allgemeinen Verkaufsbedingungen. Alle Bedingungen und Spezifikationen, die der LIEFERANT in seine Angebote, Rechnungen oder andere Dokumente einf\u00fcgen mag, die nicht schriftlich zwischen den Parteien vereinbart wurden und diesen ALLGEMEINEN EINKAUFSBEDINGUNGEN widersprechen, werden als null und nichtig betrachtet. <\/p>\n<h4>3. Formalisierung von Bestellungen<\/h4>\n<p>3.1. Nur schriftlich von KYMOS GROUP auf ihrem Bestellformular (nachfolgend \u201edie Bestellung\/en\u201c) aufgegebene Bestellungen sind g\u00fcltig. Eine m\u00fcndliche Bestellung ist nur dann bindend, wenn KYMOS GROUP sie schriftlich best\u00e4tigt. Ebenso verpflichtet sich der LIEFERANT, alle Bestellungen mit einem unterzeichneten Dokument oder einem Genehmigungsschreiben\/einer Genehmigungs-E-Mail anzunehmen und schriftlich zu best\u00e4tigen. KYMOS GROUP ist nicht verpflichtet, Produkte zu erwerben, die sich auf eine vom LIEFERANTEN nicht angenommene oder best\u00e4tigte Bestellung beziehen.   <\/p>\n<h4>4. Versand und Lieferung. Vertragsstrafen bei Lieferverzug <\/h4>\n<p>4.1. Die Versand- und Transportkosten zum Lieferort werden vom LIEFERANTEN getragen, sofern in der Bestellung nichts anderes angegeben ist. Jede Lieferung wird von der entsprechenden Mitteilung oder dem Lieferschein des LIEFERANTEN begleitet, der den Inhalt, den Preis, die Bestellnummer und die Anzahl der Pakete angibt. <\/p>\n<p>4.2. Alle mit dem Vorgang bis zur Lieferung am Bestimmungsort verbundenen Risiken tr\u00e4gt der LIEFERANT.<\/p>\n<p>4.3. Die Produkte werden, sofern gesetzlich vorgeschrieben, mit der notwendigen Bedienungsanleitung in spanischer Sprache, technischen Gebrauchsanweisungen und Pr\u00e4ventionshandb\u00fcchern versehen.<\/p>\n<p>4.5. Produkte m\u00fcssen KYMOS GROUP gem\u00e4\u00df der entsprechenden Bestellung und allen zwischen den Parteien vereinbarten Protokollen und fristgerecht geliefert werden. Sollte der LIEFERANT feststellen, dass er die gesch\u00e4tzten Fristen nicht einhalten kann, muss er KYMOS GROUP benachrichtigen und alle Anstrengungen unternehmen, um eine solche Verz\u00f6gerung zu minimieren. <\/p>\n<p>4.6. Die Nichteinhaltung der Lieferfristen durch den LIEFERANTEN verpflichtet diesen automatisch zur Zahlung einer Vertragsstrafe von 1 % des Auftragswertes f\u00fcr jede Woche oder jeden Teil einer Woche der Verz\u00f6gerung, bis zu einem Maximum von 10 %.<\/p>\n<h4>5. Preise und Zahlungsbedingungen<\/h4>\n<p>5.1. KYMOS GROUP zahlt dem LIEFERANTEN die Produkte gem\u00e4\u00df den in der Bestellung festgelegten Preisen und Bedingungen. Die in der Bestellung angegebenen Preise unterliegen keiner \u00dcberpr\u00fcfung, es sei denn, es ist angegeben, dass die Preise einer weiteren \u00dcberpr\u00fcfung unterliegen k\u00f6nnen. <\/p>\n<p>5.2. Alle Betr\u00e4ge sind innerhalb von sechzig (60) Tagen f\u00e4llig.<\/p>\n<p>5.3. Wird ein Teil einer Rechnung beanstandet, zahlt KYMOS GROUP den unbestrittenen Betrag unverz\u00fcglich. Beide Parteien werden sich nach besten Kr\u00e4ften bem\u00fchen, Differenzen oder Unstimmigkeiten in k\u00fcrzester Zeit zu kl\u00e4ren. <\/p>\n<h4>6. Produktgarantie<\/h4>\n<p>6.1. Der LIEFERANT muss garantieren, dass er Eigent\u00fcmer der zu liefernden Produkte ist, dass diese frei von jeglichen Belastungen und Lasten sind und dass kein Hindernis deren \u00dcbertragung, friedliche Nutzung und Vermarktung entgegensteht.<\/p>\n<p>6.2. Der LIEFERANT garantiert ferner die Qualit\u00e4t der Produkte und die Einhaltung der technischen und sonstigen Bedingungen sowie die M\u00e4ngelfreiheit der verwendeten Materialien und deren Design, Herstellung und Entwicklung.<\/p>\n<p>6.3. Sofern gesetzlich nichts anderes vorgeschrieben oder vereinbart ist, betr\u00e4gt die Dauer der Garantie zwei (2) Jahre ab Empfang der Produkte. W\u00e4hrend dieses Zeitraums ist der LIEFERANT auf Verlangen von KYMOS GROUP verpflichtet, die mangelhaften Produkte auf eigene Kosten zu ersetzen und\/oder zu reparieren. Nach Durchf\u00fchrung der Reparaturen und\/oder Ersatzlieferungen beginnt eine neue Garantiezeit, die der urspr\u00fcnglichen Dauer entspricht, in Bezug auf die ersetzten und\/oder reparierten Produkte.  <\/p>\n<p>6.4. Reparaturen und\/oder Ersatzlieferungen m\u00fcssen innerhalb der von KYMOS GROUP festgelegten Frist erfolgen. Andernfalls kann KYMOS GROUP die notwendigen Arbeiten selbst oder durch Dritte ausf\u00fchren lassen und dem LIEFERANTEN in Rechnung stellen.<\/p>\n<h4>7. Untervergabe<\/h4>\n<p>Der LIEFERANT ist nicht berechtigt, alle oder einen Teil der Dienstleistungen ohne schriftliche Zustimmung von KYMOS GROUP an Dritte zu vergeben.<\/p>\n<h4>8. Schadloshaltung<\/h4>\n<p>8.1. Der LIEFERANT stellt KYMOS GROUP von jeglicher rechtlichen Haftung, Verlusten, Sch\u00e4den, Kosten oder Ausgaben, einschlie\u00dflich angemessener Anwaltskosten, frei, die sich aus einer fahrl\u00e4ssigen Handlung, vors\u00e4tzlichem Fehlverhalten, Unterlassung oder Verletzung der Bestimmungen dieser Allgemeinen Einkaufsbedingungen ergeben.<\/p>\n<h4>9. Geistige Eigentumsrechte<\/h4>\n<p>Der LIEFERANT garantiert, dass seine Herstellungsprozesse und Produkte keine Patente, Gesch\u00e4ftsgeheimnisse oder andere geistige Eigentumsrechte Dritter in Bezug auf Produkte, Muster, Know-how und Verfahren verletzen, und ist in jedem Fall f\u00fcr Sch\u00e4den verantwortlich, die KYMOS GROUP im Falle von Anspr\u00fcchen Dritter entstehen k\u00f6nnten.<\/p>\n<h4>10. Versicherung<\/h4>\n<p>W\u00e4hrend der Dauer der Dienstleistungen unterhalten beide Parteien geeignete Versicherungspolicen, die allgemeine, zivilrechtliche und berufliche Haftpflichten abdecken.<\/p>\n<h4>11. Materialhinterlegung<\/h4>\n<p>Modelle, Werkzeuge, Muster, Fertigungsvorrichtungen, Zeichnungen, Pl\u00e4ne, Designs, Formen und andere \u00e4hnliche Elemente sowie Materialien oder Produkte im Eigentum von KYMOS GROUP, die dem LIEFERANTEN zur Erf\u00fcllung der Bestellung zur Verf\u00fcgung gestellt wurden, gelten als Hinterlegung und bleiben das vollst\u00e4ndige und ausschlie\u00dfliche Eigentum von KYMOS GROUP. Sie d\u00fcrfen nicht verwendet oder an Dritte \u00fcbertragen werden, und der LIEFERANT wird sie ausschlie\u00dflich zur Ausf\u00fchrung der Bestellung verwenden und sie KYMOS GROUP unverz\u00fcglich nach Abschluss und Lieferung der Bestellung zur\u00fcckgeben. <\/p>\n<h4>12. Verhaltenskodex des LIEFERANTEN<\/h4>\n<p>12.1 Der LIEFERANT ist verpflichtet, die geltende Gesetzgebung strikt einzuhalten. Insbesondere wird er keine direkten oder indirekten Bestechungs- oder Korruptionshandlungen begehen und alle Umweltgesetze sowie die Verpflichtungen, die sich aus den Steuer-, Arbeits- und Sozialversicherungsgesetzen f\u00fcr Arbeitgeber in Bezug auf alle seine Mitarbeiter ergeben, getreu einhalten. <\/p>\n<p>12.2. Die Nichteinhaltung der oben genannten gesetzlichen Verpflichtungen berechtigt KYMOS GROUP, jeden mit dem LIEFERANTEN vereinbarten Vertrag oder jede Bestellung einseitig und fristlos zu k\u00fcndigen.<\/p>\n<h4>13. Aufl\u00f6sung<\/h4>\n<p>F\u00fcr den Fall, dass (i) der LIEFERANT eine seiner vertraglichen Verpflichtungen nicht erf\u00fcllt oder gegen eine der Bestimmungen dieser ALLGEMEINEN EINKAUFSBEDINGUNGEN oder eine andere Vereinbarung zwischen den Parteien verst\u00f6\u00dft und dieser Versto\u00df wesentlich ist und nicht innerhalb von drei\u00dfig (30) Tagen nach Erhalt einer schriftlichen Aufforderung zur Behebung des Versto\u00dfes durch die nicht s\u00e4umige Partei behoben wird, oder (ii) der LIEFERANT aus irgendeinem Grund seine Gesch\u00e4ftst\u00e4tigkeit einstellt oder in Liquidation geht, kann KYMOS GROUP die Bestellung ganz oder teilweise durch schriftliche Mitteilung an den LIEFERANTEN aussetzen und die Zahlung f\u00fcr die bis dahin ordnungsgem\u00e4\u00df erbrachten Produkte oder Dienstleistungen leisten. Der LIEFERANT hat keinen Anspruch auf die Zahlung weiterer Betr\u00e4ge als Entsch\u00e4digung.   <\/p>\n<h4>14. H\u00f6here Gewalt<\/h4>\n<p>Keine Partei ist verantwortlich f\u00fcr Verz\u00f6gerungen, Nichtlieferungen, Nichterf\u00fcllung, Verluste, Kosten, Anspr\u00fcche oder die Nichterf\u00fcllung ganz oder teilweise, wenn diese durch Streiks, Krieg, Aufruhr, Revolution, Terrorismus, Embargos, Br\u00e4nde, \u00dcberschwemmungen, D\u00fcrren, Unf\u00e4lle, Aussperrungen, Maschinenausf\u00e4lle, Arbeitsniederlegungen, staatliche Verbote oder andere Ursachen au\u00dferhalb der Kontrolle einer Partei verursacht werden, vorausgesetzt, die betroffene Partei benachrichtigt die andere Partei unverz\u00fcglich und unternimmt alle zumutbaren Anstrengungen, um die Ursache und die Auswirkungen eines solchen Ereignisses zu beheben, zu beseitigen oder zu mildern. Wenn ein Ereignis h\u00f6herer Gewalt eine der Parteien l\u00e4nger als 3 Monate an der Erf\u00fcllung ihrer Verpflichtungen hindert, ist die andere Partei berechtigt, diese Vereinbarung zu k\u00fcndigen. <\/p>\n<h4>15. Fortbestehende Verpflichtungen<\/h4>\n<p>Bei Beendigung der Dienstleistungen aus irgendeinem Grund bleiben die erworbenen Rechte, Pflichten und Rechtsbehelfe der Parteien gem\u00e4\u00df diesen ALLGEMEINEN EINKAUFSBEDINGUNGEN unber\u00fchrt, und diejenigen Bestimmungen, die fortbestehen oder in Kraft treten sollen, tun dies ungeachtet der Beendigung.<\/p>\n<h4>16. Abtretung<\/h4>\n<p>Au\u00dfer an ein verbundenes Unternehmen und nach vorheriger Mitteilung an die andere Partei, darf weder KYMOS GROUP noch der LIEFERANT eine Vereinbarung oder Forderung ohne Zustimmung der anderen Partei abtreten.<\/p>\n<h4>17. Salvatorische Klausel<\/h4>\n<p>Sollte eine Bestimmung dieser ALLGEMEINEN EINKAUFSBEDINGUNGEN ung\u00fcltig oder nicht durchsetzbar sein, bleiben die \u00fcbrigen Bestimmungen davon unber\u00fchrt und sind im vollen gesetzlich zul\u00e4ssigen Umfang g\u00fcltig und durchsetzbar.<\/p>\n<h4>18. Unabh\u00e4ngige Auftragnehmer<\/h4>\n<p>Die Parteien sind unabh\u00e4ngige Auftragnehmer, und unter keinen Umst\u00e4nden d\u00fcrfen eine Partei, ihre Mitarbeiter oder Vertreter als Vertreter, Angestellte oder Joint-Venture-Partner der anderen Partei angesehen werden. Keine Partei hat das Recht, Vertr\u00e4ge oder Verpflichtungen im Namen oder im Auftrag der anderen in irgendeiner Hinsicht einzugehen. <\/p>\n<h4>19. Datenschutz<\/h4>\n<p>Gem\u00e4\u00df den Bestimmungen der Verordnung (EU) 2016\/679 vom 27. April 2016 und des LSSICE 34\/2002 vom 11. Juli, der Informationsgesellschaft und des elektronischen Handels, wird KYMOS GROUP die darin enthaltenen personenbezogenen Daten des LIEFERANTEN zusammen mit den w\u00e4hrend der G\u00fcltigkeit einer Vereinbarung zwischen den Parteien erhaltenen Daten in eine unter ihrer Verantwortung erstellte Datei aufnehmen, um die Verwaltung dieser Vertragsbeziehung durchzuf\u00fchren und auch um kommerzielle Informationen auf elektronischem oder postalischem Wege zu versenden. Diese Verarbeitung dient diesen Zwecken und hat als Rechtsgrundlage die Verwaltung der Vertragsbeziehung mit dem LIEFERANTEN. Der LIEFERANT kann als Eigent\u00fcmer der Daten jederzeit seine Rechte auf Datenzugriff, Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung, Widerspruch gegen die Verarbeitung und automatisierte Entscheidungsfindung sowie das Recht auf Daten\u00fcbertragbarkeit aus\u00fcben, indem er an die unter Klausel 20 angegebene Adresse schreibt. Wir erinnern Sie an Ihr Recht, eine Beschwerde bei der spanischen Datenschutzbeh\u00f6rde einzureichen, falls Sie der Ansicht sind, dass ein Versto\u00df gegen die geltenden Datenschutzbestimmungen vorliegt, indem Sie an diese Beh\u00f6rde C\/ Jorge Juan, Nummer 6, 28001 &#8211; Madrid oder \u00fcber die Website <a href=\"https:\/\/www.agdp.es\/\" data-wpel-link=\"external\">www.agpd.es<\/a> schreiben.   <\/p>\n<h4>20. Mitteilungen<\/h4>\n<p>Jede erforderliche oder zul\u00e4ssige Mitteilung, Anfrage, Aufforderung, Zustimmung oder sonstige Kommunikation muss schriftlich erfolgen und ist wirksam, wenn sie pers\u00f6nlich zugestellt, per zertifiziertem Fax \u00fcbermittelt oder per Einschreiben versandt wird. Die angegebene Adresse f\u00fcr KYMOS GROUP S.L. zu H\u00e4nden der Gesch\u00e4ftsleitung lautet: Parc Tecnol\u00f2gic del Vall\u00e8s. Ronda Can Fatj\u00f3 5, Geb\u00e4ude D. 08290 Cerdanyola del Vall\u00e8s. Barcelona. Spanien. E-Mail <a href=\"mailto:legal@kymos.com\" data-wpel-link=\"internal\">legal@kymos.com<\/a>.     <\/p>\n<h4>21. Anwendbares Recht und Gerichtsstand<\/h4>\n<p>Alle Streitigkeiten, die im Zusammenhang mit diesen ALLGEMEINEN EINKAUFSBEDINGUNGEN entstehen und nicht g\u00fctlich beigelegt werden k\u00f6nnen, werden ausschlie\u00dflich von den Gerichten in Barcelona gem\u00e4\u00df den Gesetzen Spaniens entschieden, ohne Ber\u00fccksichtigung der Kollisionsnormen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1170px + 20px );margin-left: calc(-20px \/ 2 );margin-right: calc(-20px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:10px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:10px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:10px;--awb-spacing-left-medium:10px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:10px;--awb-spacing-left-small:10px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two kymos-header\" style=\"--awb-text-color:var(--awb-color5);\"><h2 class=\"fusion-title-heading title-heading-center\" style=\"margin:0;\"><a id=\"form_anchor_legal\"><\/a>WHISTLEBLOWER-KANAL \u2013 R\u00dcCKRUFANFRAGE<\/h2><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f29217-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"29217\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/37368#wpcf7-f29217-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"29217\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f29217-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Geben Sie Ihre vollst\u00e4ndige Telefonnummer mit Landesvorwahl an (+34 935 481 848 zum Beispiel).<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-number\" \/><\/span> <\/label>\n<\/p>\n<p><label> W\u00e4hlen Sie den Zeitraum aus, in dem Sie kontaktiert werden m\u00f6chten (z. B. 9-12 Uhr).<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-time-slot\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-time-slot\" \/><\/span> <\/label>\n<\/p>\n<p><label> Geben Sie Ihre E-Mail-Adresse an, falls der Termin verschoben werden muss.<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email-reschedule\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email-reschedule\" \/><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Einreichen\" \/>\n<\/p><div class=\"fusion-alert alert custom alert-custom fusion-alert-center wpcf7-response-output awb-alert-native-link-color alert-dismissable awb-alert-close-boxed\" style=\"--awb-border-size:1px;--awb-border-top-left-radius:0px;--awb-border-top-right-radius:0px;--awb-border-bottom-left-radius:0px;--awb-border-bottom-right-radius:0px;\" role=\"alert\"><div class=\"fusion-alert-content-wrapper\"><span class=\"fusion-alert-content\"><\/span><\/div><button type=\"button\" class=\"close toggle-alert\" data-dismiss=\"alert\" aria-label=\"Close\">&times;<\/button><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-37368","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rechtliches | Kymos<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rechtliches | Kymos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kymos.com\/de\/rechtliches\/\" \/>\n<meta property=\"og:site_name\" content=\"Kymos\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-04T09:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kymos.com\/wp-content\/uploads\/2023\/06\/Foto-Logo-Kymos-Edificio.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@KymosGroup\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"62\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/rechtliches\\\/\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/rechtliches\\\/\",\"name\":\"Rechtliches | Kymos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#website\"},\"datePublished\":\"2021-08-31T14:52:00+00:00\",\"dateModified\":\"2026-08-04T09:22:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/rechtliches\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kymos.com\\\/de\\\/rechtliches\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/rechtliches\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kymos.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rechtliches\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kymos.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/kymos.com\\\/de\\\/\",\"name\":\"Kymos Group\",\"description\":\"Kymos Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kymos.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rechtliches | Kymos","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"Rechtliches | Kymos","og_url":"https:\/\/kymos.com\/de\/rechtliches\/","og_site_name":"Kymos","article_modified_time":"2026-08-04T09:22:38+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/kymos.com\/wp-content\/uploads\/2023\/06\/Foto-Logo-Kymos-Edificio.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@KymosGroup","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"62\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kymos.com\/de\/rechtliches\/","url":"https:\/\/kymos.com\/de\/rechtliches\/","name":"Rechtliches | Kymos","isPartOf":{"@id":"https:\/\/kymos.com\/de\/#website"},"datePublished":"2021-08-31T14:52:00+00:00","dateModified":"2026-08-04T09:22:38+00:00","breadcrumb":{"@id":"https:\/\/kymos.com\/de\/rechtliches\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kymos.com\/de\/rechtliches\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kymos.com\/de\/rechtliches\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kymos.com\/de\/"},{"@type":"ListItem","position":2,"name":"Rechtliches"}]},{"@type":"WebSite","@id":"https:\/\/kymos.com\/de\/#website","url":"https:\/\/kymos.com\/de\/","name":"Kymos Group","description":"Kymos Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kymos.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/pages\/37368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/comments?post=37368"}],"version-history":[{"count":12,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/pages\/37368\/revisions"}],"predecessor-version":[{"id":47785,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/pages\/37368\/revisions\/47785"}],"wp:attachment":[{"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/media?parent=37368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/categories?post=37368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kymos.com\/de\/wp-json\/wp\/v2\/tags?post=37368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}